{"id":8894,"date":"2018-05-04T14:17:24","date_gmt":"2018-05-04T12:17:24","guid":{"rendered":"http:\/\/www.asajacyl.com\/leon\/?p=8894"},"modified":"2018-05-11T14:40:13","modified_gmt":"2018-05-11T12:40:13","slug":"las-seis-noticias-agrarias-de-la-semana-04-05-2018","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 04-05-2018"},"content":{"rendered":"<h2><strong>Precio de la leche, zona de especial incidencia de tuberculosis, cebollas, asegurar la cosecha y elecciones municipales<\/strong><\/h2>\n<h6><\/h6>\n<ol>\n<li>\n<h6>\u00a0En los primeros meses del a\u00f1o se est\u00e1 produciendo una <strong>correcci\u00f3n a la baja de los precios de la leche<\/strong> en la mayor\u00eda de los pa\u00edses de la Uni\u00f3n Europea. A\u00fan as\u00ed, se sigue manteniendo un importante diferencial entre Espa\u00f1a y los pa\u00edses m\u00e1s directamente competidores. As\u00ed, mientras que en el mes de marzo la leche se pag\u00f3 en Espa\u00f1a a 31,94 euros por cada 100 kilos, en Alemania se pag\u00f3 a 34,88 euros, en Francia a 34,22 euros y la media de la Uni\u00f3n Europea a 33,94 euros por cada cien kilos. El sector espera que la leche en Espa\u00f1a, que no subi\u00f3 cuando deb\u00eda, no se vea arrastrada por una bajada estacional en pa\u00edses que aumentan sus\u00a0 producciones en la \u00e9poca de pastos.<\/h6>\n<\/li>\n<li>\n<h6>La organizaci\u00f3n agraria ASAJA le ha pedido a la Junta que estudie la conveniencia de levantamiento de la <strong>zona de especial incidencia de tuberculosis de la Monta\u00f1a de Ria\u00f1o<\/strong>, una vez que en la comarca se ha reducido los porcentajes de positividad a esa enfermedad haci\u00e9ndolos homologables a los del resto de la provincia. ASAJA pide se tome esta decisi\u00f3n para facilitar la gesti\u00f3n de las explotaciones, y sin que ello ponga en riesgo el actual estatus sanitario de la caba\u00f1a ganadera local y provincial. La organizaci\u00f3n agraria es temerosa del riesgo que entra\u00f1a el tr\u00e1nsito de animales de otras comunidades aut\u00f3nomas lim\u00edtrofes.<\/h6>\n<\/li>\n<li>\n<h6>Un grupo de agricultores de las vegas de La Ba\u00f1eza han sembrado 30 hect\u00e1reas de <strong>cebollas<\/strong> con contratos en pre campa\u00f1a. Este cultivo, para el que se han buscado terrenos de vega, tiene un ciclo similar al de las patatas, pues se han sembrado a mediados de abril y est\u00e1\u00a0 prevista su recolecci\u00f3n para el mes de septiembre. Los productores esperan una mayor rentabilidad que en otros cultivos como las patatas o la remolacha. El trabajo est\u00e1 mecanizado. Esta iniciativa es un paso en la b\u00fasqueda de cultivos alternativos que aporten m\u00e1s valor a\u00f1adido.<\/h6>\n<\/li>\n<li>\n<h6>El buen aspecto que presentan por ahora los cereales de invierno invita a ampliar la producci\u00f3n con respecto a la asegurada en invierno cuando se hizo el seguro de rendimientos, en el caso de agricultores que eligieron esta opci\u00f3n, y a suscribir el seguro de primavera contra pedrisco e incendio quienes todav\u00eda no han contratado ning\u00fan seguro. Ni los costes ni la despreocupaci\u00f3n deben de ser motivos para no <strong>tener asegurada la cosecha<\/strong> un a\u00f1o en el que hay una buena expectativa y despu\u00e9s de venir de una campa\u00f1a desastrosa que diezm\u00f3 las rentas de los productores.<\/h6>\n<\/li>\n<li>\n<h6>La bajada de las temperaturas nocturnas los primeros d\u00edas de la presente semana hicieron temer una cat\u00e1strofe agraria por <strong>da\u00f1os de heladas<\/strong> como ya ocurriera el pasado a\u00f1o por las mismas fechas. Salvo algunas zonas puntuales, todo apunta a que los da\u00f1os han sido escasos debido tanto a que las temperaturas no fueron extremas, al situarse en un m\u00ednimo de menos dos grados cent\u00edgrados, como a que la mayor\u00eda de los cultivos tienen un retraso importante en su ciclo. Los frutales, ubicados en su mayor\u00eda en El Bierzo, tienen todav\u00eda por delante unos d\u00edas cr\u00edticos en los que se pueden producir da\u00f1os tanto en la floraci\u00f3n como en la fruta reci\u00e9n formada.<\/h6>\n<\/li>\n<li>\n<h6>Los principales partidos pol\u00edticos con implantaci\u00f3n en la provincia de Le\u00f3n est\u00e1n haciendo los primeros movimientos para la <strong>b\u00fasqueda de candidatos de cara a las elecciones municipales<\/strong>, auton\u00f3micas y europeas que se celebrar\u00e1n dentro de un a\u00f1o. Su labor m\u00e1s ardua es encontrar voluntarios con tir\u00f3n popular para las candidaturas a los peque\u00f1os municipios y a las juntas vecinales. La mayor\u00eda de estos puestos pol\u00edticos no son remunerados y por el contrario requieren de cierta dedicaci\u00f3n y compromiso. En muchas ocasiones los que ocupan estos cargos municipales no son\u00a0 quienes viven y trabajan en el medio rural.<\/h6>\n<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Precio de la leche, zona de especial incidencia de tuberculosis, cebollas, asegurar la cosecha y elecciones municipales \u00a0En los primeros meses del a\u00f1o se est\u00e1 produciendo una correcci\u00f3n a la baja de los precios de la leche en la mayor\u00eda de los pa\u00edses de la Uni\u00f3n Europea. A\u00fan as\u00ed, se sigue manteniendo un importante diferencial [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":7563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 04-05-2018 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Precio de la leche, zona de especial incidencia de tuberculosis, cebollas, asegurar la cosecha y elecciones municipales \u00a0En los primeros meses del a\u00f1o se\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 04-05-2018 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Precio de la leche, zona de especial incidencia de tuberculosis, cebollas, asegurar la cosecha y elecciones municipales \u00a0En los primeros meses del a\u00f1o se\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-04T12:17:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-11T12:40:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1109\" \/>\n\t<meta property=\"og:image:height\" content=\"926\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018\",\"name\":\"Las seis noticias agrarias de la semana - 04-05-2018 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg\",\"datePublished\":\"2018-05-04T12:17:24+00:00\",\"dateModified\":\"2018-05-11T12:40:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Precio de la leche, zona de especial incidencia de tuberculosis, cebollas, asegurar la cosecha y elecciones municipales \u00a0En los primeros meses del a\u00f1o se\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg\",\"width\":1109,\"height\":926},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 04-05-2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 04-05-2018 - ASAJA Le\u00f3n","description":"Precio de la leche, zona de especial incidencia de tuberculosis, cebollas, asegurar la cosecha y elecciones municipales \u00a0En los primeros meses del a\u00f1o se","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 04-05-2018 - ASAJA Le\u00f3n","og_description":"Precio de la leche, zona de especial incidencia de tuberculosis, cebollas, asegurar la cosecha y elecciones municipales \u00a0En los primeros meses del a\u00f1o se","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2018-05-04T12:17:24+00:00","article_modified_time":"2018-05-11T12:40:13+00:00","og_image":[{"width":1109,"height":926,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018","name":"Las seis noticias agrarias de la semana - 04-05-2018 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg","datePublished":"2018-05-04T12:17:24+00:00","dateModified":"2018-05-11T12:40:13+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Precio de la leche, zona de especial incidencia de tuberculosis, cebollas, asegurar la cosecha y elecciones municipales \u00a0En los primeros meses del a\u00f1o se","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/VACUNO_LECHE.jpg","width":1109,"height":926},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-05-2018#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 04-05-2018"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/8894"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=8894"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/8894\/revisions"}],"predecessor-version":[{"id":8895,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/8894\/revisions\/8895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/7563"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=8894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=8894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=8894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}