{"id":900,"date":"2004-03-30T00:00:00","date_gmt":"2004-03-29T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2004\/03\/30\/la-herencia-de-arias-caete\/"},"modified":"2017-11-15T10:03:25","modified_gmt":"2017-11-15T09:03:25","slug":"la-herencia-de-arias-caete","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete","title":{"rendered":"La herencia de arias ca&#241;ete"},"content":{"rendered":"<h2>Quedan pocos d&#237;as para un traspaso de poderes del actual Gobierno en funciones a quienes leg&#237;timamente ganaron las elecciones del 14 de marzo.<\/h2>\n<p align=\"center\"><font size=\"2\">&#160;&#160;<\/font><i><font color=\"#009900\" size=\"2\"><strong>La herencia de arias ca&#241;ete<\/strong><\/font><\/i><font size=\"2\"> <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font><i><\/p>\n<p align=\"center\"><font size=\"2\">Jos&#233; Antonio Turrado*<\/font><\/p>\n<p><\/i><font size=\"2\"> <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Quedan pocos d&#237;as para un traspaso de poderes del actual Gobierno en funciones a quienes leg&#237;timamente ganaron las elecciones del 14 de marzo. No quiero adelantarme a hacer un balance pormenorizado de los cuatro a&#241;os de Miguel Arias Ca&#241;ete al frente de la cartera de agricultura, pues tiempo habr&#225; para hacerlo y seguramente personas m&#225;s cualificadas y autorizadas para ello. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Pero hay algunos temas que forman parte de la herencia de Arias Ca&#241;ete, de los que se tendr&#225; que hablar en las pr&#243;ximas fechas, y que tendr&#225;n una incidencia muy importante en el futuro de la agricultura y la ganader&#237;a de nuestro pa&#237;s, y por tanto en el bolsillo de todos y cada uno de nuestros agricultores. Para empezar, el nuevo Gobierno se encontrar&#225; con la inminente entrada en vigor de una nueva Ley de Arrendamientos R&#250;sticos con la que ya ha dicho que no est&#225; de acuerdo y que va a cambiarla. Y me alegro de que Arias Ca&#241;ete vea desde su puesto de parlamentario c&#243;mo se le deroga una Ley auspiciada por &#233;l mismo antes casi de su entrada en vigor. Me alegro del escarnio al que va a ser sometido, y lamento que en el Partido Popular no se hayan dado cuenta que tambi&#233;n por la prepotencia, la chuler&#237;a y la falta de sensibilidad con la que se trataron cuestiones como el tr&#225;mite de esa Ley, se pueden perder unas elecciones. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Pero la peor herencia de Arias Ca&#241;ete tiene sin duda que ver con la reforma de la PAC aprobada el pasado mes de junio. El todav&#237;a ministro vino de Bruselas apunt&#225;ndose el &#233;xito de una negociaci&#243;n en la que, a propuesta suya, se hab&#237;a aprobado un desacoplamiento parcial de las ayudas cuya aplicaci&#243;n ser&#237;a potestativa de los estados miembros. Y quienes nunca cre&#237;mos en el desacoplamiento de las ayudas, no tardamos tiempo en darnos cuenta que el desacoplamiento parcial, en bajos porcentajes como ocurre con los cultivos herb&#225;ceos, es en s&#237; mismo peor que la propuesta inicial de Fischler, y por tanto lo rechazamos como lo rechazan todos nuestros agricultores y ganaderos profesionales. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Hasta Arias Ca&#241;ete hab&#237;a cedido ya a la presi&#243;n de sus asesores, de las comunidades aut&#243;nomas y de las organizaciones serias, y hab&#237;a apostado por el desacoplamiento total al menos en herb&#225;ceos, y as&#237; se aprob&#243; en la &#250;ltima Sectorial de Agricultura anterior a las elecciones. Pero mira por d&#243;nde, sin estar previsto ha ganado el PSOE y van a cambiar muchas cosas, entre otras la opini&#243;n sobre la aplicaci&#243;n de la reforma de la PAC. Y al componente ideol&#243;gico, que sin duda pesar&#225; en la toma de decisiones por parte del partido Socialista, se sumar&#225; el de la UPA-UGT, y el de algunos socios parlamentarios que pensar&#225;n en todo menos en el bienestar de agricultores y ganaderos. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">As&#237; las cosas, todo parece que la decisi&#243;n sobre la reforma no va a beneficiar a los profesionales del campo, y aunque si es as&#237; la culpa se la echaremos al nuevo Gobierno, no es menos cierto que el actual ha dado pie a que esto llegue a pasar. El debate del desacoplamiento, y tener este asunto abierto a estas alturas, forma sin duda parte de la herencia, de la mala herencia, que nos deja Arias Ca&#241;ete como ministro del Reino de Espa&#241;a. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Es deseo de quien esto escribe, que no es sospechoso de connivencia con los que llegan, que Arias Ca&#241;ete sea como diputado de la oposici&#243;n mejor que lo fue como ministro, y si se ocupa de las labores agrarias, que cambie antes muchos conceptos, pues no ser&#237;a agradable tener que luchar contra gobierno y contra oposici&#243;n pol&#237;tica para defender los intereses agrarios. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p><font size=\"2\">&#160;<\/font><i><font size=\"2\"> <\/font><\/p>\n<p align=\"right\"><font size=\"2\">* Jos&#233; Antonio Turrado es secretario general de ASAJA de Castilla y Le&#243;n<\/font><\/p>\n<p><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quedan pocos d&#237;as para un traspaso de poderes del actual Gobierno en funciones a quienes leg&#237;timamente ganaron las elecciones del 14 de marzo.<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La herencia de arias ca&#241;ete - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Quedan pocos d&#237;as para un traspaso de poderes del actual Gobierno en funciones a quienes leg&#237;timamente ganaron las elecciones del 14 de marzo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La herencia de arias ca&#241;ete - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Quedan pocos d&#237;as para un traspaso de poderes del actual Gobierno en funciones a quienes leg&#237;timamente ganaron las elecciones del 14 de marzo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2004-03-29T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-15T09:03:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete\",\"name\":\"La herencia de arias ca&#241;ete - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2004-03-29T22:00:00+00:00\",\"dateModified\":\"2017-11-15T09:03:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Quedan pocos d&#237;as para un traspaso de poderes del actual Gobierno en funciones a quienes leg&#237;timamente ganaron las elecciones del 14 de marzo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La herencia de arias ca&#241;ete\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La herencia de arias ca&#241;ete - ASAJA Le\u00f3n","description":"Quedan pocos d&#237;as para un traspaso de poderes del actual Gobierno en funciones a quienes leg&#237;timamente ganaron las elecciones del 14 de marzo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete","og_locale":"es_ES","og_type":"article","og_title":"La herencia de arias ca&#241;ete - ASAJA Le\u00f3n","og_description":"Quedan pocos d&#237;as para un traspaso de poderes del actual Gobierno en funciones a quienes leg&#237;timamente ganaron las elecciones del 14 de marzo.","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2004-03-29T22:00:00+00:00","article_modified_time":"2017-11-15T09:03:25+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete","name":"La herencia de arias ca&#241;ete - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2004-03-29T22:00:00+00:00","dateModified":"2017-11-15T09:03:25+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Quedan pocos d&#237;as para un traspaso de poderes del actual Gobierno en funciones a quienes leg&#237;timamente ganaron las elecciones del 14 de marzo.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-herencia-de-arias-caete#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"La herencia de arias ca&#241;ete"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/900"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=900"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/900\/revisions"}],"predecessor-version":[{"id":1265,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/900\/revisions\/1265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}