{"id":903,"date":"2004-02-02T00:00:00","date_gmt":"2004-02-01T23:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2004\/02\/02\/urcacyl-ya-es-un-sindicato-agrario\/"},"modified":"2017-11-15T10:03:28","modified_gmt":"2017-11-15T09:03:28","slug":"urcacyl-ya-es-un-sindicato-agrario","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario","title":{"rendered":"URCACYL YA ES UN SINDICATO AGRARIO"},"content":{"rendered":"<h2>Por fin Urcacyl, una uni&#243;n regional de cooperativas en la que no est&#225;n todas ni est&#225;n las m&#225;s importantes, tiene el reconocimiento de la Consejer&#237;a de Agricultura y Ganader&#237;a para sentarse en el Consejo Regional Agrario como una cuarta organizaci&#243;n agraria &#8211;junto a Coag, Upa y ASAJA&#8211;, y por tanto desempe&#241;ando una labor reivindicativa en materia de pol&#237;tica agraria.<\/h2>\n<p><b><\/p>\n<p align=\"center\"><font color=\"#009900\" size=\"2\">URCACYL YA ES UN SINDICATO AGRARIO<\/font><i><\/p>\n<p align=\"center\">\n<p align=\"center\"><font size=\"2\">Jos&#233; Antonio Turrado*<\/font><\/p>\n<p><\/i><\/p>\n<p><\/b><\/p>\n<p><font size=\"2\">P<\/font><font size=\"2\">or fin Urcacyl, una uni&#243;n regional de cooperativas en la que no est&#225;n todas ni est&#225;n las m&#225;s importantes, tiene el reconocimiento de la Consejer&#237;a de Agricultura y Ganader&#237;a para sentarse en el Consejo Regional Agrario como una cuarta organizaci&#243;n agraria &#8211;junto a Coag, Upa y ASAJA&#8211;, y por tanto desempe&#241;ando una labor reivindicativa en materia de pol&#237;tica agraria.<\/font>\n<\/p>\n<p align=\"justify\">\n<p align=\"justify\"><font size=\"2\">Este logro es sin duda un &#233;xito personal de su presidente, Ricardo Mart&#237;n, que siempre ha entendido que las cooperativas tienen que tener cabida en todos los foros en los que est&#225;n presentes las organizaciones agrarias, y muy especialmente en las reuniones con la Administraci&#243;n y en los medios de comunicaci&#243;n. ASAJA est&#225; totalmente en desacuerdo con que las cooperativas se atribuyan el papel reivindicativo, y est&#225; en contra de que ofrezcan ciertos servicios que dan las organizaciones, como pueda ser tramitar ayudas, pues en ambos casos suelen hacerlo mal, y lo hacen en competencia desleal con los sindicatos agrarios.<\/font>\n<\/p>\n<p align=\"justify\">\n<p align=\"justify\"><font size=\"2\">Pero ahora ya no importa lo que ASAJA diga y opine. Las cooperativas de Castilla y Le&#243;n aglutinadas en el entorno de Urcacyl, porque de las otras el consejero no se ocupa, son a todos los efectos una cuarta organizaci&#243;n agraria para informar, reivindicar y dar servicios. Ahora queda por demostrar que ese papel para el que se le ha otorgado diploma, lo ejercen con dignidad, con &#233;xito e independencia, y que ello redunde en beneficio para los agricultores y ganaderos. Porque meterse en estos l&#237;os, adem&#225;s de servir para sacar pecho en los peri&#243;dicos y las televisiones, tiene acarreadas no pocas responsabilidades. Ahora los socios de cooperativas integradas en Urcacyl, que al parecer son decenas de miles, y que muchos de ellos se supone son socios tambi&#233;n de ASAJA, tienen una nueva puerta a la que ir a llamar cuando las cosas vayan mal. Antes de ir a ASAJA a quejarse por las ayudas que no se aprueban, por los expedientes que se atrancan en los despachos, por las multas que pone Medio Ambientes, por las inspecciones de la PAC, por la equivocada pol&#237;tica agraria de Bruselas, por los bajos precios de los productos o por los altos costes de los medios de producci&#243;n, tendr&#225;n que pasar a quejarse al despacho del presidente o del gerente de su cooperativa m&#225;s pr&#243;xima. Y ya no valen excusas, no valen pretextos, no vale echar responsabilidades fuera, pues ahora los presidentes de cooperativas tendr&#225;n que criticar al poder pol&#237;tico, tendr&#225;n que resolver papeles a los agricultores, tendr&#225;n que sacar comunicados de protesta, y tendr&#225;n que ser los primeros en agarrar las pancartas y en convocar de motu propio las manifestaciones.<\/font>\n<\/p>\n<p align=\"justify\">\n<p align=\"justify\"><font size=\"2\">Y toda esta nueva responsabilidad, asignada por el consejero despu&#233;s de haber sido reiteradamente demandada por Urcacyl, la tendr&#225;n que compaginar con la esencia de su objeto social, que no es otra que la de comercializar y transformar los productos para que el agricultor y ganadero socio obtenga un valor a&#241;adido al de la producci&#243;n. Y desde ASAJA esperamos que en este campo, donde tanto queda por hacer y muy especialmente en esta regi&#243;n, las cooperativas de Urcacyl no caigan en la desidia y abandonen sus responsabilidades por dedicarse a partir de ahora a agarrar pancartas. Est&#225; bien diversificar, eso dicen los buenos empresarios, y las cooperativas empresa son, pero como me dec&#237;a estos d&#237;as un buen cooperativista que a la vez cree en el sindicalismo agrario, haber si por meternos en la pol&#237;tica nos olvidamos de ganar un c&#233;ntimo al kilo de trigo o al litro de leche.<\/font>\n<\/p>\n<p align=\"justify\"><i><\/p>\n<p align=\"right\"><font size=\"2\">* Jos&#233; Antonio Turrado es secretario general de ASAJA de Castilla y Le&#243;n<\/font><\/p>\n<p><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por fin Urcacyl, una uni&#243;n regional de cooperativas en la que no est&#225;n todas ni est&#225;n las m&#225;s importantes, tiene el reconocimiento de la Consejer&#237;a de Agricultura y Ganader&#237;a para sentarse en el Consejo Regional Agrario como una cuarta organizaci&#243;n agraria &#8211;junto a Coag, Upa y ASAJA&#8211;, y por tanto desempe&#241;ando una labor reivindicativa en materia de pol&#237;tica agraria.<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>URCACYL YA ES UN SINDICATO AGRARIO - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Por fin Urcacyl, una uni&#243;n regional de cooperativas en la que no est&#225;n todas ni est&#225;n las m&#225;s importantes, tiene el reconocimiento de la Consejer&#237;a de Agricultura y Ganader&#237;a para sentarse en el Consejo Regional Agrario como una cuarta organizaci&#243;n agraria &#8211;junto a Coag, Upa y ASAJA&#8211;, y por tanto desempe&#241;ando una labor reivindicativa en materia de pol&#237;tica agraria.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"URCACYL YA ES UN SINDICATO AGRARIO - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Por fin Urcacyl, una uni&#243;n regional de cooperativas en la que no est&#225;n todas ni est&#225;n las m&#225;s importantes, tiene el reconocimiento de la Consejer&#237;a de Agricultura y Ganader&#237;a para sentarse en el Consejo Regional Agrario como una cuarta organizaci&#243;n agraria &#8211;junto a Coag, Upa y ASAJA&#8211;, y por tanto desempe&#241;ando una labor reivindicativa en materia de pol&#237;tica agraria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2004-02-01T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-15T09:03:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario\",\"name\":\"URCACYL YA ES UN SINDICATO AGRARIO - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2004-02-01T23:00:00+00:00\",\"dateModified\":\"2017-11-15T09:03:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Por fin Urcacyl, una uni&#243;n regional de cooperativas en la que no est&#225;n todas ni est&#225;n las m&#225;s importantes, tiene el reconocimiento de la Consejer&#237;a de Agricultura y Ganader&#237;a para sentarse en el Consejo Regional Agrario como una cuarta organizaci&#243;n agraria &#8211;junto a Coag, Upa y ASAJA&#8211;, y por tanto desempe&#241;ando una labor reivindicativa en materia de pol&#237;tica agraria.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"URCACYL YA ES UN SINDICATO AGRARIO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"URCACYL YA ES UN SINDICATO AGRARIO - ASAJA Le\u00f3n","description":"Por fin Urcacyl, una uni&#243;n regional de cooperativas en la que no est&#225;n todas ni est&#225;n las m&#225;s importantes, tiene el reconocimiento de la Consejer&#237;a de Agricultura y Ganader&#237;a para sentarse en el Consejo Regional Agrario como una cuarta organizaci&#243;n agraria &#8211;junto a Coag, Upa y ASAJA&#8211;, y por tanto desempe&#241;ando una labor reivindicativa en materia de pol&#237;tica agraria.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario","og_locale":"es_ES","og_type":"article","og_title":"URCACYL YA ES UN SINDICATO AGRARIO - ASAJA Le\u00f3n","og_description":"Por fin Urcacyl, una uni&#243;n regional de cooperativas en la que no est&#225;n todas ni est&#225;n las m&#225;s importantes, tiene el reconocimiento de la Consejer&#237;a de Agricultura y Ganader&#237;a para sentarse en el Consejo Regional Agrario como una cuarta organizaci&#243;n agraria &#8211;junto a Coag, Upa y ASAJA&#8211;, y por tanto desempe&#241;ando una labor reivindicativa en materia de pol&#237;tica agraria.","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2004-02-01T23:00:00+00:00","article_modified_time":"2017-11-15T09:03:28+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario","name":"URCACYL YA ES UN SINDICATO AGRARIO - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2004-02-01T23:00:00+00:00","dateModified":"2017-11-15T09:03:28+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Por fin Urcacyl, una uni&#243;n regional de cooperativas en la que no est&#225;n todas ni est&#225;n las m&#225;s importantes, tiene el reconocimiento de la Consejer&#237;a de Agricultura y Ganader&#237;a para sentarse en el Consejo Regional Agrario como una cuarta organizaci&#243;n agraria &#8211;junto a Coag, Upa y ASAJA&#8211;, y por tanto desempe&#241;ando una labor reivindicativa en materia de pol&#237;tica agraria.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/urcacyl-ya-es-un-sindicato-agrario#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"URCACYL YA ES UN SINDICATO AGRARIO"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/903"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=903"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/903\/revisions"}],"predecessor-version":[{"id":1268,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/903\/revisions\/1268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}