{"id":9336,"date":"2018-10-05T09:15:53","date_gmt":"2018-10-05T07:15:53","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=9336"},"modified":"2018-10-04T10:36:51","modified_gmt":"2018-10-04T08:36:51","slug":"callejas-hay-pocos","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos","title":{"rendered":"Callejas hay pocos"},"content":{"rendered":"<h6>Cuando alguien triunfa en la vida, o sencillamente acede a un cargo de cierta relevancia, se tira de curr\u00edculum y si alguna vez se pase\u00f3 por esta provincia ya le consideramos leon\u00e9s, \u201cleon\u00e9s de pura cepa\u201d si hace falta. Esto es muy propio de los medios de comunicaci\u00f3n, quiz\u00e1s por ese af\u00e1n de buscar siempre la noticia, incluso cuando no la hay. Un ejemplo pr\u00f3ximo en el tiempo ha sido la vinculaci\u00f3n con Le\u00f3n de Pablo Casado, o si se quiere el de la se\u00f1ora esposa de Pedro S\u00e1nchez. Bueno, pues entre tanto fraude de pertenencia a esta provincia leonesa, donde tenemos hasta parlamentarios que dicen ser de aqu\u00ed y que nadie los conoce, tenemos una relevante excepci\u00f3n en la figura de Jes\u00fas Calleja. Un leon\u00e9s antes de saltar a la fama que sigue siendo leon\u00e9s ahora que se le conoce en toda Espa\u00f1a y hasta en medio mundo. Un leon\u00e9s que cuando ha triunfado se ha hecho una casa a las afueras de la ciudad, o si se quiere en el campo, a la que le da uso \u2013 otros famosos la pusieron a la venta-, que tiene recorridos varias veces los picos de todas nuestras monta\u00f1as, y que pregona lo nuestro all\u00ed donde tiene la ocasi\u00f3n. Parece sencillo ser leon\u00e9s y ejercer de ello, pero en la pr\u00e1ctica, la realidad es que qui\u00e9n se va y triunfa no vuelve, y \u201cse agarrar a un clavo ardiendo\u201d antes de decir algo bonito de nosotros. Por si fuera poco meritorio el trabajo de Calleja como aventurero y productor de programas televisivos de divulgaci\u00f3n y entretenimiento, el tipo es simp\u00e1tico y ocurrente, y consecuencia de ello y de otras virtudes, cae bien a casi todo el mundo. La Medalla de Oro de la provincia que le ha concedido la Diputaci\u00f3n de Le\u00f3n a Jes\u00fas Calleja es un acto de justicia con un personaje que se lo merece como pocos y que deja el list\u00f3n alto para cuando las m\u00e1s altas instituciones leonesas piensen en futuros reconocimientos. Ser\u00eda bueno que se revisasen las bases que regulan estos reconocimientos honor\u00edficos para que de verdad recaigan en quienes siendo leoneses ejerzan realmente de ello y trabajen para que la provincia tenga proyecci\u00f3n y prospere.<\/h6>\n<h6>*Art\u00edculo de opini\u00f3n de Jos\u00e9 Antonio Turrado publicado en La Nueva Cr\u00f3nica del viernes 5 de octubre de 2018.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Cuando alguien triunfa en la vida, o sencillamente acede a un cargo de cierta relevancia, se tira de curr\u00edculum y si alguna vez se pase\u00f3 por esta provincia ya le consideramos leon\u00e9s, \u201cleon\u00e9s de pura cepa\u201d si hace falta. Esto es muy propio de los medios de comunicaci\u00f3n, quiz\u00e1s por ese af\u00e1n de buscar siempre [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":9338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Callejas hay pocos - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Cuando alguien triunfa en la vida, o sencillamente acede a un cargo de cierta relevancia, se tira de curr\u00edculum y si alguna vez se pase\u00f3 por esta\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Callejas hay pocos - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Cuando alguien triunfa en la vida, o sencillamente acede a un cargo de cierta relevancia, se tira de curr\u00edculum y si alguna vez se pase\u00f3 por esta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-05T07:15:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/10\/JES\u00daS-CALLEJA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1068\" \/>\n\t<meta property=\"og:image:height\" content=\"688\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos\",\"name\":\"Callejas hay pocos - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/10\/JES\u00daS-CALLEJA.jpg\",\"datePublished\":\"2018-10-05T07:15:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Cuando alguien triunfa en la vida, o sencillamente acede a un cargo de cierta relevancia, se tira de curr\u00edculum y si alguna vez se pase\u00f3 por esta\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/10\/JES\u00daS-CALLEJA.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/10\/JES\u00daS-CALLEJA.jpg\",\"width\":1068,\"height\":688},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Callejas hay pocos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Callejas hay pocos - ASAJA Le\u00f3n","description":"Cuando alguien triunfa en la vida, o sencillamente acede a un cargo de cierta relevancia, se tira de curr\u00edculum y si alguna vez se pase\u00f3 por esta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos","og_locale":"es_ES","og_type":"article","og_title":"Callejas hay pocos - ASAJA Le\u00f3n","og_description":"Cuando alguien triunfa en la vida, o sencillamente acede a un cargo de cierta relevancia, se tira de curr\u00edculum y si alguna vez se pase\u00f3 por esta","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2018-10-05T07:15:53+00:00","og_image":[{"width":1068,"height":688,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/10\/JES\u00daS-CALLEJA.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos","name":"Callejas hay pocos - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/10\/JES\u00daS-CALLEJA.jpg","datePublished":"2018-10-05T07:15:53+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Cuando alguien triunfa en la vida, o sencillamente acede a un cargo de cierta relevancia, se tira de curr\u00edculum y si alguna vez se pase\u00f3 por esta","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/10\/JES\u00daS-CALLEJA.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/10\/JES\u00daS-CALLEJA.jpg","width":1068,"height":688},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/callejas-hay-pocos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Callejas hay pocos"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/9336"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=9336"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/9336\/revisions"}],"predecessor-version":[{"id":9337,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/9336\/revisions\/9337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/9338"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=9336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=9336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=9336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}