{"id":9626,"date":"2019-01-09T18:54:34","date_gmt":"2019-01-09T17:54:34","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=9626"},"modified":"2019-01-09T18:54:34","modified_gmt":"2019-01-09T17:54:34","slug":"cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019","title":{"rendered":"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n &#8211; Sesi\u00f3n 09\/01\/2019"},"content":{"rendered":"<h2><strong><u>Factores externos impulsan el precio del trigo<\/u><\/strong><\/h2>\n<p>Varios factores en los mercados internacionales est\u00e1n incrementado el precio de este cereal.<\/p>\n<p>Rusia primer exportador mundial, est\u00e1 dando s\u00edntomas de agotamiento de este grano y los precios en este pa\u00eds est\u00e1n repuntando.<\/p>\n<p>Tambi\u00e9n est\u00e1 subiendo el precio en EEUU que ve como ahora su trigo es el m\u00e1s barato del mundo, y espera que en las pr\u00f3ximas licitaciones de pa\u00edses importadores nadie pueda competir con ellos.<\/p>\n<p>Europa y Australia tambi\u00e9n tienen limitadas sus exportaciones puesto que la sequ\u00eda redujo significativamente sus producciones.<\/p>\n<p>Respecto a Argentina, en la cosecha que pr\u00e1cticamente finaliza ahora, se est\u00e1 observando una baja calidad en algunas partidas de sus granos que han llegado incluso a que Argelia, una de los principales importadores del mundo, rechazase un cargamento al no cumplir los requisitos del contrato, puesto que el grano estaba brotado.<\/p>\n<p>A todo esto hay que sumar que el gobierno de EEUU mantiene el cierre de su administraci\u00f3n, lo que afecta directamente al USDA que desde principios de a\u00f1o ya no emite informes de mercados, e incluso su p\u00e1gina web est\u00e1 fuera de servicio, lo que est\u00e1 haciendo m\u00e1s dif\u00edcil ,a\u00fan si cabe, el an\u00e1lisis de todas estas informaciones.<\/p>\n<p>En la sesi\u00f3n de lonja celebrada hoy en Santa Mar\u00eda del P\u00e1ramo el trigo ha subido 2 euros, pasando a cotizar a 187\u20ac\/t. El resto de precios puede consultase en <a href=\"http:\/\/www.lonjadeleon.es\/\">www.lonjadeleon.es<\/a>.<\/p>\n<p>En Le\u00f3n a 09 de enero de 2.019.<\/p>\n<p>&nbsp;<\/p>\n<p>Precios Orientativos Euros\/Tonelada en <strong><u>Origen Almac\u00e9n Agricultor<\/u><\/strong><\/p>\n<p>(Condiciones de Calidad O.C.M. Cereales-F.E.G.A. Campa\u00f1a 2016\/2017)<\/p>\n<p>&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"206\"><strong>CEREALES<\/strong><\/td>\n<td width=\"123\"><strong>COTIZACION<\/strong><\/p>\n<p><strong>ANTERIOR<\/strong><\/td>\n<td width=\"132\"><strong>COTIZACION<\/strong><\/p>\n<p><strong>ACTUAL<\/strong><\/td>\n<td width=\"113\"><strong>DIF.<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"206\"><\/td>\n<td width=\"123\"><strong>\u20ac\/t<\/strong><\/td>\n<td width=\"132\"><strong>\u20ac\/t<\/strong><\/td>\n<td width=\"113\"><strong>\u00a0<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"206\">Trigo Pienso<\/td>\n<td width=\"123\">185,00<\/td>\n<td width=\"132\">187,00<\/td>\n<td width=\"113\">\u25b2<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">Cebada<\/td>\n<td width=\"123\">180,00<\/td>\n<td width=\"132\">180,00<\/td>\n<td width=\"113\">=<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">Triticale<\/td>\n<td width=\"123\">S\/C<\/td>\n<td width=\"132\">S\/C<\/td>\n<td width=\"113\"><\/td>\n<\/tr>\n<tr>\n<td width=\"206\">Centeno<\/td>\n<td width=\"123\">163,00<\/td>\n<td width=\"132\">163,00<\/td>\n<td width=\"113\">=<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">Avena<\/td>\n<td width=\"123\">155,00<\/td>\n<td width=\"132\">157,00<\/td>\n<td width=\"113\">\u25b2<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">Ma\u00edz<\/td>\n<td width=\"123\">182,00<\/td>\n<td width=\"132\">182,00<\/td>\n<td width=\"113\">=<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>* Ma\u00edz destino secadero.<\/p>\n<p>Actividad subvencionada por la Diputaci\u00f3n Provincial de Le\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"206\"><strong>ALUBIAS<\/strong><\/td>\n<td width=\"123\"><strong>COTIZACION<\/strong><\/p>\n<p><strong>ANTERIOR<\/strong><\/td>\n<td width=\"132\"><strong>COTIZACION<\/strong><\/p>\n<p><strong>ACTUAL<\/strong><\/td>\n<td width=\"113\"><strong>DIF.<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"206\"><\/td>\n<td width=\"123\"><strong>\u20ac\/kg<\/strong><\/td>\n<td width=\"132\"><strong>\u20ac\/kg<\/strong><\/td>\n<td width=\"113\"><\/td>\n<\/tr>\n<tr>\n<td width=\"206\">Canela<\/td>\n<td width=\"123\">1,40<\/td>\n<td width=\"132\">1,40<\/td>\n<td width=\"113\">=<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">Negra<\/td>\n<td width=\"123\">3,05<\/td>\n<td width=\"132\">2,95<\/td>\n<td width=\"113\">\u25bc<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">Palme\u00f1a Redonda<\/td>\n<td width=\"123\">1,70<\/td>\n<td width=\"132\">1,70<\/td>\n<td width=\"113\">=<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">Planchada<\/td>\n<td width=\"123\">1,30<\/td>\n<td width=\"132\">1,30<\/td>\n<td width=\"113\">=<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">Plancheta<\/td>\n<td width=\"123\">1,45<\/td>\n<td width=\"132\">1,45<\/td>\n<td width=\"113\">=<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">Pinta<\/td>\n<td width=\"123\">0,80<\/td>\n<td width=\"132\">0,80<\/td>\n<td width=\"113\">=<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">Ri\u00f1\u00f3n de Le\u00f3n<\/td>\n<td width=\"123\">0,95<\/td>\n<td width=\"132\">0,95<\/td>\n<td width=\"113\">=<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">Redonda<\/td>\n<td width=\"123\">0,95<\/td>\n<td width=\"132\">0,95<\/td>\n<td width=\"113\">=<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Actividad subvencionada por la Diputaci\u00f3n Provincial de Le\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Factores externos impulsan el precio del trigo Varios factores en los mercados internacionales est\u00e1n incrementado el precio de este cereal. Rusia primer exportador mundial, est\u00e1 dando s\u00edntomas de agotamiento de este grano y los precios en este pa\u00eds est\u00e1n repuntando. Tambi\u00e9n est\u00e1 subiendo el precio en EEUU que ve como ahora su trigo es el [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":9629,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,67,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cotizaciones de la Lonja Agropecuaria de Le\u00f3n - Sesi\u00f3n 09\/01\/2019 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Factores externos impulsan el precio del trigo Varios factores en los mercados internacionales est\u00e1n incrementado el precio de este cereal. Rusia primer\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n - Sesi\u00f3n 09\/01\/2019 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Factores externos impulsan el precio del trigo Varios factores en los mercados internacionales est\u00e1n incrementado el precio de este cereal. Rusia primer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-09T17:54:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/01\/GRANOS_TRIGO_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"685\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gonzalofa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"gonzalofa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019\",\"name\":\"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n - Sesi\u00f3n 09\/01\/2019 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/01\/GRANOS_TRIGO_1.jpg\",\"datePublished\":\"2019-01-09T17:54:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/061f8efaa09cf43f8868e57fe9592bfa\"},\"description\":\"Factores externos impulsan el precio del trigo Varios factores en los mercados internacionales est\u00e1n incrementado el precio de este cereal. Rusia primer\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/01\/GRANOS_TRIGO_1.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/01\/GRANOS_TRIGO_1.jpg\",\"width\":960,\"height\":685},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n &#8211; Sesi\u00f3n 09\/01\/2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/061f8efaa09cf43f8868e57fe9592bfa\",\"name\":\"gonzalofa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ae85559b262be23fe1587f91beb8e527?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ae85559b262be23fe1587f91beb8e527?s=96&d=mm&r=g\",\"caption\":\"gonzalofa\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/gonzalofa\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n - Sesi\u00f3n 09\/01\/2019 - ASAJA Le\u00f3n","description":"Factores externos impulsan el precio del trigo Varios factores en los mercados internacionales est\u00e1n incrementado el precio de este cereal. Rusia primer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019","og_locale":"es_ES","og_type":"article","og_title":"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n - Sesi\u00f3n 09\/01\/2019 - ASAJA Le\u00f3n","og_description":"Factores externos impulsan el precio del trigo Varios factores en los mercados internacionales est\u00e1n incrementado el precio de este cereal. Rusia primer","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2019-01-09T17:54:34+00:00","og_image":[{"width":960,"height":685,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/01\/GRANOS_TRIGO_1.jpg","type":"image\/jpeg"}],"author":"gonzalofa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"gonzalofa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019","name":"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n - Sesi\u00f3n 09\/01\/2019 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/01\/GRANOS_TRIGO_1.jpg","datePublished":"2019-01-09T17:54:34+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/061f8efaa09cf43f8868e57fe9592bfa"},"description":"Factores externos impulsan el precio del trigo Varios factores en los mercados internacionales est\u00e1n incrementado el precio de este cereal. Rusia primer","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/01\/GRANOS_TRIGO_1.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2019\/01\/GRANOS_TRIGO_1.jpg","width":960,"height":685},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/lonjas-mercados\/cotizaciones-de-la-lonja-agropecuaria-de-leon-sesion-09-01-2019#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Cotizaciones de la Lonja Agropecuaria de Le\u00f3n &#8211; Sesi\u00f3n 09\/01\/2019"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/061f8efaa09cf43f8868e57fe9592bfa","name":"gonzalofa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ae85559b262be23fe1587f91beb8e527?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ae85559b262be23fe1587f91beb8e527?s=96&d=mm&r=g","caption":"gonzalofa"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/gonzalofa"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/9626"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=9626"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/9626\/revisions"}],"predecessor-version":[{"id":9628,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/9626\/revisions\/9628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/9629"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=9626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=9626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=9626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}