{"id":9989,"date":"2019-04-03T20:01:00","date_gmt":"2019-04-03T18:01:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=9989"},"modified":"2019-04-03T20:01:00","modified_gmt":"2019-04-03T18:01:00","slug":"estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25","title":{"rendered":"Estimamos una reducci\u00f3n de la superficie de trigo de regad\u00edo en el entorno del 25%"},"content":{"rendered":"<h6>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La complicaci\u00f3n en las siembras de trigo este invierno ha hecho que muchos agricultores de regad\u00edo desestimasen las mismas y hayan apostado por otros cultivos alternativos, la pasada campa\u00f1a en la provincia de le\u00f3n hab\u00eda sembradas de este cereal 30.785 hect\u00e1reas y en la presente seg\u00fan nuestras estimaciones, apenas se sobrepasar\u00e1n las 23.000 ha.<\/h6>\n<h6>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Tambi\u00e9n se espera una reducci\u00f3n aunque no tan importante en el trigo de secano puesto que la pasada campa\u00f1a hab\u00eda sembradas 35.069 ha. Y en la presente nuestra estimaci\u00f3n no sobrepasa las 32.000 ha., es decir una reducci\u00f3n cercana al 9%.<\/h6>\n<h6>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 En cuanto al pron\u00f3stico de rendimientos es a\u00fan muy pronto para dar cifras, la provincia de Le\u00f3n es muy dependiente de los regad\u00edos que esta campa\u00f1a est\u00e1n asegurados, quiz\u00e1s la mayor incertidumbre radique en c\u00f3mo evolucionar\u00e1 el cereal en unas siembras realizadas muy tard\u00edas y que por tanto se encuentran muy retrasadas respecto a lo que ser\u00eda un a\u00f1o normal.<\/h6>\n<h6>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 En los secanos hay una preocupaci\u00f3n creciente por la falta de precipitaciones aunque a d\u00eda de hoy el estado de los cultivos aun permitir\u00eda una buena recuperaci\u00f3n si las lluvias apareciesen en estas dos pr\u00f3ximas semanas y a la vez fuesen abundantes.<\/h6>\n<h6><\/h6>\n<h6>Los precios pueden consultase en <a href=\"http:\/\/www.lonjadeleon.es\/\">www.lonjadeleon.es<\/a>.<\/h6>\n<h6><\/h6>\n<h6>En Le\u00f3n a 03 de abril de 2.019.<\/h6>\n<h6><\/h6>\n<h6><\/h6>\n<h6>Precios Orientativos Euros\/Tonelada <u>en Almac\u00e9n<\/u><\/h6>\n<h6>(Condiciones de Calidad O.C.M. Cereales-F.E.G.A. Campa\u00f1a 2016\/2017)<\/h6>\n<h6><\/h6>\n<table>\n<tbody>\n<tr>\n<td width=\"206\">\n<h6><strong>CEREALES<\/strong><\/h6>\n<\/td>\n<td width=\"123\">\n<h6><strong>COTIZACION<\/strong><\/h6>\n<h6><strong>ANTERIOR<\/strong><\/h6>\n<\/td>\n<td width=\"132\">\n<h6><strong>COTIZACION<\/strong><\/h6>\n<h6><strong>ACTUAL<\/strong><\/h6>\n<\/td>\n<td width=\"113\">\n<h6><strong>DIF.<\/strong><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6><\/h6>\n<\/td>\n<td width=\"123\">\n<h6><strong>\u20ac\/t<\/strong><\/h6>\n<\/td>\n<td width=\"132\">\n<h6><strong>\u20ac\/t<\/strong><\/h6>\n<\/td>\n<td width=\"113\">\n<h6><strong>\u00a0<\/strong><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Trigo Pienso<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>188,00<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>187,00<\/h6>\n<\/td>\n<td width=\"113\">\n<h6>\u25bc<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Cebada<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>174,00<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>174,00<\/h6>\n<\/td>\n<td width=\"113\">\n<h6>=<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Triticale<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>S\/C<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>S\/C<\/h6>\n<\/td>\n<td width=\"113\">\n<h6><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Centeno<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>162,00<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>162,00<\/h6>\n<\/td>\n<td width=\"113\">\n<h6>=<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Avena<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>155,00<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>155,00<\/h6>\n<\/td>\n<td width=\"113\">\n<h6>=<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Ma\u00edz<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>171,00<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>171,00<\/h6>\n<\/td>\n<td width=\"113\">\n<h6>=<\/h6>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h6><\/h6>\n<h6>*\u00a0 Ma\u00edz\u00a0 con menos del 15% de humedad<\/h6>\n<h6>Actividad subvencionada por la Diputaci\u00f3n Provincial de Le\u00f3n.<\/h6>\n<table>\n<tbody>\n<tr>\n<td width=\"206\">\n<h6><strong>ALUBIAS<\/strong><\/h6>\n<\/td>\n<td width=\"123\">\n<h6><strong>COTIZACION<\/strong><\/h6>\n<h6><strong>ANTERIOR<\/strong><\/h6>\n<\/td>\n<td width=\"132\">\n<h6><strong>COTIZACION<\/strong><\/h6>\n<h6><strong>ACTUAL<\/strong><\/h6>\n<\/td>\n<td width=\"113\">\n<h6><strong>DIF.<\/strong><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6><\/h6>\n<\/td>\n<td width=\"123\">\n<h6><strong>\u20ac\/kg<\/strong><\/h6>\n<\/td>\n<td width=\"132\">\n<h6><strong>\u20ac\/kg<\/strong><\/h6>\n<\/td>\n<td width=\"113\">\n<h6><\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Canela<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>1,40<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>1,40<\/h6>\n<\/td>\n<td width=\"113\">\n<h6>=<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Negra<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>2,95<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>2,95<\/h6>\n<\/td>\n<td width=\"113\">\n<h6>=<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Palme\u00f1a Redonda<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>1,70<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>1,70<\/h6>\n<\/td>\n<td width=\"113\">\n<h6>=<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Planchada<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>1,30<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>1,30<\/h6>\n<\/td>\n<td width=\"113\">\n<h6>=<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Plancheta<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>1,45<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>1,45<\/h6>\n<\/td>\n<td width=\"113\">\n<h6>=<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Pinta<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>0,75<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>0,75<\/h6>\n<\/td>\n<td width=\"113\">\n<h6>=<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Ri\u00f1\u00f3n de Le\u00f3n<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>0,95<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>0,95<\/h6>\n<\/td>\n<td width=\"113\">\n<h6>=<\/h6>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"206\">\n<h6>Redonda<\/h6>\n<\/td>\n<td width=\"123\">\n<h6>0,95<\/h6>\n<\/td>\n<td width=\"132\">\n<h6>0,95<\/h6>\n<\/td>\n<td width=\"113\">\n<h6>=<\/h6>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h6>Actividad subvencionada por la Diputaci\u00f3n Provincial de Le\u00f3n.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La complicaci\u00f3n en las siembras de trigo este invierno ha hecho que muchos agricultores de regad\u00edo desestimasen las mismas y hayan apostado por otros cultivos alternativos, la pasada campa\u00f1a en la provincia de le\u00f3n hab\u00eda sembradas de este cereal 30.785 hect\u00e1reas y en la presente seg\u00fan nuestras estimaciones, apenas se sobrepasar\u00e1n las 23.000 ha. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":9506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,67,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estimamos una reducci\u00f3n de la superficie de trigo de regad\u00edo en el entorno del 25% - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La complicaci\u00f3n en las siembras de trigo este invierno ha hecho que muchos agricultores de regad\u00edo desestimasen las mismas y hayan apostado\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estimamos una reducci\u00f3n de la superficie de trigo de regad\u00edo en el entorno del 25% - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La complicaci\u00f3n en las siembras de trigo este invierno ha hecho que muchos agricultores de regad\u00edo desestimasen las mismas y hayan apostado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-03T18:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/11\/cultivo-encharcado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25\",\"name\":\"Estimamos una reducci\u00f3n de la superficie de trigo de regad\u00edo en el entorno del 25% - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/11\/cultivo-encharcado.jpg\",\"datePublished\":\"2019-04-03T18:01:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La complicaci\u00f3n en las siembras de trigo este invierno ha hecho que muchos agricultores de regad\u00edo desestimasen las mismas y hayan apostado\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/11\/cultivo-encharcado.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/11\/cultivo-encharcado.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estimamos una reducci\u00f3n de la superficie de trigo de regad\u00edo en el entorno del 25%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estimamos una reducci\u00f3n de la superficie de trigo de regad\u00edo en el entorno del 25% - ASAJA Le\u00f3n","description":"\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La complicaci\u00f3n en las siembras de trigo este invierno ha hecho que muchos agricultores de regad\u00edo desestimasen las mismas y hayan apostado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25","og_locale":"es_ES","og_type":"article","og_title":"Estimamos una reducci\u00f3n de la superficie de trigo de regad\u00edo en el entorno del 25% - ASAJA Le\u00f3n","og_description":"\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La complicaci\u00f3n en las siembras de trigo este invierno ha hecho que muchos agricultores de regad\u00edo desestimasen las mismas y hayan apostado","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2019-04-03T18:01:00+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/11\/cultivo-encharcado.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25","name":"Estimamos una reducci\u00f3n de la superficie de trigo de regad\u00edo en el entorno del 25% - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/11\/cultivo-encharcado.jpg","datePublished":"2019-04-03T18:01:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La complicaci\u00f3n en las siembras de trigo este invierno ha hecho que muchos agricultores de regad\u00edo desestimasen las mismas y hayan apostado","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/11\/cultivo-encharcado.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/11\/cultivo-encharcado.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/estimamos-una-reduccion-de-la-superficie-de-trigo-de-regadio-en-el-entorno-del-25#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Estimamos una reducci\u00f3n de la superficie de trigo de regad\u00edo en el entorno del 25%"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/9989"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=9989"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/9989\/revisions"}],"predecessor-version":[{"id":9990,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/9989\/revisions\/9990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/9506"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=9989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=9989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=9989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}