{"id":12792,"date":"2023-03-31T14:34:00","date_gmt":"2023-03-31T12:34:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/palencia\/?p=12792"},"modified":"2023-03-31T14:37:05","modified_gmt":"2023-03-31T12:37:05","slug":"campo-palentino-30-03-2023","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023","title":{"rendered":"Campo Palentino &#8211; 30\/03\/2023"},"content":{"rendered":"\n<p>En este programa entrevistamos al afable Mariano Bustillo, responsable del Observatorio de Carralobo (Astudillo) y que en la pasada semana ha recibido un merecido reconocimiento de la AEMET.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"kCDxhDxU6Jo\"><iframe loading=\"lazy\" title=\"&#039;Campo Palentino&#039; (30-3-2023)\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/kCDxhDxU6Jo?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En este programa entrevistamos al afable Mariano Bustillo, responsable del Observatorio de Carralobo (Astudillo) y que en la pasada semana ha recibido un merecido reconocimiento de la AEMET.<\/p>\n","protected":false},"author":9,"featured_media":12793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Campo Palentino - 30\/03\/2023 - ASAJA Palencia<\/title>\n<meta name=\"description\" content=\"En este programa entrevistamos al afable Mariano Bustillo, responsable del Observatorio de Carralobo (Astudillo) y que en la pasada semana ha recibido un\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campo Palentino - 30\/03\/2023 - ASAJA Palencia\" \/>\n<meta property=\"og:description\" content=\"En este programa entrevistamos al afable Mariano Bustillo, responsable del Observatorio de Carralobo (Astudillo) y que en la pasada semana ha recibido un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Palencia\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-31T12:34:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-31T12:37:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2023\/03\/TV-MARIANO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1275\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023\",\"name\":\"Campo Palentino - 30\/03\/2023 - ASAJA Palencia\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2023\/03\/TV-MARIANO.jpg\",\"datePublished\":\"2023-03-31T12:34:00+00:00\",\"dateModified\":\"2023-03-31T12:37:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1\"},\"description\":\"En este programa entrevistamos al afable Mariano Bustillo, responsable del Observatorio de Carralobo (Astudillo) y que en la pasada semana ha recibido un\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2023\/03\/TV-MARIANO.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2023\/03\/TV-MARIANO.jpg\",\"width\":1275,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/palencia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campo Palentino &#8211; 30\/03\/2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/\",\"name\":\"ASAJA Palencia\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1\",\"name\":\"Administrador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g\",\"caption\":\"Administrador\"},\"url\":\"https:\/\/www.asajacyl.com\/palencia\/author\/carlosrm\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campo Palentino - 30\/03\/2023 - ASAJA Palencia","description":"En este programa entrevistamos al afable Mariano Bustillo, responsable del Observatorio de Carralobo (Astudillo) y que en la pasada semana ha recibido un","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023","og_locale":"es_ES","og_type":"article","og_title":"Campo Palentino - 30\/03\/2023 - ASAJA Palencia","og_description":"En este programa entrevistamos al afable Mariano Bustillo, responsable del Observatorio de Carralobo (Astudillo) y que en la pasada semana ha recibido un","og_url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023","og_site_name":"ASAJA Palencia","article_published_time":"2023-03-31T12:34:00+00:00","article_modified_time":"2023-03-31T12:37:05+00:00","og_image":[{"width":1275,"height":655,"url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2023\/03\/TV-MARIANO.jpg","type":"image\/jpeg"}],"author":"Administrador","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Administrador","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023","url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023","name":"Campo Palentino - 30\/03\/2023 - ASAJA Palencia","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2023\/03\/TV-MARIANO.jpg","datePublished":"2023-03-31T12:34:00+00:00","dateModified":"2023-03-31T12:37:05+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1"},"description":"En este programa entrevistamos al afable Mariano Bustillo, responsable del Observatorio de Carralobo (Astudillo) y que en la pasada semana ha recibido un","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023#primaryimage","url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2023\/03\/TV-MARIANO.jpg","contentUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2023\/03\/TV-MARIANO.jpg","width":1275,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-03-2023#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/palencia\/"},{"@type":"ListItem","position":2,"name":"Campo Palentino &#8211; 30\/03\/2023"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/palencia\/#website","url":"https:\/\/www.asajacyl.com\/palencia\/","name":"ASAJA Palencia","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1","name":"Administrador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g","caption":"Administrador"},"url":"https:\/\/www.asajacyl.com\/palencia\/author\/carlosrm"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/12792"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/comments?post=12792"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/12792\/revisions"}],"predecessor-version":[{"id":12797,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/12792\/revisions\/12797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media\/12793"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media?parent=12792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/categories?post=12792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/tags?post=12792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}