{"id":17984,"date":"2024-11-08T13:04:33","date_gmt":"2024-11-08T12:04:33","guid":{"rendered":"https:\/\/www.asajacyl.com\/palencia\/?p=17984"},"modified":"2024-11-08T13:05:12","modified_gmt":"2024-11-08T12:05:12","slug":"palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region","title":{"rendered":"Palencia ya supera este a\u00f1o el centenar de casos de tularemia, con tres de cada cuatro en la regi\u00f3n"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Palencia ya ha constatado ciento dos enfermos de tularemia este 2024, acumulando pr\u00e1cticamente tres de cada cuatro casos detectados en Castilla y Le\u00f3n, seg\u00fan los datos que ha difundido este mismo viernes, 8 de noviembre, la Consejer\u00eda de Sanidad de la Junta de Castilla y Le\u00f3n. Desde que se confirm\u00f3 el primer episodio, a finales de marzo, nuestra provincia ha encabezado la incidencia del brote, tan vinculado con la proliferaci\u00f3n del topillo campesino, especie que es vector de contagio. Como ASAJA-Palencia ha venido denunciando, adem\u00e1s de los da\u00f1os en la agricultura, la proliferaci\u00f3n del topillo \u2014que adquiere rango de plaga en algunas localidades\u2014 acaba por generar problemas sanitarios. Burgos, Le\u00f3n y Valladolid son, a considerable distancia de Palencia, los tres territorios de la regi\u00f3n con m\u00e1s casos (catorce, diez y cuatro, respectivamente).<\/h2>\n\n\n\n<p>Aunque no ha alcanzado la incidencia de brotes tan graves como los de 1997-98 y 2007, la tularemia ha vuelto a estar presente este a\u00f1o en  nuestra comunidad y, de manera m\u00e1s acentuada, en la provincia de Palencia. Nuestros profesionales del campo han sido el segmento de poblaci\u00f3n m\u00e1s expuesto, pero la mera exposici\u00f3n ambiental en el medio rural ha generado muchos de los casos, en especial en el periodo estival, cuando en los pueblos hay m\u00e1s poblaci\u00f3n y se efect\u00faan m\u00e1s actividades al aire libre (paseos por los alrededores, pesca, jardiner\u00eda). <\/p>\n\n\n\n<p>No por casualidad, el pico de casos se produjo en el tr\u00e1nsito de los meses de julio y agosto, justo cuando en nuestro medio rural hay m\u00e1s poblaci\u00f3n, pero desde entonces ha continuado un goteo de positivos. El \u00faltimo mes, pr\u00e1cticamente se ha confirmado uno cada tres d\u00edas en el conjunto de la comunidad; lejos ya de la veintena de casos que se alcanzaron aquella semana 31, en pleno verano. <\/p>\n\n\n\n<p><strong>ROEDORES Y CANGREJOS.<\/strong> Los propios informes de la Direcci\u00f3n General de Salud P\u00fablica de la Junta destacan que los factores de exposici\u00f3n est\u00e1n vinculados con las actividades del campo tales como las tareas de la agricultura (siega y empacado de paja, principalmente), pero tambi\u00e9n con las labores de jardiner\u00eda, limpieza de cunetas y contacto con roedores y cangrejos de r\u00edo.<\/p>\n\n\n\n<p>Pr\u00e1cticamente, por cada caso en una mujer (19,6 % del total) hay cuatro de varones (80,4 %). La media de edad de los contagiados es bastante avanzada, 56 a\u00f1os y tres meses, pero hay casos desde edades muy tempranas (ocho a\u00f1os, el m\u00e1s joven) hasta ancianos de 92 a\u00f1os. La franja con m\u00e1s incidencia es la de los adultos de 55 a 64 a\u00f1os, con casi uno de cada cuatro casos (24,6 %). Sin embargo, entre los varones, la franja m\u00e1s com\u00fan es la inmediatamente anterior, de 45 a 54 a\u00f1os.<strong>\/<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Palencia ya ha constatado ciento dos enfermos de tularemia este 2024, acumulando pr\u00e1cticamente tres de cada cuatro casos detectados en Castilla y Le\u00f3n, seg\u00fan los datos que ha difundido este mismo viernes, 8 de noviembre, la Consejer\u00eda de Sanidad de la Junta de Castilla y Le\u00f3n. Desde que se confirm\u00f3 el primer episodio, a finales [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":17988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,29,28],"tags":[58,351,66,571,469,829],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Palencia ya supera este a\u00f1o el centenar de casos de tularemia, con tres de cada cuatro en la regi\u00f3n - ASAJA Palencia<\/title>\n<meta name=\"description\" content=\"Palencia ya ha constatado ciento dos enfermos de tularemia este 2024, acumulando pr\u00e1cticamente tres de cada cuatro casos detectados en Castilla y Le\u00f3n,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palencia ya supera este a\u00f1o el centenar de casos de tularemia, con tres de cada cuatro en la regi\u00f3n - ASAJA Palencia\" \/>\n<meta property=\"og:description\" content=\"Palencia ya ha constatado ciento dos enfermos de tularemia este 2024, acumulando pr\u00e1cticamente tres de cada cuatro casos detectados en Castilla y Le\u00f3n,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Palencia\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-08T12:04:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-08T12:05:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/11\/Topillo-campesino-huras-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1890\" \/>\n\t<meta property=\"og:image:height\" content=\"1654\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region\",\"name\":\"Palencia ya supera este a\u00f1o el centenar de casos de tularemia, con tres de cada cuatro en la regi\u00f3n - ASAJA Palencia\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/11\/Topillo-campesino-huras-web.jpg\",\"datePublished\":\"2024-11-08T12:04:33+00:00\",\"dateModified\":\"2024-11-08T12:05:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1\"},\"description\":\"Palencia ya ha constatado ciento dos enfermos de tularemia este 2024, acumulando pr\u00e1cticamente tres de cada cuatro casos detectados en Castilla y Le\u00f3n,\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/11\/Topillo-campesino-huras-web.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/11\/Topillo-campesino-huras-web.jpg\",\"width\":1890,\"height\":1654},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/palencia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palencia ya supera este a\u00f1o el centenar de casos de tularemia, con tres de cada cuatro en la regi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/\",\"name\":\"ASAJA Palencia\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1\",\"name\":\"Administrador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g\",\"caption\":\"Administrador\"},\"url\":\"https:\/\/www.asajacyl.com\/palencia\/author\/carlosrm\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palencia ya supera este a\u00f1o el centenar de casos de tularemia, con tres de cada cuatro en la regi\u00f3n - ASAJA Palencia","description":"Palencia ya ha constatado ciento dos enfermos de tularemia este 2024, acumulando pr\u00e1cticamente tres de cada cuatro casos detectados en Castilla y Le\u00f3n,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region","og_locale":"es_ES","og_type":"article","og_title":"Palencia ya supera este a\u00f1o el centenar de casos de tularemia, con tres de cada cuatro en la regi\u00f3n - ASAJA Palencia","og_description":"Palencia ya ha constatado ciento dos enfermos de tularemia este 2024, acumulando pr\u00e1cticamente tres de cada cuatro casos detectados en Castilla y Le\u00f3n,","og_url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region","og_site_name":"ASAJA Palencia","article_published_time":"2024-11-08T12:04:33+00:00","article_modified_time":"2024-11-08T12:05:12+00:00","og_image":[{"width":1890,"height":1654,"url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/11\/Topillo-campesino-huras-web.jpg","type":"image\/jpeg"}],"author":"Administrador","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Administrador","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region","url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region","name":"Palencia ya supera este a\u00f1o el centenar de casos de tularemia, con tres de cada cuatro en la regi\u00f3n - ASAJA Palencia","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/11\/Topillo-campesino-huras-web.jpg","datePublished":"2024-11-08T12:04:33+00:00","dateModified":"2024-11-08T12:05:12+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1"},"description":"Palencia ya ha constatado ciento dos enfermos de tularemia este 2024, acumulando pr\u00e1cticamente tres de cada cuatro casos detectados en Castilla y Le\u00f3n,","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region#primaryimage","url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/11\/Topillo-campesino-huras-web.jpg","contentUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/11\/Topillo-campesino-huras-web.jpg","width":1890,"height":1654},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/palencia-ya-ha-superado-este-ano-el-centenar-de-casos-de-tularemia-con-tres-de-cada-cuatro-en-la-region#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/palencia\/"},{"@type":"ListItem","position":2,"name":"Palencia ya supera este a\u00f1o el centenar de casos de tularemia, con tres de cada cuatro en la regi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/palencia\/#website","url":"https:\/\/www.asajacyl.com\/palencia\/","name":"ASAJA Palencia","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1","name":"Administrador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g","caption":"Administrador"},"url":"https:\/\/www.asajacyl.com\/palencia\/author\/carlosrm"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/17984"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/comments?post=17984"}],"version-history":[{"count":5,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/17984\/revisions"}],"predecessor-version":[{"id":17992,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/17984\/revisions\/17992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media\/17988"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media?parent=17984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/categories?post=17984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/tags?post=17984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}