{"id":19882,"date":"2025-05-17T09:00:00","date_gmt":"2025-05-17T07:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/palencia\/?p=19882"},"modified":"2025-05-16T12:19:48","modified_gmt":"2025-05-16T10:19:48","slug":"el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024","title":{"rendered":"El FEGA publica los importes unitarios definitivos con los que van a liquidarse los ecorreg\u00edmenes de 2024"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El Fondo Espa\u00f1ol de Garant\u00eda Agraria (FEGA) ha publicado ya los importes unitarios definitivos de los ecorreg\u00edmenes de la campa\u00f1a 2024, con los que se podr\u00e1n liquidar la totalidad de los pagos a los solicitantes de estas ayudas antes del 30 de junio. Los ecorreg\u00edmenes, con pr\u00e1cticas voluntarias que van m\u00e1s all\u00e1 de la l\u00ednea b\u00e1sica (condicionalidad reforzada), son una de las novedades de la vigente PAC 2023-2027. Los ecorreg\u00edmenes incluyen las diversas pr\u00e1cticas de la agricultura de carbono y agroecolog\u00eda. Con respecto a los importes definitivos de la campa\u00f1a anterior de 2023, hay ciertas diferencias en los montantes, que en algunos casos llegan a doce euros m\u00e1s por hect\u00e1rea. <\/h2>\n\n\n\n<p>As\u00ed, se abonar\u00e1n en torno a unos tres euros m\u00e1s por hect\u00e1rea que en 2023 en el primer tramo (hasta 65 hect\u00e1reas) de la pr\u00e1ctica de pastoreo extensivo, siega y biodiversidad en pastos humedos; y unos 2,2 euros m\u00e1s por hect\u00e1rea que en la campa\u00f1a de 2023 en el primer tramo (hasta 95 hect\u00e1reas) en esa misma pr\u00e1ctica en pastos mediterr\u00e1neos. Los importes en los segundos tramos son pr\u00e1cticamente id\u00e9nticos a los del precedente inmediato.<\/p>\n\n\n\n<p>En cuanto a las rotaciones y siembra directa, los importes definitivos son algo menores en el caso de los cultivos de secano, pero s\u00ed suben en los de secano h\u00famedo (unos doce euros por hect\u00e1rea) y en los de regad\u00edo (unos siete euros por hect\u00e1rea).<\/p>\n\n\n\n<p><strong>PLURIANUALIDAD. <\/strong>Recordamos que, a la hora de calcular los importes unitarios definitivos, la norma establece un complemento de plurianualidad de veinticinco euros por hect\u00e1rea en las pr\u00e1cticas de siembra directa y de cubiertas vegetales, que debe ser pagado \u00edntegramente a los titulares que contraen el compromiso de realizarlas en la siguiente campa\u00f1a.<\/p>\n\n\n\n<p>En las cubiertas vegetales e inertes en cultivos le\u00f1osos las ayudas definitivas de 2024 bajan apenas un euro, mientras en los espacios de biodiversidad se elevan en torno a euro y medio con respecto a las de la campa\u00f1a 2023. El cuadro inferior recoge los importes unitarios definitivos de los ecorreg\u00edmenes de la campa\u00f1a 2024.<\/p>\n\n\n\n<p>Una de las principales novedades de la Pol\u00edtica Agr\u00edcola Com\u00fan 2023 son los reg\u00edmenes en favor del clima y el medio ambiente, m\u00e1s<br>conocidos como ecorreg\u00edmenes. Se trata de reg\u00edmenes voluntarios para el agricultor, consistentes en pr\u00e1cticas en favor del clima y el medio ambiente, que van m\u00e1s all\u00e1 de la l\u00ednea de base (condicionalidad reforzada).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"414\" src=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2025\/05\/Pago-ecorregimenes-2024-1024x414.jpg\" alt=\"\" class=\"wp-image-19883\" style=\"width:1069px;height:auto\" srcset=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2025\/05\/Pago-ecorregimenes-2024-1024x414.jpg 1024w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2025\/05\/Pago-ecorregimenes-2024-300x121.jpg 300w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2025\/05\/Pago-ecorregimenes-2024-768x311.jpg 768w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2025\/05\/Pago-ecorregimenes-2024-1536x621.jpg 1536w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2025\/05\/Pago-ecorregimenes-2024-2048x828.jpg 2048w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2025\/05\/Pago-ecorregimenes-2024-1039x420.jpg 1039w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2025\/05\/Pago-ecorregimenes-2024-696x281.jpg 696w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2025\/05\/Pago-ecorregimenes-2024-1068x432.jpg 1068w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2025\/05\/Pago-ecorregimenes-2024-1920x776.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">FUENTE: Fondo Espa\u00f1ol de Garant\u00eda Agraria (FEGA). Ministerio de Agricultura, Pesca y Alimentaci\u00f3n (MAPA).<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Fondo Espa\u00f1ol de Garant\u00eda Agraria (FEGA) ha publicado ya los importes unitarios definitivos de los ecorreg\u00edmenes de la campa\u00f1a 2024, con los que se podr\u00e1n liquidar la totalidad de los pagos a los solicitantes de estas ayudas antes del 30 de junio. Los ecorreg\u00edmenes, con pr\u00e1cticas voluntarias que van m\u00e1s all\u00e1 de la l\u00ednea [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":17570,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,31,29,28,13],"tags":[58,59,729,142,250,1047,77,66,110,458,693,98,295,89],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El FEGA publica los importes unitarios definitivos con los que van a liquidarse los ecorreg\u00edmenes de 2024 - ASAJA Palencia<\/title>\n<meta name=\"description\" content=\"El Fondo Espa\u00f1ol de Garant\u00eda Agraria (FEGA) ha publicado ya los importes unitarios definitivos de los ecorreg\u00edmenes de la campa\u00f1a 2024, con los que se\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El FEGA publica los importes unitarios definitivos con los que van a liquidarse los ecorreg\u00edmenes de 2024 - ASAJA Palencia\" \/>\n<meta property=\"og:description\" content=\"El Fondo Espa\u00f1ol de Garant\u00eda Agraria (FEGA) ha publicado ya los importes unitarios definitivos de los ecorreg\u00edmenes de la campa\u00f1a 2024, con los que se\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Palencia\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-17T07:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/10\/Siembra-directa-ASAJA-Valladolid-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1890\" \/>\n\t<meta property=\"og:image:height\" content=\"1654\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024\",\"name\":\"El FEGA publica los importes unitarios definitivos con los que van a liquidarse los ecorreg\u00edmenes de 2024 - ASAJA Palencia\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/10\/Siembra-directa-ASAJA-Valladolid-web.jpg\",\"datePublished\":\"2025-05-17T07:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1\"},\"description\":\"El Fondo Espa\u00f1ol de Garant\u00eda Agraria (FEGA) ha publicado ya los importes unitarios definitivos de los ecorreg\u00edmenes de la campa\u00f1a 2024, con los que se\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/10\/Siembra-directa-ASAJA-Valladolid-web.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/10\/Siembra-directa-ASAJA-Valladolid-web.jpg\",\"width\":1890,\"height\":1654},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/palencia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El FEGA publica los importes unitarios definitivos con los que van a liquidarse los ecorreg\u00edmenes de 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/\",\"name\":\"ASAJA Palencia\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1\",\"name\":\"Administrador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g\",\"caption\":\"Administrador\"},\"url\":\"https:\/\/www.asajacyl.com\/palencia\/author\/carlosrm\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El FEGA publica los importes unitarios definitivos con los que van a liquidarse los ecorreg\u00edmenes de 2024 - ASAJA Palencia","description":"El Fondo Espa\u00f1ol de Garant\u00eda Agraria (FEGA) ha publicado ya los importes unitarios definitivos de los ecorreg\u00edmenes de la campa\u00f1a 2024, con los que se","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024","og_locale":"es_ES","og_type":"article","og_title":"El FEGA publica los importes unitarios definitivos con los que van a liquidarse los ecorreg\u00edmenes de 2024 - ASAJA Palencia","og_description":"El Fondo Espa\u00f1ol de Garant\u00eda Agraria (FEGA) ha publicado ya los importes unitarios definitivos de los ecorreg\u00edmenes de la campa\u00f1a 2024, con los que se","og_url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024","og_site_name":"ASAJA Palencia","article_published_time":"2025-05-17T07:00:00+00:00","og_image":[{"width":1890,"height":1654,"url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/10\/Siembra-directa-ASAJA-Valladolid-web.jpg","type":"image\/jpeg"}],"author":"Administrador","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Administrador","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024","url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024","name":"El FEGA publica los importes unitarios definitivos con los que van a liquidarse los ecorreg\u00edmenes de 2024 - ASAJA Palencia","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/10\/Siembra-directa-ASAJA-Valladolid-web.jpg","datePublished":"2025-05-17T07:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1"},"description":"El Fondo Espa\u00f1ol de Garant\u00eda Agraria (FEGA) ha publicado ya los importes unitarios definitivos de los ecorreg\u00edmenes de la campa\u00f1a 2024, con los que se","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024#primaryimage","url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/10\/Siembra-directa-ASAJA-Valladolid-web.jpg","contentUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2024\/10\/Siembra-directa-ASAJA-Valladolid-web.jpg","width":1890,"height":1654},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/el-fega-publica-los-importes-unitarios-definitivos-con-los-que-liquidar-los-ecorregimenes-2024#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/palencia\/"},{"@type":"ListItem","position":2,"name":"El FEGA publica los importes unitarios definitivos con los que van a liquidarse los ecorreg\u00edmenes de 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/palencia\/#website","url":"https:\/\/www.asajacyl.com\/palencia\/","name":"ASAJA Palencia","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1","name":"Administrador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g","caption":"Administrador"},"url":"https:\/\/www.asajacyl.com\/palencia\/author\/carlosrm"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/19882"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/comments?post=19882"}],"version-history":[{"count":3,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/19882\/revisions"}],"predecessor-version":[{"id":19891,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/19882\/revisions\/19891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media\/17570"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media?parent=19882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/categories?post=19882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/tags?post=19882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}