{"id":3416,"date":"2003-04-15T00:00:00","date_gmt":"2003-04-14T22:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/palencia\/sin-categoria\/los-seores-feudales-y-sus-castillos"},"modified":"2003-04-15T00:00:00","modified_gmt":"2003-04-14T22:00:00","slug":"los-seores-feudales-y-sus-castillos","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos","title":{"rendered":"LOS SE&#209;ORES FEUDALES Y SUS CASTILLOS"},"content":{"rendered":"<h2>El pasado 12 de marzo los regantes y las organizaciones agrarias de la provincia se trasladaron en el tiempo a la Edad Media.<\/h2>\n<p>El pasado 12 de marzo los regantes y las organizaciones agrarias de la provincia se trasladaron en el tiempo a la Edad Media. El pueblo de Palencia quer&#237;a expresar sus quejas y malestar por las deficiencias hidr&#225;ulicas de la cuenca del Carri&#243;n. Es larga ya la historia de reuniones, concentraciones, y manifestaciones que este sector ha tenido en los &#250;ltimos a&#241;os por la precariedad de los regad&#237;os de la cuenca del Carri&#243;n.<br \/>\n<br \/>\nSus inicios comenzaron en los a&#241;os 90, cuando las decisiones pol&#237;ticas privaron a esta provincia del pantano de Vidrieros y por lo tanto, de la regulaci&#243;n propia del r&#237;o Carri&#243;n. A cambio se prometi&#243; un trasvase de agua del pantano de Ria&#241;o que vendr&#237;a a solventar las escasez de embalse de los nuestros.<br \/>\n<br \/>\nNo tardaron en surgir los problemas cuando ese trasvase lleg&#243; tarde y con un presupuesto del doble de lo inicial. A esto hay que a&#241;adir la negativa de las administraciones a una concesi&#243;n de agua que se prometi&#243; en su momento y que hasta ahora no ha llegado.<br \/>\n<br \/>\nOtro punto problem&#225;tico es la cuant&#237;a a pagar por parte de los regantes sobre  la obra realizada. No se entiende que la CHD pretenda recaudar los fondos que la UE ha dado para el desarrollo palentino.<br \/>\n<br \/>\nEn m&#225;s de una d&#233;cada de lucha ha habido momentos de incertidumbre, de acercamiento con las administraciones, pero nunca como en los &#250;ltimos a&#241;os, una dejadez tan impresionante por parte de la CHD de no dar ninguna respuesta a este problema.<br \/>\n<br \/>\nEse ente dependiente del Ministerio de Medio Ambiente y con mucha autonom&#237;a propia ha dado la espalda a esta provincia. Como m&#225;s puntual destacar&#237;amos la petici&#243;n de los regantes de la cuenca del Carri&#243;n, pero sin duda alguna hay otros muchos temas en los que no se ha hecho nada. Podr&#237;amos hablar del abandono total de la limpieza de los r&#237;os, arroyos y dem&#225;s infraestructuras hidr&#225;ulicas. Podr&#237;amos hablar de la falta de di&#225;logo con las comunidades de regantes y las OPAS. Podr&#237;amos hablar del poco entendimiento con la empresa estatal Seiasa y la Consejer&#237;a de Agricultura para desarrollar inversiones en los regad&#237;os existentes o en los nuevos.<br \/>\n<br \/>\nTodos esto y alg&#250;n problema m&#225;s es lo que ha movido a las OPAS y las comunidades de regantes a buscar por todos los medios interlocutores v&#225;lidos para solucionar el problema. Entre ellos, se pens&#243; que las Cortes de Fuensalda&#241;a era la instituci&#243;n que podr&#237;a defender perfectamente y entender nuestro problema. En el pleno a celebrar el d&#237;a 12 de marzo se ten&#237;a pedida y concertada una reuni&#243;n con el presidente de las Cortes. &#205;bamos a explicarle,  como representante de los pol&#237;ticos de Castilla y Le&#243;n, nuestra problem&#225;tica, nuestra incertidumbre y la pensosa situaci&#243;n en la que nos encontramos.<br \/>\n<br \/>\nLas OPAS y los regantes del Carri&#243;n entend&#237;an que el poder pol&#237;tico all&#237; presente dar&#237;a una soluci&#243;n a esta grave situaci&#243;n. Nunca m&#225;s lejos de nuestras intenciones molestar o interferir en el trabajo diario de sus se&#241;or&#237;as los pol&#237;ticos, pero sin embargo, la respuesta de estos a trav&#233;s de los grupos de acci&#243;n rural de la Guardia Civil fue totalmente desproporcionada y falta de sentido.<br \/>\n<br \/>\nEn ese momento entendimos que los castillos siguen dando cobijo dentro de sus paredes a se&#241;ores feudales de la Edad Media con los mismos vicios, poderes y escasez de sensibilidad que aquellos ten&#237;an en su tiempo. El trato que ese d&#237;a tuvieron los regantes palentinos no es propio del siglo XXI. No es propia la contestaci&#243;n de los representantes del pueblo para defender los intereses de los regantes, y no es propio de las personas que hace casi 4 a&#241;os obtuvieron ese puesto con nuestros votos. Lamentamos desde ASAJA que siga habiendo actitudes feudalistas por parte de quien gobierna en Castilla y Le&#243;n. Lamentamos que por parte de este gobierno, en vez de solucionar los problemas, se intente callar la boca a quien los tiene por la v&#237;a de la fuerza, y desde luego, rechazamos que en el siglo XXI los castillos sigan acogiendo a hombres feudales para aplastar al pueblo  que por ley merece el respeto y ser escuchado y atendido ante la grave situaci&#243;n por los problemas que plantea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 12 de marzo los regantes y las organizaciones agrarias de la provincia se trasladaron en el tiempo a la Edad Media.<\/p>\n","protected":false},"author":3,"featured_media":1176,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,30],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LOS SE&#209;ORES FEUDALES Y SUS CASTILLOS<\/title>\n<meta name=\"description\" content=\"El pasado 12 de marzo los regantes y las organizaciones agrarias de la provincia se trasladaron en el tiempo a la Edad Media.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LOS SE&#209;ORES FEUDALES Y SUS CASTILLOS\" \/>\n<meta property=\"og:description\" content=\"El pasado 12 de marzo los regantes y las organizaciones agrarias de la provincia se trasladaron en el tiempo a la Edad Media.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Palencia\" \/>\n<meta property=\"article:published_time\" content=\"2003-04-14T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos\",\"name\":\"LOS SE&#209;ORES FEUDALES Y SUS CASTILLOS\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2003-04-14T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"El pasado 12 de marzo los regantes y las organizaciones agrarias de la provincia se trasladaron en el tiempo a la Edad Media.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/palencia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LOS SE&#209;ORES FEUDALES Y SUS CASTILLOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/\",\"name\":\"ASAJA Palencia\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/palencia\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LOS SE&#209;ORES FEUDALES Y SUS CASTILLOS","description":"El pasado 12 de marzo los regantes y las organizaciones agrarias de la provincia se trasladaron en el tiempo a la Edad Media.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos","og_locale":"es_ES","og_type":"article","og_title":"LOS SE&#209;ORES FEUDALES Y SUS CASTILLOS","og_description":"El pasado 12 de marzo los regantes y las organizaciones agrarias de la provincia se trasladaron en el tiempo a la Edad Media.","og_url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos","og_site_name":"ASAJA Palencia","article_published_time":"2003-04-14T22:00:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos","url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos","name":"LOS SE&#209;ORES FEUDALES Y SUS CASTILLOS","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos#primaryimage"},"thumbnailUrl":"","datePublished":"2003-04-14T22:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"El pasado 12 de marzo los regantes y las organizaciones agrarias de la provincia se trasladaron en el tiempo a la Edad Media.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/los-seores-feudales-y-sus-castillos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/palencia\/"},{"@type":"ListItem","position":2,"name":"LOS SE&#209;ORES FEUDALES Y SUS CASTILLOS"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/palencia\/#website","url":"https:\/\/www.asajacyl.com\/palencia\/","name":"ASAJA Palencia","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/palencia\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/3416"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/comments?post=3416"}],"version-history":[{"count":0,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/3416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media?parent=3416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/categories?post=3416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/tags?post=3416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}