{"id":3581,"date":"2015-06-08T00:00:00","date_gmt":"2015-06-07T22:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/palencia\/sin-categoria\/campo-palentino-4-junio-2015"},"modified":"2017-11-29T16:48:01","modified_gmt":"2017-11-29T15:48:01","slug":"campo-palentino-4-junio-2015","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015","title":{"rendered":"Campo Palentino 4 junio 2015"},"content":{"rendered":"<h2>Campos de ensayo de C&#225;mara Agraria, Itagra y Junta &#8211; preparando mercado de emprendedores &#8211; medidas para paliar los da&#241;os de la nieve &#8211; seguros agrarios<\/h2>\n<p><!--more--><br \/>\n<iframe loading=\"lazy\" title=\"&#039;Campo Palentino&#039; (4-6-2015)\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/GVyV04eOH68?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Campos de ensayo de C&#225;mara Agraria, Itagra y Junta &#8211; preparando mercado de emprendedores &#8211; medidas para paliar los da&#241;os de la nieve &#8211; seguros agrarios<\/p>\n","protected":false},"author":3,"featured_media":4166,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[9,8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Campo Palentino 4 junio 2015 - ASAJA Palencia<\/title>\n<meta name=\"description\" content=\"Campos de ensayo de C&#225;mara Agraria, Itagra y Junta - preparando mercado de emprendedores - medidas para paliar los da&#241;os de la nieve - seguros agrarios\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campo Palentino 4 junio 2015 - ASAJA Palencia\" \/>\n<meta property=\"og:description\" content=\"Campos de ensayo de C&#225;mara Agraria, Itagra y Junta - preparando mercado de emprendedores - medidas para paliar los da&#241;os de la nieve - seguros agrarios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Palencia\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-07T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-29T15:48:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-374.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015\",\"name\":\"Campo Palentino 4 junio 2015 - ASAJA Palencia\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-374.jpg\",\"datePublished\":\"2015-06-07T22:00:00+00:00\",\"dateModified\":\"2017-11-29T15:48:01+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Campos de ensayo de C&#225;mara Agraria, Itagra y Junta - preparando mercado de emprendedores - medidas para paliar los da&#241;os de la nieve - seguros agrarios\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-374.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-374.jpg\",\"width\":480,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/palencia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campo Palentino 4 junio 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/\",\"name\":\"ASAJA Palencia\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/palencia\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campo Palentino 4 junio 2015 - ASAJA Palencia","description":"Campos de ensayo de C&#225;mara Agraria, Itagra y Junta - preparando mercado de emprendedores - medidas para paliar los da&#241;os de la nieve - seguros agrarios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015","og_locale":"es_ES","og_type":"article","og_title":"Campo Palentino 4 junio 2015 - ASAJA Palencia","og_description":"Campos de ensayo de C&#225;mara Agraria, Itagra y Junta - preparando mercado de emprendedores - medidas para paliar los da&#241;os de la nieve - seguros agrarios","og_url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015","og_site_name":"ASAJA Palencia","article_published_time":"2015-06-07T22:00:00+00:00","article_modified_time":"2017-11-29T15:48:01+00:00","og_image":[{"width":480,"height":360,"url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-374.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015","url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015","name":"Campo Palentino 4 junio 2015 - ASAJA Palencia","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-374.jpg","datePublished":"2015-06-07T22:00:00+00:00","dateModified":"2017-11-29T15:48:01+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Campos de ensayo de C&#225;mara Agraria, Itagra y Junta - preparando mercado de emprendedores - medidas para paliar los da&#241;os de la nieve - seguros agrarios","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015#primaryimage","url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-374.jpg","contentUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-374.jpg","width":480,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-junio-2015#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/palencia\/"},{"@type":"ListItem","position":2,"name":"Campo Palentino 4 junio 2015"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/palencia\/#website","url":"https:\/\/www.asajacyl.com\/palencia\/","name":"ASAJA Palencia","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/palencia\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/3581"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/comments?post=3581"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/3581\/revisions"}],"predecessor-version":[{"id":3908,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/3581\/revisions\/3908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media\/4166"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media?parent=3581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/categories?post=3581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/tags?post=3581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}