{"id":3622,"date":"2014-12-11T00:00:00","date_gmt":"2014-12-10T23:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/palencia\/sin-categoria\/campo-palentino-4-diciembre-2014"},"modified":"2017-11-29T16:49:17","modified_gmt":"2017-11-29T15:49:17","slug":"campo-palentino-4-diciembre-2014","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014","title":{"rendered":"CAMPO PALENTINO 4 diciembre 2014"},"content":{"rendered":"<h2>ASAJA denuncia nuevos ataques de lobos en Cervera y La Lastra, entrevista a Jos&#233; F&#233;lix Curieses tras el congreso nacional de j&#243;venes agricultores, participaci&#243;n de ASAJA PALENCIA en la jornada sobre ovino de leche de Vi&#241;alta, ASAJA pide una soluci&#243;n permanente al problema de las ITV de las cabinas, el d&#237;a 20 finaliza el plazo para el seguro agrario<\/h2>\n<p><!--more--><br \/>\n<iframe loading=\"lazy\" title=\"Campo Palentino 4 Diciembre de 2014\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/sZPMxt34Zzg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ASAJA denuncia nuevos ataques de lobos en Cervera y La Lastra, entrevista a Jos&#233; F&#233;lix Curieses tras el congreso nacional de j&#243;venes agricultores, participaci&#243;n de ASAJA PALENCIA en la jornada sobre ovino de leche de Vi&#241;alta, ASAJA pide una soluci&#243;n permanente al problema de las ITV de las cabinas, el d&#237;a 20 finaliza el plazo para el seguro agrario<\/p>\n","protected":false},"author":3,"featured_media":4215,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[9,8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CAMPO PALENTINO 4 diciembre 2014 - ASAJA Palencia<\/title>\n<meta name=\"description\" content=\"ASAJA denuncia nuevos ataques de lobos en Cervera y La Lastra, entrevista a Jos&#233; F&#233;lix Curieses tras el congreso nacional de j&#243;venes agricultores, participaci&#243;n de ASAJA PALENCIA en la jornada sobre ovino de leche de Vi&#241;alta, ASAJA pide una soluci&#243;n permanente al problema de las ITV de las cabinas, el d&#237;a 20 finaliza el plazo para el seguro agrario\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAMPO PALENTINO 4 diciembre 2014 - ASAJA Palencia\" \/>\n<meta property=\"og:description\" content=\"ASAJA denuncia nuevos ataques de lobos en Cervera y La Lastra, entrevista a Jos&#233; F&#233;lix Curieses tras el congreso nacional de j&#243;venes agricultores, participaci&#243;n de ASAJA PALENCIA en la jornada sobre ovino de leche de Vi&#241;alta, ASAJA pide una soluci&#243;n permanente al problema de las ITV de las cabinas, el d&#237;a 20 finaliza el plazo para el seguro agrario\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Palencia\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-10T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-29T15:49:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-393.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014\",\"name\":\"CAMPO PALENTINO 4 diciembre 2014 - ASAJA Palencia\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-393.jpg\",\"datePublished\":\"2014-12-10T23:00:00+00:00\",\"dateModified\":\"2017-11-29T15:49:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"ASAJA denuncia nuevos ataques de lobos en Cervera y La Lastra, entrevista a Jos&#233; F&#233;lix Curieses tras el congreso nacional de j&#243;venes agricultores, participaci&#243;n de ASAJA PALENCIA en la jornada sobre ovino de leche de Vi&#241;alta, ASAJA pide una soluci&#243;n permanente al problema de las ITV de las cabinas, el d&#237;a 20 finaliza el plazo para el seguro agrario\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-393.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-393.jpg\",\"width\":480,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/palencia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CAMPO PALENTINO 4 diciembre 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/\",\"name\":\"ASAJA Palencia\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/palencia\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAMPO PALENTINO 4 diciembre 2014 - ASAJA Palencia","description":"ASAJA denuncia nuevos ataques de lobos en Cervera y La Lastra, entrevista a Jos&#233; F&#233;lix Curieses tras el congreso nacional de j&#243;venes agricultores, participaci&#243;n de ASAJA PALENCIA en la jornada sobre ovino de leche de Vi&#241;alta, ASAJA pide una soluci&#243;n permanente al problema de las ITV de las cabinas, el d&#237;a 20 finaliza el plazo para el seguro agrario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014","og_locale":"es_ES","og_type":"article","og_title":"CAMPO PALENTINO 4 diciembre 2014 - ASAJA Palencia","og_description":"ASAJA denuncia nuevos ataques de lobos en Cervera y La Lastra, entrevista a Jos&#233; F&#233;lix Curieses tras el congreso nacional de j&#243;venes agricultores, participaci&#243;n de ASAJA PALENCIA en la jornada sobre ovino de leche de Vi&#241;alta, ASAJA pide una soluci&#243;n permanente al problema de las ITV de las cabinas, el d&#237;a 20 finaliza el plazo para el seguro agrario","og_url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014","og_site_name":"ASAJA Palencia","article_published_time":"2014-12-10T23:00:00+00:00","article_modified_time":"2017-11-29T15:49:17+00:00","og_image":[{"width":480,"height":360,"url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-393.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014","url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014","name":"CAMPO PALENTINO 4 diciembre 2014 - ASAJA Palencia","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-393.jpg","datePublished":"2014-12-10T23:00:00+00:00","dateModified":"2017-11-29T15:49:17+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"ASAJA denuncia nuevos ataques de lobos en Cervera y La Lastra, entrevista a Jos&#233; F&#233;lix Curieses tras el congreso nacional de j&#243;venes agricultores, participaci&#243;n de ASAJA PALENCIA en la jornada sobre ovino de leche de Vi&#241;alta, ASAJA pide una soluci&#243;n permanente al problema de las ITV de las cabinas, el d&#237;a 20 finaliza el plazo para el seguro agrario","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014#primaryimage","url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-393.jpg","contentUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-393.jpg","width":480,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-4-diciembre-2014#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/palencia\/"},{"@type":"ListItem","position":2,"name":"CAMPO PALENTINO 4 diciembre 2014"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/palencia\/#website","url":"https:\/\/www.asajacyl.com\/palencia\/","name":"ASAJA Palencia","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/palencia\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/3622"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/comments?post=3622"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/3622\/revisions"}],"predecessor-version":[{"id":4213,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/3622\/revisions\/4213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media\/4215"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media?parent=3622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/categories?post=3622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/tags?post=3622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}