{"id":3644,"date":"2014-06-27T00:00:00","date_gmt":"2014-06-26T22:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/palencia\/sin-categoria\/campo-palentino-26-junio-2014"},"modified":"2017-11-29T16:50:00","modified_gmt":"2017-11-29T15:50:00","slug":"campo-palentino-26-junio-2014","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014","title":{"rendered":"Campo Palentino 26 junio 2014"},"content":{"rendered":"<h2>M&#225;s de 70.000 Has afectadas por el topillo, adelanto de cosecha para las agroambientales, partes de siniestros en seguros agrarios, ganader&#237;a caballar de Jes&#250;s Lobete, ASAJA despedir&#225; el verano con las vacaciones en Pe&#241;&#237;scola&#8230;<\/h2>\n<p><!--more--><br \/>\n<iframe loading=\"lazy\" title=\"Programa Campo Palentino 26 Junio de 2014\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/JtlI_BRpD6A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M&#225;s de 70.000 Has afectadas por el topillo, adelanto de cosecha para las agroambientales, partes de siniestros en seguros agrarios, ganader&#237;a caballar de Jes&#250;s Lobete, ASAJA despedir&#225; el verano con las vacaciones en Pe&#241;&#237;scola&#8230;<\/p>\n","protected":false},"author":3,"featured_media":4248,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[9,8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Campo Palentino 26 junio 2014 - ASAJA Palencia<\/title>\n<meta name=\"description\" content=\"M&#225;s de 70.000 Has afectadas por el topillo, adelanto de cosecha para las agroambientales, partes de siniestros en seguros agrarios, ganader&#237;a caballar de Jes&#250;s Lobete, ASAJA despedir&#225; el verano con las vacaciones en Pe&#241;&#237;scola...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campo Palentino 26 junio 2014 - ASAJA Palencia\" \/>\n<meta property=\"og:description\" content=\"M&#225;s de 70.000 Has afectadas por el topillo, adelanto de cosecha para las agroambientales, partes de siniestros en seguros agrarios, ganader&#237;a caballar de Jes&#250;s Lobete, ASAJA despedir&#225; el verano con las vacaciones en Pe&#241;&#237;scola...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Palencia\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-26T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-29T15:50:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-404.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014\",\"name\":\"Campo Palentino 26 junio 2014 - ASAJA Palencia\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-404.jpg\",\"datePublished\":\"2014-06-26T22:00:00+00:00\",\"dateModified\":\"2017-11-29T15:50:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"M&#225;s de 70.000 Has afectadas por el topillo, adelanto de cosecha para las agroambientales, partes de siniestros en seguros agrarios, ganader&#237;a caballar de Jes&#250;s Lobete, ASAJA despedir&#225; el verano con las vacaciones en Pe&#241;&#237;scola...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-404.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-404.jpg\",\"width\":480,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/palencia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campo Palentino 26 junio 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/\",\"name\":\"ASAJA Palencia\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/palencia\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campo Palentino 26 junio 2014 - ASAJA Palencia","description":"M&#225;s de 70.000 Has afectadas por el topillo, adelanto de cosecha para las agroambientales, partes de siniestros en seguros agrarios, ganader&#237;a caballar de Jes&#250;s Lobete, ASAJA despedir&#225; el verano con las vacaciones en Pe&#241;&#237;scola...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014","og_locale":"es_ES","og_type":"article","og_title":"Campo Palentino 26 junio 2014 - ASAJA Palencia","og_description":"M&#225;s de 70.000 Has afectadas por el topillo, adelanto de cosecha para las agroambientales, partes de siniestros en seguros agrarios, ganader&#237;a caballar de Jes&#250;s Lobete, ASAJA despedir&#225; el verano con las vacaciones en Pe&#241;&#237;scola...","og_url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014","og_site_name":"ASAJA Palencia","article_published_time":"2014-06-26T22:00:00+00:00","article_modified_time":"2017-11-29T15:50:00+00:00","og_image":[{"width":480,"height":360,"url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-404.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014","url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014","name":"Campo Palentino 26 junio 2014 - ASAJA Palencia","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-404.jpg","datePublished":"2014-06-26T22:00:00+00:00","dateModified":"2017-11-29T15:50:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"M&#225;s de 70.000 Has afectadas por el topillo, adelanto de cosecha para las agroambientales, partes de siniestros en seguros agrarios, ganader&#237;a caballar de Jes&#250;s Lobete, ASAJA despedir&#225; el verano con las vacaciones en Pe&#241;&#237;scola...","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014#primaryimage","url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-404.jpg","contentUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-404.jpg","width":480,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-26-junio-2014#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/palencia\/"},{"@type":"ListItem","position":2,"name":"Campo Palentino 26 junio 2014"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/palencia\/#website","url":"https:\/\/www.asajacyl.com\/palencia\/","name":"ASAJA Palencia","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/palencia\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/3644"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/comments?post=3644"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/3644\/revisions"}],"predecessor-version":[{"id":4246,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/3644\/revisions\/4246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media\/4248"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media?parent=3644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/categories?post=3644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/tags?post=3644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}