{"id":3682,"date":"2014-01-31T00:00:00","date_gmt":"2014-01-30T23:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/palencia\/sin-categoria\/campo-palentino-30-enero-2014"},"modified":"2017-11-29T16:51:30","modified_gmt":"2017-11-29T15:51:30","slug":"campo-palentino-30-enero-2014","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014","title":{"rendered":"Campo Palentino 30 enero 2014"},"content":{"rendered":"<h2>Asamblea nacional de ASAJA reelecci&#243;n Pedro Barato y Donaciano Dujo, proximo fin de la campa&#241;a de remolacha, se iniciaron las asambleas comarcales de ASAJA PALENCIA, pr&#243;ximos cursos de ASAJA, seguros agrarios y ganaderos<\/h2>\n<p><!--more--><br \/>\n<iframe loading=\"lazy\" title=\"Programa Campo Palentino 30 de Enero de 2014\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/TTohPfbG1g4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asamblea nacional de ASAJA reelecci&#243;n Pedro Barato y Donaciano Dujo, proximo fin de la campa&#241;a de remolacha, se iniciaron las asambleas comarcales de ASAJA PALENCIA, pr&#243;ximos cursos de ASAJA, seguros agrarios y ganaderos<\/p>\n","protected":false},"author":3,"featured_media":4305,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[9,8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Campo Palentino 30 enero 2014 - ASAJA Palencia<\/title>\n<meta name=\"description\" content=\"Asamblea nacional de ASAJA reelecci&#243;n Pedro Barato y Donaciano Dujo, proximo fin de la campa&#241;a de remolacha, se iniciaron las asambleas comarcales de ASAJA PALENCIA, pr&#243;ximos cursos de ASAJA, seguros agrarios y ganaderos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campo Palentino 30 enero 2014 - ASAJA Palencia\" \/>\n<meta property=\"og:description\" content=\"Asamblea nacional de ASAJA reelecci&#243;n Pedro Barato y Donaciano Dujo, proximo fin de la campa&#241;a de remolacha, se iniciaron las asambleas comarcales de ASAJA PALENCIA, pr&#243;ximos cursos de ASAJA, seguros agrarios y ganaderos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Palencia\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-30T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-29T15:51:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-423.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014\",\"name\":\"Campo Palentino 30 enero 2014 - ASAJA Palencia\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-423.jpg\",\"datePublished\":\"2014-01-30T23:00:00+00:00\",\"dateModified\":\"2017-11-29T15:51:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Asamblea nacional de ASAJA reelecci&#243;n Pedro Barato y Donaciano Dujo, proximo fin de la campa&#241;a de remolacha, se iniciaron las asambleas comarcales de ASAJA PALENCIA, pr&#243;ximos cursos de ASAJA, seguros agrarios y ganaderos\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-423.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-423.jpg\",\"width\":480,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/palencia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campo Palentino 30 enero 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/\",\"name\":\"ASAJA Palencia\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/palencia\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campo Palentino 30 enero 2014 - ASAJA Palencia","description":"Asamblea nacional de ASAJA reelecci&#243;n Pedro Barato y Donaciano Dujo, proximo fin de la campa&#241;a de remolacha, se iniciaron las asambleas comarcales de ASAJA PALENCIA, pr&#243;ximos cursos de ASAJA, seguros agrarios y ganaderos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014","og_locale":"es_ES","og_type":"article","og_title":"Campo Palentino 30 enero 2014 - ASAJA Palencia","og_description":"Asamblea nacional de ASAJA reelecci&#243;n Pedro Barato y Donaciano Dujo, proximo fin de la campa&#241;a de remolacha, se iniciaron las asambleas comarcales de ASAJA PALENCIA, pr&#243;ximos cursos de ASAJA, seguros agrarios y ganaderos","og_url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014","og_site_name":"ASAJA Palencia","article_published_time":"2014-01-30T23:00:00+00:00","article_modified_time":"2017-11-29T15:51:30+00:00","og_image":[{"width":480,"height":360,"url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-423.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014","url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014","name":"Campo Palentino 30 enero 2014 - ASAJA Palencia","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-423.jpg","datePublished":"2014-01-30T23:00:00+00:00","dateModified":"2017-11-29T15:51:30+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Asamblea nacional de ASAJA reelecci&#243;n Pedro Barato y Donaciano Dujo, proximo fin de la campa&#241;a de remolacha, se iniciaron las asambleas comarcales de ASAJA PALENCIA, pr&#243;ximos cursos de ASAJA, seguros agrarios y ganaderos","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014#primaryimage","url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-423.jpg","contentUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/11\/hqdefault-423.jpg","width":480,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/videos\/campo-palentino-30-enero-2014#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/palencia\/"},{"@type":"ListItem","position":2,"name":"Campo Palentino 30 enero 2014"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/palencia\/#website","url":"https:\/\/www.asajacyl.com\/palencia\/","name":"ASAJA Palencia","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/palencia\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/3682"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/comments?post=3682"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/3682\/revisions"}],"predecessor-version":[{"id":4303,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/3682\/revisions\/4303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media\/4305"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media?parent=3682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/categories?post=3682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/tags?post=3682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}