{"id":5358,"date":"2018-09-05T14:23:02","date_gmt":"2018-09-05T12:23:02","guid":{"rendered":"https:\/\/www.asajacyl.com\/palencia\/?p=5358"},"modified":"2018-09-05T14:26:03","modified_gmt":"2018-09-05T12:26:03","slug":"despues-la-cosecha","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha","title":{"rendered":"Despu\u00e9s de la cosecha"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4919\" src=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-300x225.jpg 300w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-768x576.jpg 768w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-1024x768.jpg 1024w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-80x60.jpg 80w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-696x522.jpg 696w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-1068x801.jpg 1068w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-560x420.jpg 560w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-1920x1440.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><strong>POR HONORATO MENESES, PRESIDENTE DE ASAJA PALENCIA<\/strong><\/p>\n<p>Cuando las cosechadoras dan por concluida su labor en la provincia, ya se pueden avanzar los datos pr\u00e1cticamente definitivos de campa\u00f1a y con los que se puede decir que se han cumplido las expectativas que se manejaban.<\/p>\n<p>Unos datos que hablan de 1,26 millones de toneladas en la provincia, con rendimientos medios de m\u00e1s de cuatro mil kilos por hect\u00e1rea, lo que la convertir\u00eda en una de las mejores cosechas de los \u00faltimos a\u00f1os.<\/p>\n<p>Eso s\u00ed, para llegar al final de la campa\u00f1a los agricultores han sufrido lo suyo. Primero, porque se sembr\u00f3 en seco y las plantas acusaron la falta de agua en momentos vitales de su crecimiento. Vinieron luego las lluvias que dieron la vuelta al pesimismo y al aspecto del campo, aunque m\u00e1s tarde, convertidas en pedrisco, ensombrecieron de nuevo el panorama principalmente en la comarca de Boedo Ojeda.<\/p>\n<p>Por todo esto somos optimistas, pero al optimismo hay que restarle las p\u00e9rdidas causadas por el granizo cuando ya estaba avanzado el verano. Y por supuesto, hay que tener en cuenta que los costes de producci\u00f3n han sido muy altos a lo largo del a\u00f1o a causa del incremento del precio del gas\u00f3leo,\u00a0 los fertilizantes y los fitosanitarios.<\/p>\n<p>Hemos llegado a finales de agosto y ahora hay que \u201ccerrar\u201d una campa\u00f1a tard\u00eda, un proceso que no acaba hasta que el cereal se ha vendido. Un a\u00f1o puede ser bueno en producciones, pero tienen que acompa\u00f1ar los precios y aqu\u00ed, en casa, poco tenemos que decir los agricultores, porque como bien es sabido, son referencias que se marcan en los mercados internacionales.<\/p>\n<p>Es cierto que despu\u00e9s de un largo periodo de bajadas, repuntan los precios en el mercado interior, quiz\u00e1s porque los grandes productores mundiales manejan bajas previsiones de cosecha. Por eso ya no se cumple aquello de que a m\u00e1s cosecha menos precio, y viceversa, dado que ahora estamos inmersos en un mercado globalizado.<\/p>\n<p>A pesar de las buenas cifras de producci\u00f3n de cereal en Espa\u00f1a, seguimos siendo deficitarios y por tanto, dependemos del mercado exterior. Necesitamos que esas cifras se traduzcan en liquidez para compensar la cat\u00e1strofe de la pasada campa\u00f1a a causa de la sequ\u00eda.<\/p>\n<p>Precisamente las circunstancias meteorol\u00f3gicas que se han producido en estas dos \u00faltimas campa\u00f1as -sequ\u00eda y pedrisco- confirman la importancia de contar con un seguro\u00a0 agrario, una herramienta imprescindible en la explotaci\u00f3n que debe ser asumida como un coste fijo y confiarla a los expertos. El sistema de seguros en Espa\u00f1a es bueno, pero desde ASAJA seguimos trabajando en aquellos aspectos susceptibles de mejorar, como algunas coberturas y rendimientos en determinadas comarcas y producciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POR HONORATO MENESES, PRESIDENTE DE ASAJA PALENCIA Cuando las cosechadoras dan por concluida su labor en la provincia, ya se pueden avanzar los datos pr\u00e1cticamente definitivos de campa\u00f1a y con los que se puede decir que se han cumplido las expectativas que se manejaban. Unos datos que hablan de 1,26 millones de toneladas en la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":4919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,30],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Despu\u00e9s de la cosecha - ASAJA Palencia<\/title>\n<meta name=\"description\" content=\"POR HONORATO MENESES, PRESIDENTE DE ASAJA PALENCIA Cuando las cosechadoras dan por concluida su labor en la provincia, ya se pueden avanzar los datos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Despu\u00e9s de la cosecha - ASAJA Palencia\" \/>\n<meta property=\"og:description\" content=\"POR HONORATO MENESES, PRESIDENTE DE ASAJA PALENCIA Cuando las cosechadoras dan por concluida su labor en la provincia, ya se pueden avanzar los datos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Palencia\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-05T12:23:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-05T12:26:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha\",\"name\":\"Despu\u00e9s de la cosecha - ASAJA Palencia\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg\",\"datePublished\":\"2018-09-05T12:23:02+00:00\",\"dateModified\":\"2018-09-05T12:26:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1\"},\"description\":\"POR HONORATO MENESES, PRESIDENTE DE ASAJA PALENCIA Cuando las cosechadoras dan por concluida su labor en la provincia, ya se pueden avanzar los datos\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg\",\"width\":2500,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/palencia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Despu\u00e9s de la cosecha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/\",\"name\":\"ASAJA Palencia\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1\",\"name\":\"Administrador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g\",\"caption\":\"Administrador\"},\"url\":\"https:\/\/www.asajacyl.com\/palencia\/author\/carlosrm\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Despu\u00e9s de la cosecha - ASAJA Palencia","description":"POR HONORATO MENESES, PRESIDENTE DE ASAJA PALENCIA Cuando las cosechadoras dan por concluida su labor en la provincia, ya se pueden avanzar los datos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha","og_locale":"es_ES","og_type":"article","og_title":"Despu\u00e9s de la cosecha - ASAJA Palencia","og_description":"POR HONORATO MENESES, PRESIDENTE DE ASAJA PALENCIA Cuando las cosechadoras dan por concluida su labor en la provincia, ya se pueden avanzar los datos","og_url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha","og_site_name":"ASAJA Palencia","article_published_time":"2018-09-05T12:23:02+00:00","article_modified_time":"2018-09-05T12:26:03+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg","type":"image\/jpeg"}],"author":"Administrador","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Administrador","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha","url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha","name":"Despu\u00e9s de la cosecha - ASAJA Palencia","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg","datePublished":"2018-09-05T12:23:02+00:00","dateModified":"2018-09-05T12:26:03+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1"},"description":"POR HONORATO MENESES, PRESIDENTE DE ASAJA PALENCIA Cuando las cosechadoras dan por concluida su labor en la provincia, ya se pueden avanzar los datos","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha#primaryimage","url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg","contentUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg","width":2500,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/despues-la-cosecha#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/palencia\/"},{"@type":"ListItem","position":2,"name":"Despu\u00e9s de la cosecha"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/palencia\/#website","url":"https:\/\/www.asajacyl.com\/palencia\/","name":"ASAJA Palencia","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1","name":"Administrador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g","caption":"Administrador"},"url":"https:\/\/www.asajacyl.com\/palencia\/author\/carlosrm"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/5358"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/comments?post=5358"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/5358\/revisions"}],"predecessor-version":[{"id":5359,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/5358\/revisions\/5359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media\/4919"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media?parent=5358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/categories?post=5358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/tags?post=5358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}