{"id":6393,"date":"2019-07-05T13:47:30","date_gmt":"2019-07-05T11:47:30","guid":{"rendered":"https:\/\/www.asajacyl.com\/palencia\/?p=6393"},"modified":"2019-07-05T13:47:30","modified_gmt":"2019-07-05T11:47:30","slug":"trece-anos-seguimos-igual","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual","title":{"rendered":"Trece a\u00f1os y seguimos igual"},"content":{"rendered":"<h4>Por Honorato Meneses, presidente de ASAJA Palencia<\/h4>\n<p>Lo que empez\u00f3 como un problema del sector agrario se convirti\u00f3 despu\u00e9s en un problema medioambiental y acab\u00f3 siendo un problema sanitario. Me estoy refiriendo a lo sucedido entre 2006 y 2008 en la provincia.<\/p>\n<p>ASAJA cifr\u00f3 entonces en 30 millones de euros las p\u00e9rdidas econ\u00f3micas provocadas por la plaga de topillos en los cultivos. Pero junto a las p\u00e9rdidas econ\u00f3micas, hubo otra: cientos de enfermos de tularemia, muchos de los cuales arrastraron las secuelas durante a\u00f1os.<\/p>\n<p>Lo que estamos viendo este a\u00f1o en el campo se parece bastante al escenario de 2007. Al principio de la campa\u00f1a ASAJA ha denunciado la superpoblaci\u00f3n de topillos, sin que se hayan ofrecido soluciones reales.<\/p>\n<p>Cuando est\u00e1 acabando la campa\u00f1a, la situaci\u00f3n se repite: p\u00e9rdidas econ\u00f3micas, cultivos arrasados, da\u00f1os en cereal, leguminosas, girasol y forrajes. Pero lo peor parece que est\u00e1 por venir, a juzgar por la contaminaci\u00f3n que estamos viendo en r\u00edos, arroyos y acequias: miles de topillos muertos flotando sobre las aguas.<\/p>\n<p>El espect\u00e1culo es desalentador: paisajes rodeados de topillos vivos y muertos, moscas enormes y desagradables olores por la descomposici\u00f3n de los animales. Pero lo peor es el problema sanitario que puede reproducirse, ya que con este panorama vuelve el temor a la tularemia, una enfermedad asociada cient\u00edficamente a la superpoblaci\u00f3n de topillos.<\/p>\n<p>El problema que hasta ahora se circunscrib\u00eda a la agricultura trasciende a la sociedad. La presencia de topillos muertos en las parcelas, en fase de descomposici\u00f3n, atrae la plaga de mosca negra. A ello se suma la garrapata de los topillos vivos, par\u00e1sitos que propagan todo tipo de enfermedades. Las liebres y conejos se contagian de la tularemia, e incluso los cangrejos se infectan de igual forma. Por tanto afecta a la caza y la pesca, pero tambi\u00e9n a los miles de veraneantes y vecinos de nuestros pueblos.<\/p>\n<p>La contaminaci\u00f3n de los cauces plagados de topillos muertos incrementa las dudas sobre la salubridad de las aguas, y por lo tanto, del abastecimiento de nucleos rurales y la capital. Los topillos ya pueden verse correteando por parques, jardines y piscinas de los pueblos .<\/p>\n<p>Se trata de un c\u00famulo de circunstancias que hace necesaria la intervenci\u00f3n urgente de la administraci\u00f3n. Por ello desde ASAJA exigimos que se tomen las medidas oportunas para que exista el m\u00ednimo riesgo de enfermedad y contagio, y se garanticen las condiciones sanitarias en los pueblos.<\/p>\n<p>Lo que ha resultado ineficaz es el programa de vigilancia de las poblaciones de topillo de la Junta y las recomendaciones al respecto. Por lo tanto tampoco sirve que ahora la Consejer\u00eda notifique la alerta para que\u00a0 los agricultores hagan seguimiento de la plaga y tengan en cuenta esas recomendaciones, ya que el descontrolado aumento del topillo requiere de intervenciones eficaces y r\u00e1pidas.<\/p>\n<p><a href=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4919\" src=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-300x225.jpg 300w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-768x576.jpg 768w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-1024x768.jpg 1024w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-80x60.jpg 80w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-696x522.jpg 696w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-1068x801.jpg 1068w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-560x420.jpg 560w, https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses-1920x1440.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Honorato Meneses, presidente de ASAJA Palencia Lo que empez\u00f3 como un problema del sector agrario se convirti\u00f3 despu\u00e9s en un problema medioambiental y acab\u00f3 siendo un problema sanitario. Me estoy refiriendo a lo sucedido entre 2006 y 2008 en la provincia. ASAJA cifr\u00f3 entonces en 30 millones de euros las p\u00e9rdidas econ\u00f3micas provocadas por [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":4919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trece a\u00f1os y seguimos igual - ASAJA Palencia<\/title>\n<meta name=\"description\" content=\"Por Honorato Meneses, presidente de ASAJA Palencia Lo que empez\u00f3 como un problema del sector agrario se convirti\u00f3 despu\u00e9s en un problema medioambiental y\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trece a\u00f1os y seguimos igual - ASAJA Palencia\" \/>\n<meta property=\"og:description\" content=\"Por Honorato Meneses, presidente de ASAJA Palencia Lo que empez\u00f3 como un problema del sector agrario se convirti\u00f3 despu\u00e9s en un problema medioambiental y\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Palencia\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-05T11:47:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual\",\"name\":\"Trece a\u00f1os y seguimos igual - ASAJA Palencia\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg\",\"datePublished\":\"2019-07-05T11:47:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1\"},\"description\":\"Por Honorato Meneses, presidente de ASAJA Palencia Lo que empez\u00f3 como un problema del sector agrario se convirti\u00f3 despu\u00e9s en un problema medioambiental y\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg\",\"width\":2500,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/palencia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trece a\u00f1os y seguimos igual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/\",\"name\":\"ASAJA Palencia\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1\",\"name\":\"Administrador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g\",\"caption\":\"Administrador\"},\"url\":\"https:\/\/www.asajacyl.com\/palencia\/author\/carlosrm\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trece a\u00f1os y seguimos igual - ASAJA Palencia","description":"Por Honorato Meneses, presidente de ASAJA Palencia Lo que empez\u00f3 como un problema del sector agrario se convirti\u00f3 despu\u00e9s en un problema medioambiental y","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual","og_locale":"es_ES","og_type":"article","og_title":"Trece a\u00f1os y seguimos igual - ASAJA Palencia","og_description":"Por Honorato Meneses, presidente de ASAJA Palencia Lo que empez\u00f3 como un problema del sector agrario se convirti\u00f3 despu\u00e9s en un problema medioambiental y","og_url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual","og_site_name":"ASAJA Palencia","article_published_time":"2019-07-05T11:47:30+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg","type":"image\/jpeg"}],"author":"Administrador","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Administrador","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual","url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual","name":"Trece a\u00f1os y seguimos igual - ASAJA Palencia","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg","datePublished":"2019-07-05T11:47:30+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1"},"description":"Por Honorato Meneses, presidente de ASAJA Palencia Lo que empez\u00f3 como un problema del sector agrario se convirti\u00f3 despu\u00e9s en un problema medioambiental y","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual#primaryimage","url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg","contentUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2017\/12\/Honorato-Meneses.jpg","width":2500,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/trece-anos-seguimos-igual#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/palencia\/"},{"@type":"ListItem","position":2,"name":"Trece a\u00f1os y seguimos igual"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/palencia\/#website","url":"https:\/\/www.asajacyl.com\/palencia\/","name":"ASAJA Palencia","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1","name":"Administrador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g","caption":"Administrador"},"url":"https:\/\/www.asajacyl.com\/palencia\/author\/carlosrm"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/6393"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/comments?post=6393"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/6393\/revisions"}],"predecessor-version":[{"id":6394,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/6393\/revisions\/6394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media\/4919"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media?parent=6393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/categories?post=6393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/tags?post=6393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}