{"id":9667,"date":"2022-01-11T16:28:00","date_gmt":"2022-01-11T15:28:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/palencia\/?p=9667"},"modified":"2022-01-10T11:31:03","modified_gmt":"2022-01-10T10:31:03","slug":"dos-modelos-ganaderos","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos","title":{"rendered":"Dos modelos ganaderos"},"content":{"rendered":"\n<p><strong><em>Jos\u00e9 Antonio Turrado, Secretario General de ASAJA Castilla y Le\u00f3n<\/em><\/strong><\/p>\n\n\n\n<p>Resumiendo mucho, en Espa\u00f1a, como en una gran parte del mundo, existen dos modelos de producci\u00f3n ganadera: la extensiva y la intensiva. La extensiva es la que est\u00e1 vinculada al factor tierra o pastos y data desde la \u00e9poca en la que el hombre domestic\u00f3 a los animales, hecho ya de por s\u00ed aberrante para muchos de nuestros actuales cong\u00e9neres. Es bueno que la ganader\u00eda extensiva haya pervivido hasta nuestros tiempos en amplias zonas del planeta y que haya pol\u00edticas agrarias que garanticen su viabilidad econ\u00f3mica futura, pues adem\u00e1s de ser una fuente de alimentos de m\u00e1xima calidad, aprovechan recursos naturales que de otra forma se perder\u00edan, y contribuyen a mejorar los ecosistemas, el paisaje rural, y todo junto fija poblaci\u00f3n en los territorios casi siempre m\u00e1s despoblados, agrestes y perif\u00e9ricos.<\/p>\n\n\n\n<p>El otro modelo, el de la ganader\u00eda intensiva, el que no depende de una base de tierra o de pastos, es un modelo ganadero del siglo XX que por suerte sigue siendo \u00fatil y viable en nuestros d\u00edas, es el modelo ganadero que ha permitido acercar la prote\u00edna animal tambi\u00e9n a las capas sociales m\u00e1s humildes, y ha contribuido y est\u00e1 contribuyendo a la dif\u00edcil tarea de erradicar el hambre en el mundo. Los profesionales del sector saben c\u00f3mo gestionar las explotaciones para que sean econ\u00f3micamente viables, para producir con los m\u00e1s elevados est\u00e1ndares de sanidad y bienestar animal que imponen administraciones exigentes como la europea, y para poder ofrecer al consumidor prote\u00edna animal que adem\u00e1s de nutrir conforma uno de los placeres de la vida. Un placer legal y leg\u00edtimo, como para algunos es fumar porros.<\/p>\n\n\n\n<p>En los \u00faltimos tiempos, y de la mano de grupos conservacionistas con ideolog\u00eda de extrema izquierda, se ha cuestionado el modelo de ganader\u00eda intensiva que se practica en el mundo m\u00e1s desarrollado, y se hace no con una base cient\u00edfica, sino con argumentos ideol\u00f3gicos. A la ganader\u00eda intensiva no se le reconoce m\u00e9rito alguno, al ganadero no se le valora su trabajo y su inversi\u00f3n, por lo que es permanentemente denostada asoci\u00e1ndola incluso a los grandes capitales y fortunas colg\u00e1ndoles el sambenito de que son \u201cmacrogranjas\u201d. Todo es una \u201cmacrogranja\u201d donde a puerta cerrada se maltrata y tortura a los animales.<\/p>\n\n\n\n<p>Los ganaderos tenemos dif\u00edcil defender nuestro papel en una sociedad a la que ya le sobra de todo, hasta alimentos, y defender nuestro papel ante una opini\u00f3n p\u00fablica donde el que opina es el radical, mientras que el ciudadano normal moderado aguanta estoicamente las ocurrencias de una legi\u00f3n de \u201cperroflautas\u201d negacionistas de los alimentos con apoyos cada vez m\u00e1s frecuentes en los gobiernos de los pa\u00edses europeos, empezando por el nuestro.<\/p>\n\n\n\n<p>El debate en el modelo ganadero no es el que ha abierto el ministro Garz\u00f3n, ni el de algunos ganaderos que se apuntan a defender lo suyo y que se alegran del mal del vecino, el debate es que un pa\u00eds como Espa\u00f1a, en el que afortunadamente tenemos una caba\u00f1a ganadera envidiable en medio mundo y que est\u00e1 encontrando un important\u00edsimo nicho de mercado en la exportaci\u00f3n, conviva el modelo de explotaci\u00f3n ganadera extensiva con el de las granjas m\u00e1s intensivas. Ambos modelos, en su conjunto y no siendo auto excluyentes, dar\u00e1n sentido a nuestra agricultura, potenciar\u00e1n como lo est\u00e1n haciendo nuestra balanza comercial exterior, prestigiar\u00e1n nuestra turismo gastron\u00f3mico y asentar\u00e1n poblaci\u00f3n en el territorio rural. Es el momento de cerrar un debate est\u00e9ril que surge de quienes han nacido en la opulencia y no piensan en los dem\u00e1s, tan siquiera en esa gran parte del mundo en la que se pasa hambre, en la que la gentes se muere de hambre, y en la que un ni\u00f1o llorar\u00eda de felicidad si pudiera comerse a dos manos un muslo de pollo o una chuleta de cerdo agarrada por el hueso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jos\u00e9 Antonio Turrado, Secretario General de ASAJA Castilla y Le\u00f3n Resumiendo mucho, en Espa\u00f1a, como en una gran parte del mundo, existen dos modelos de producci\u00f3n ganadera: la extensiva y la intensiva. La extensiva es la que est\u00e1 vinculada al factor tierra o pastos y data desde la \u00e9poca en la que el hombre domestic\u00f3 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":5827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,30],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dos modelos ganaderos - ASAJA Palencia<\/title>\n<meta name=\"description\" content=\"Jos\u00e9 Antonio Turrado, Secretario General de ASAJA Castilla y Le\u00f3n Resumiendo mucho, en Espa\u00f1a, como en una gran parte del mundo, existen dos modelos de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dos modelos ganaderos - ASAJA Palencia\" \/>\n<meta property=\"og:description\" content=\"Jos\u00e9 Antonio Turrado, Secretario General de ASAJA Castilla y Le\u00f3n Resumiendo mucho, en Espa\u00f1a, como en una gran parte del mundo, existen dos modelos de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Palencia\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-11T15:28:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/turrado-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"254\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos\",\"name\":\"Dos modelos ganaderos - ASAJA Palencia\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/turrado-1.jpg\",\"datePublished\":\"2022-01-11T15:28:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1\"},\"description\":\"Jos\u00e9 Antonio Turrado, Secretario General de ASAJA Castilla y Le\u00f3n Resumiendo mucho, en Espa\u00f1a, como en una gran parte del mundo, existen dos modelos de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/turrado-1.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/turrado-1.jpg\",\"width\":254,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/palencia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dos modelos ganaderos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/\",\"name\":\"ASAJA Palencia\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1\",\"name\":\"Administrador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g\",\"caption\":\"Administrador\"},\"url\":\"https:\/\/www.asajacyl.com\/palencia\/author\/carlosrm\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dos modelos ganaderos - ASAJA Palencia","description":"Jos\u00e9 Antonio Turrado, Secretario General de ASAJA Castilla y Le\u00f3n Resumiendo mucho, en Espa\u00f1a, como en una gran parte del mundo, existen dos modelos de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos","og_locale":"es_ES","og_type":"article","og_title":"Dos modelos ganaderos - ASAJA Palencia","og_description":"Jos\u00e9 Antonio Turrado, Secretario General de ASAJA Castilla y Le\u00f3n Resumiendo mucho, en Espa\u00f1a, como en una gran parte del mundo, existen dos modelos de","og_url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos","og_site_name":"ASAJA Palencia","article_published_time":"2022-01-11T15:28:00+00:00","og_image":[{"width":254,"height":300,"url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/turrado-1.jpg","type":"image\/jpeg"}],"author":"Administrador","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Administrador","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos","url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos","name":"Dos modelos ganaderos - ASAJA Palencia","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/turrado-1.jpg","datePublished":"2022-01-11T15:28:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1"},"description":"Jos\u00e9 Antonio Turrado, Secretario General de ASAJA Castilla y Le\u00f3n Resumiendo mucho, en Espa\u00f1a, como en una gran parte del mundo, existen dos modelos de","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos#primaryimage","url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/turrado-1.jpg","contentUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/turrado-1.jpg","width":254,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/opinion-asaja\/dos-modelos-ganaderos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/palencia\/"},{"@type":"ListItem","position":2,"name":"Dos modelos ganaderos"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/palencia\/#website","url":"https:\/\/www.asajacyl.com\/palencia\/","name":"ASAJA Palencia","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1","name":"Administrador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g","caption":"Administrador"},"url":"https:\/\/www.asajacyl.com\/palencia\/author\/carlosrm"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/9667"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/comments?post=9667"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/9667\/revisions"}],"predecessor-version":[{"id":9668,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/9667\/revisions\/9668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media\/5827"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media?parent=9667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/categories?post=9667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/tags?post=9667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}