{"id":9700,"date":"2022-01-19T13:12:00","date_gmt":"2022-01-19T12:12:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/palencia\/?p=9700"},"modified":"2022-01-17T13:25:35","modified_gmt":"2022-01-17T12:25:35","slug":"se-autorizan-los-neonicotinoides-en-remolacha-para-2022","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022","title":{"rendered":"Se autorizan los neonicotinoides en remolacha para 2022"},"content":{"rendered":"\n<p>La Direcci\u00f3n General de Sanidad de la Producci\u00f3n Agropecuaria, dependiente del Ministerio de Agricultura, Pesca y Alimentaci\u00f3n, ha autorizado excepcionalmente la comercializaci\u00f3n y uso de neonicotinoides en remolacha, para la campa\u00f1a de siembra que est\u00e1 punto de comenzar en Castilla y Le\u00f3n. Esta autorizaci\u00f3n tendr\u00e1 vigencia del 15 de febrero hasta el 14 de junio del a\u00f1o 2022.<\/p>\n\n\n\n<p>Los condicionantes para la utilizaci\u00f3n de neonicotinoides son los siguientes:<\/p>\n\n\n\n<ul><li>La siembra debe realizarse dejando una banda de tierra en barbecho de 1 metro, perimetral a la parcela de siembra.<\/li><li>En las parcelas sembradas con semillas de remolacha tratadas con neonicotinoides ser\u00e1 obligatorio que la siembra del a\u00f1o siguiente se realice con un cultivo considerado como no atractivos para los polinizadores.<\/li><li>Los agricultores deber\u00e1n presentar, previamente a la siembra, un listado de parcelas en las que se vaya a realizar la siembra con las semillas tratadas.<\/li><li>Los agricultores deben rellenar un formulario, dirigido al Jefe del Servicio Territorial de Agricultura, Ganader\u00eda y Desarrollo Rural y que ser\u00e1 necesario presentar antes de la ejecuci\u00f3n de las labores de siembra de la remolacha para poder realizar un control de dicha actuaci\u00f3n.<\/li><li>Es necesario no haber cultivado el a\u00f1o anterior ni colza, ni cultivos del g\u00e9nero <em>Brassica<\/em> en la parcelas que se vayan a sembrar con semillas de remolacha tratadas con el producto autorizado.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n General de Sanidad de la Producci\u00f3n Agropecuaria, dependiente del Ministerio de Agricultura, Pesca y Alimentaci\u00f3n, ha autorizado excepcionalmente la comercializaci\u00f3n y uso de neonicotinoides en remolacha, para la campa\u00f1a de siembra que est\u00e1 punto de comenzar en Castilla y Le\u00f3n. Esta autorizaci\u00f3n tendr\u00e1 vigencia del 15 de febrero hasta el 14 de junio [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":5807,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,29,28],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se autorizan los neonicotinoides en remolacha para 2022 - ASAJA Palencia<\/title>\n<meta name=\"description\" content=\"La Direcci\u00f3n General de Sanidad de la Producci\u00f3n Agropecuaria, dependiente del Ministerio de Agricultura, Pesca y Alimentaci\u00f3n, ha autorizado\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se autorizan los neonicotinoides en remolacha para 2022 - ASAJA Palencia\" \/>\n<meta property=\"og:description\" content=\"La Direcci\u00f3n General de Sanidad de la Producci\u00f3n Agropecuaria, dependiente del Ministerio de Agricultura, Pesca y Alimentaci\u00f3n, ha autorizado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Palencia\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-19T12:12:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/remolacha1-VALL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1213\" \/>\n\t<meta property=\"og:image:height\" content=\"772\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022\",\"name\":\"Se autorizan los neonicotinoides en remolacha para 2022 - ASAJA Palencia\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/remolacha1-VALL.jpg\",\"datePublished\":\"2022-01-19T12:12:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1\"},\"description\":\"La Direcci\u00f3n General de Sanidad de la Producci\u00f3n Agropecuaria, dependiente del Ministerio de Agricultura, Pesca y Alimentaci\u00f3n, ha autorizado\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/remolacha1-VALL.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/remolacha1-VALL.jpg\",\"width\":1213,\"height\":772},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/palencia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se autorizan los neonicotinoides en remolacha para 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/palencia\/\",\"name\":\"ASAJA Palencia\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1\",\"name\":\"Administrador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g\",\"caption\":\"Administrador\"},\"url\":\"https:\/\/www.asajacyl.com\/palencia\/author\/carlosrm\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se autorizan los neonicotinoides en remolacha para 2022 - ASAJA Palencia","description":"La Direcci\u00f3n General de Sanidad de la Producci\u00f3n Agropecuaria, dependiente del Ministerio de Agricultura, Pesca y Alimentaci\u00f3n, ha autorizado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022","og_locale":"es_ES","og_type":"article","og_title":"Se autorizan los neonicotinoides en remolacha para 2022 - ASAJA Palencia","og_description":"La Direcci\u00f3n General de Sanidad de la Producci\u00f3n Agropecuaria, dependiente del Ministerio de Agricultura, Pesca y Alimentaci\u00f3n, ha autorizado","og_url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022","og_site_name":"ASAJA Palencia","article_published_time":"2022-01-19T12:12:00+00:00","og_image":[{"width":1213,"height":772,"url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/remolacha1-VALL.jpg","type":"image\/jpeg"}],"author":"Administrador","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Administrador","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022","url":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022","name":"Se autorizan los neonicotinoides en remolacha para 2022 - ASAJA Palencia","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/remolacha1-VALL.jpg","datePublished":"2022-01-19T12:12:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1"},"description":"La Direcci\u00f3n General de Sanidad de la Producci\u00f3n Agropecuaria, dependiente del Ministerio de Agricultura, Pesca y Alimentaci\u00f3n, ha autorizado","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022#primaryimage","url":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/remolacha1-VALL.jpg","contentUrl":"https:\/\/www.asajacyl.com\/palencia\/wp-content\/uploads\/sites\/3\/2019\/01\/remolacha1-VALL.jpg","width":1213,"height":772},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/palencia\/asaja-palencia-informa\/se-autorizan-los-neonicotinoides-en-remolacha-para-2022#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/palencia\/"},{"@type":"ListItem","position":2,"name":"Se autorizan los neonicotinoides en remolacha para 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/palencia\/#website","url":"https:\/\/www.asajacyl.com\/palencia\/","name":"ASAJA Palencia","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/palencia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/3ab17aeb03527485c317557fae64aab1","name":"Administrador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/palencia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/517384810d242ca9e38c180f3c9fb973?s=96&d=mm&r=g","caption":"Administrador"},"url":"https:\/\/www.asajacyl.com\/palencia\/author\/carlosrm"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/9700"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/comments?post=9700"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/9700\/revisions"}],"predecessor-version":[{"id":9701,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/posts\/9700\/revisions\/9701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media\/5807"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/media?parent=9700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/categories?post=9700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/palencia\/wp-json\/wp\/v2\/tags?post=9700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}