{"id":10546,"date":"2021-01-26T11:33:53","date_gmt":"2021-01-26T11:33:53","guid":{"rendered":"https:\/\/www.asajacyl.com\/salamanca\/?p=10546"},"modified":"2021-01-26T11:33:55","modified_gmt":"2021-01-26T11:33:55","slug":"lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021","title":{"rendered":"Lonja Agropecuaria de Salamanca del 25 de enero de 2021"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":10547,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37,38,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lonja Agropecuaria de Salamanca del 25 de enero de 2021 - ASAJA Salamanca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lonja Agropecuaria de Salamanca del 25 de enero de 2021 - ASAJA Salamanca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Salamanca\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-26T11:33:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-26T11:33:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2021\/01\/lamb-4407307_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1508\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021\",\"name\":\"Lonja Agropecuaria de Salamanca del 25 de enero de 2021 - ASAJA Salamanca\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2021\/01\/lamb-4407307_1920.jpg\",\"datePublished\":\"2021-01-26T11:33:53+00:00\",\"dateModified\":\"2021-01-26T11:33:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2021\/01\/lamb-4407307_1920.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2021\/01\/lamb-4407307_1920.jpg\",\"width\":1920,\"height\":1508},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/salamanca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lonja Agropecuaria de Salamanca del 25 de enero de 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/\",\"name\":\"ASAJA Salamanca\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\",\"name\":\"Sonia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"caption\":\"Sonia\"},\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lonja Agropecuaria de Salamanca del 25 de enero de 2021 - ASAJA Salamanca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021","og_locale":"es_ES","og_type":"article","og_title":"Lonja Agropecuaria de Salamanca del 25 de enero de 2021 - ASAJA Salamanca","og_url":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021","og_site_name":"ASAJA Salamanca","article_published_time":"2021-01-26T11:33:53+00:00","article_modified_time":"2021-01-26T11:33:55+00:00","og_image":[{"width":1920,"height":1508,"url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2021\/01\/lamb-4407307_1920.jpg","type":"image\/jpeg"}],"author":"Sonia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sonia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021","url":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021","name":"Lonja Agropecuaria de Salamanca del 25 de enero de 2021 - ASAJA Salamanca","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2021\/01\/lamb-4407307_1920.jpg","datePublished":"2021-01-26T11:33:53+00:00","dateModified":"2021-01-26T11:33:55+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f"},"breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021#primaryimage","url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2021\/01\/lamb-4407307_1920.jpg","contentUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2021\/01\/lamb-4407307_1920.jpg","width":1920,"height":1508},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-de-salamanca-del-25-de-enero-de-2021#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/salamanca\/"},{"@type":"ListItem","position":2,"name":"Lonja Agropecuaria de Salamanca del 25 de enero de 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/salamanca\/#website","url":"https:\/\/www.asajacyl.com\/salamanca\/","name":"ASAJA Salamanca","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f","name":"Sonia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","caption":"Sonia"},"url":"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/10546"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/comments?post=10546"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/10546\/revisions"}],"predecessor-version":[{"id":10550,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/10546\/revisions\/10550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media\/10547"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media?parent=10546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/categories?post=10546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/tags?post=10546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}