{"id":18423,"date":"2024-09-20T13:37:55","date_gmt":"2024-09-20T11:37:55","guid":{"rendered":"https:\/\/www.asajacyl.com\/salamanca\/?p=18423"},"modified":"2025-11-11T08:55:45","modified_gmt":"2025-11-11T07:55:45","slug":"asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero","title":{"rendered":"ASAJA pide una posici\u00f3n conjunta de Castilla y Le\u00f3n para revertir pol\u00edticas que debilitan la rentabilidad del sector agrario y ganadero"},"content":{"rendered":"\n<p><strong>El presidente de ASAJA Castilla y Le\u00f3n, ha valorado positivamente la recuperaci\u00f3n y normalizaci\u00f3n de la interlocuci\u00f3n directa con el presidente de la Junta, Alfonso Fern\u00e1ndez Ma\u00f1ueco, tras la reuni\u00f3n celebrada hoy en la sede de Presidencia con las organizaciones profesionales agrarias. \u201cEste di\u00e1logo permanente y vivo es necesario para lograr una posici\u00f3n conjunta de Castilla y Le\u00f3n frente al Gobierno nacional y la UE en temas fundamentales, como puede ser la PAC o la gesti\u00f3n del agua, para revertir pol\u00edticas que est\u00e1n debilitando la rentabilidad de nuestro sector agrario y ganadero\u201d, afirma Donaciano Dujo, responsable de la OPA.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-1024x683.jpg\" alt=\"\" class=\"wp-image-18424\" srcset=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-1024x683.jpg 1024w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-300x200.jpg 300w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-768x512.jpg 768w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-1536x1024.jpg 1536w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-630x420.jpg 630w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-696x464.jpg 696w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-1068x712.jpg 1068w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>En el encuentro con Fern\u00e1ndez Ma\u00f1ueco -en el que por parte de ASAJA han asistido adem\u00e1s del presidente regional el secretario, Jos\u00e9 Antonio Turrado, y la gerente, Nuria Ruiz Corral- la organizaci\u00f3n profesional agraria mayoritaria ha marcado prioridades que el sector necesita con urgencia. As\u00ed, preocupa la ya sistem\u00e1tica falta de rentabilidad del cereal, cultivo por excelencia de Castilla y Le\u00f3n, en un a\u00f1o que a\u00fan con una cosecha aceptable el agricultor no obtiene beneficio. Como ejemplo, Dujo se\u00f1ala que \u201choy pagamos por el abono 60 c\u00e9ntimos por kilo, y nos ofrecen 20 c\u00e9ntimos por kilo de trigo\u201d. Esta situaci\u00f3n es desesperada para varias zonas de la Comunidad Aut\u00f3noma, en las que se han recogido cosechas tan catastr\u00f3ficas como la de 2023, \u201cy que necesitan ayudas como las del a\u00f1o pasado para poder seguir sembrando\u201d.<\/p>\n\n\n\n<p>En este sentido, ASAJA se\u00f1al\u00f3 la necesidad de que revisen los acuerdos internacionales, especialmente el referente a la retirada de aranceles para las importaciones de cereal ucranio, que est\u00e1 entrando masivamente y tirando los precios en un momento muy delicado para los agricultores espa\u00f1oles. \u201cEs precisa en este sentido una postura clara de Castilla y Le\u00f3n, como granero del pa\u00eds, porque se est\u00e1 minando la rentabilidad del campo y ya se est\u00e1 trasladando a una reducci\u00f3n de la superficie sembrada, con lo que perdemos potencial productivo\u201d, indica Donaciano Dujo. Esta postura regional tambi\u00e9n es determinante para revisar la PAC actual \u201cy poder eliminar aquello que nos est\u00e1 impidiendo trabajar y producir con libertad\u201d.<\/p>\n\n\n\n<p>Otro tema importante es el sanitario, tanto en agricultura como en ganader\u00eda, con la cronificaci\u00f3n de plagas y enfermedades y la irrupci\u00f3n de otras nuevas. El presidente de ASAJA se\u00f1al\u00f3 a la fauna salvaje como un reservorio de transmisi\u00f3n y contagio, y pidi\u00f3 medidas de control, adem\u00e1s de ayudas para las explotaciones afectadas. En el cap\u00edtulo agr\u00edcola, adem\u00e1s, reclam\u00f3 de nuevo la quema controlada de rastrojos para depurar problemas fitosanitarios, quemas que se realizar\u00edan en determinadas \u00e9pocas sin peligro de incendio.<\/p>\n\n\n\n<p>El otro gran tema fundamental para el futuro del sector es la gesti\u00f3n del agua y, especialmente, el regad\u00edo. \u201cASAJA y Castilla y Le\u00f3n en su conjunto dijo no al actual Plan Hidrol\u00f3gico de la Cuenca del Duero, estamos totalmente en contra de la postura penalista y restrictiva del Ministerio de Transici\u00f3n Ecol\u00f3gica y la CHD. Castilla y Le\u00f3n tiene margen de crecimiento en regad\u00edo, solo hay un 15% de la superficie y la media nacional es del 23%. Necesitamos una pol\u00edtica del agua enfocada a la producci\u00f3n\u201d, a\u00f1ade Donaciano Dujo.<\/p>\n\n\n\n<p>En la reuni\u00f3n, adem\u00e1s, se habl\u00f3 de otros asuntos clave para el sector, tales como seguros agrarios, incorporaci\u00f3n de j\u00f3venes, modernizaci\u00f3n de explotaciones o la Ley de la cadena alimentaria.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-1-1024x576.jpg\" alt=\"\" class=\"wp-image-18425\" srcset=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-1-1024x576.jpg 1024w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-1-300x169.jpg 300w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-1-768x432.jpg 768w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-1-1536x864.jpg 1536w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-1-747x420.jpg 747w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-1-696x392.jpg 696w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-1-1068x601.jpg 1068w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-1.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"700\" src=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-2-1024x700.jpg\" alt=\"\" class=\"wp-image-18426\" srcset=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-2-1024x700.jpg 1024w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-2-300x205.jpg 300w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-2-768x525.jpg 768w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-2-1536x1050.jpg 1536w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-2-615x420.jpg 615w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-2-218x150.jpg 218w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-2-696x476.jpg 696w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-2-1068x730.jpg 1068w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/image-2.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de ASAJA Castilla y Le\u00f3n, ha valorado positivamente la recuperaci\u00f3n y normalizaci\u00f3n de la interlocuci\u00f3n directa con el presidente de la Junta, Alfonso Fern\u00e1ndez Ma\u00f1ueco, tras la reuni\u00f3n celebrada hoy en la sede de Presidencia con las organizaciones profesionales agrarias. \u201cEste di\u00e1logo permanente y vivo es necesario para lograr una posici\u00f3n conjunta de [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":18427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[510],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA pide una posici\u00f3n conjunta de Castilla y Le\u00f3n para revertir pol\u00edticas que debilitan la rentabilidad del sector agrario y ganadero - ASAJA Salamanca<\/title>\n<meta name=\"description\" content=\"El presidente de ASAJA Castilla y Le\u00f3n, ha valorado positivamente la recuperaci\u00f3n y normalizaci\u00f3n de la interlocuci\u00f3n directa con el presidente de la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA pide una posici\u00f3n conjunta de Castilla y Le\u00f3n para revertir pol\u00edticas que debilitan la rentabilidad del sector agrario y ganadero - ASAJA Salamanca\" \/>\n<meta property=\"og:description\" content=\"El presidente de ASAJA Castilla y Le\u00f3n, ha valorado positivamente la recuperaci\u00f3n y normalizaci\u00f3n de la interlocuci\u00f3n directa con el presidente de la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Salamanca\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-20T11:37:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T07:55:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/0d250ba0-070a-4fae-b6dd-64994dcfad17-1920x1280-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"819\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero\",\"name\":\"ASAJA pide una posici\u00f3n conjunta de Castilla y Le\u00f3n para revertir pol\u00edticas que debilitan la rentabilidad del sector agrario y ganadero - ASAJA Salamanca\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/0d250ba0-070a-4fae-b6dd-64994dcfad17-1920x1280-1.jpg\",\"datePublished\":\"2024-09-20T11:37:55+00:00\",\"dateModified\":\"2025-11-11T07:55:45+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\"},\"description\":\"El presidente de ASAJA Castilla y Le\u00f3n, ha valorado positivamente la recuperaci\u00f3n y normalizaci\u00f3n de la interlocuci\u00f3n directa con el presidente de la\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/0d250ba0-070a-4fae-b6dd-64994dcfad17-1920x1280-1.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/0d250ba0-070a-4fae-b6dd-64994dcfad17-1920x1280-1.jpg\",\"width\":1920,\"height\":819},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/salamanca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA pide una posici\u00f3n conjunta de Castilla y Le\u00f3n para revertir pol\u00edticas que debilitan la rentabilidad del sector agrario y ganadero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/\",\"name\":\"ASAJA Salamanca\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\",\"name\":\"Sonia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"caption\":\"Sonia\"},\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA pide una posici\u00f3n conjunta de Castilla y Le\u00f3n para revertir pol\u00edticas que debilitan la rentabilidad del sector agrario y ganadero - ASAJA Salamanca","description":"El presidente de ASAJA Castilla y Le\u00f3n, ha valorado positivamente la recuperaci\u00f3n y normalizaci\u00f3n de la interlocuci\u00f3n directa con el presidente de la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero","og_locale":"es_ES","og_type":"article","og_title":"ASAJA pide una posici\u00f3n conjunta de Castilla y Le\u00f3n para revertir pol\u00edticas que debilitan la rentabilidad del sector agrario y ganadero - ASAJA Salamanca","og_description":"El presidente de ASAJA Castilla y Le\u00f3n, ha valorado positivamente la recuperaci\u00f3n y normalizaci\u00f3n de la interlocuci\u00f3n directa con el presidente de la","og_url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero","og_site_name":"ASAJA Salamanca","article_published_time":"2024-09-20T11:37:55+00:00","article_modified_time":"2025-11-11T07:55:45+00:00","og_image":[{"width":1920,"height":819,"url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/0d250ba0-070a-4fae-b6dd-64994dcfad17-1920x1280-1.jpg","type":"image\/jpeg"}],"author":"Sonia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sonia","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero","url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero","name":"ASAJA pide una posici\u00f3n conjunta de Castilla y Le\u00f3n para revertir pol\u00edticas que debilitan la rentabilidad del sector agrario y ganadero - ASAJA Salamanca","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/0d250ba0-070a-4fae-b6dd-64994dcfad17-1920x1280-1.jpg","datePublished":"2024-09-20T11:37:55+00:00","dateModified":"2025-11-11T07:55:45+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f"},"description":"El presidente de ASAJA Castilla y Le\u00f3n, ha valorado positivamente la recuperaci\u00f3n y normalizaci\u00f3n de la interlocuci\u00f3n directa con el presidente de la","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero#primaryimage","url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/0d250ba0-070a-4fae-b6dd-64994dcfad17-1920x1280-1.jpg","contentUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/09\/0d250ba0-070a-4fae-b6dd-64994dcfad17-1920x1280-1.jpg","width":1920,"height":819},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pide-una-posicion-conjunta-de-castilla-y-leon-para-revertir-politicas-que-debilitan-la-rentabilidad-del-sector-agrario-y-ganadero#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/salamanca\/"},{"@type":"ListItem","position":2,"name":"ASAJA pide una posici\u00f3n conjunta de Castilla y Le\u00f3n para revertir pol\u00edticas que debilitan la rentabilidad del sector agrario y ganadero"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/salamanca\/#website","url":"https:\/\/www.asajacyl.com\/salamanca\/","name":"ASAJA Salamanca","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f","name":"Sonia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","caption":"Sonia"},"url":"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18423"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/comments?post=18423"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18423\/revisions"}],"predecessor-version":[{"id":18428,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18423\/revisions\/18428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media\/18427"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media?parent=18423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/categories?post=18423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/tags?post=18423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}