{"id":18625,"date":"2024-11-12T09:20:40","date_gmt":"2024-11-12T08:20:40","guid":{"rendered":"https:\/\/www.asajacyl.com\/salamanca\/?p=18625"},"modified":"2024-11-12T09:20:44","modified_gmt":"2024-11-12T08:20:44","slug":"la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024","title":{"rendered":"La dehesa como sumidero de carbono-Campo salmantino, 11 de noviembre de 2024"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.youtube.com\/@cyltvSalamanca\"><\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"GX4hr3dDGLY\"><iframe loading=\"lazy\" title=\"La dehesa como sumidero de carbono-Campo salmantino, 11 de noviembre de 2024\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/GX4hr3dDGLY?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/www.youtube.com\/watch?v=GX4hr3dDGLY<\/p>\n","protected":false},"author":10,"featured_media":18626,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La dehesa como sumidero de carbono-Campo salmantino, 11 de noviembre de 2024 - ASAJA Salamanca<\/title>\n<meta name=\"description\" content=\"https:\/\/www.youtube.com\/watch?v=GX4hr3dDGLY\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La dehesa como sumidero de carbono-Campo salmantino, 11 de noviembre de 2024 - ASAJA Salamanca\" \/>\n<meta property=\"og:description\" content=\"https:\/\/www.youtube.com\/watch?v=GX4hr3dDGLY\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Salamanca\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-12T08:20:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-12T08:20:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Captura-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"303\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024\",\"name\":\"La dehesa como sumidero de carbono-Campo salmantino, 11 de noviembre de 2024 - ASAJA Salamanca\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Captura-2.jpg\",\"datePublished\":\"2024-11-12T08:20:40+00:00\",\"dateModified\":\"2024-11-12T08:20:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\"},\"description\":\"https:\/\/www.youtube.com\/watch?v=GX4hr3dDGLY\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Captura-2.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Captura-2.jpg\",\"width\":1080,\"height\":303},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/salamanca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La dehesa como sumidero de carbono-Campo salmantino, 11 de noviembre de 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/\",\"name\":\"ASAJA Salamanca\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\",\"name\":\"Sonia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"caption\":\"Sonia\"},\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La dehesa como sumidero de carbono-Campo salmantino, 11 de noviembre de 2024 - ASAJA Salamanca","description":"https:\/\/www.youtube.com\/watch?v=GX4hr3dDGLY","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024","og_locale":"es_ES","og_type":"article","og_title":"La dehesa como sumidero de carbono-Campo salmantino, 11 de noviembre de 2024 - ASAJA Salamanca","og_description":"https:\/\/www.youtube.com\/watch?v=GX4hr3dDGLY","og_url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024","og_site_name":"ASAJA Salamanca","article_published_time":"2024-11-12T08:20:40+00:00","article_modified_time":"2024-11-12T08:20:44+00:00","og_image":[{"width":1080,"height":303,"url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Captura-2.jpg","type":"image\/jpeg"}],"author":"Sonia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sonia","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024","url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024","name":"La dehesa como sumidero de carbono-Campo salmantino, 11 de noviembre de 2024 - ASAJA Salamanca","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Captura-2.jpg","datePublished":"2024-11-12T08:20:40+00:00","dateModified":"2024-11-12T08:20:44+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f"},"description":"https:\/\/www.youtube.com\/watch?v=GX4hr3dDGLY","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024#primaryimage","url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Captura-2.jpg","contentUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Captura-2.jpg","width":1080,"height":303},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/videos-programa-tv\/la-dehesa-como-sumidero-de-carbono-campo-salmantino-11-de-noviembre-de-2024#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/salamanca\/"},{"@type":"ListItem","position":2,"name":"La dehesa como sumidero de carbono-Campo salmantino, 11 de noviembre de 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/salamanca\/#website","url":"https:\/\/www.asajacyl.com\/salamanca\/","name":"ASAJA Salamanca","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f","name":"Sonia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","caption":"Sonia"},"url":"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18625"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/comments?post=18625"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18625\/revisions"}],"predecessor-version":[{"id":18627,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18625\/revisions\/18627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media\/18626"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media?parent=18625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/categories?post=18625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/tags?post=18625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}