{"id":18658,"date":"2024-11-27T08:54:11","date_gmt":"2024-11-27T07:54:11","guid":{"rendered":"https:\/\/www.asajacyl.com\/salamanca\/?p=18658"},"modified":"2025-11-11T08:51:21","modified_gmt":"2025-11-11T07:51:21","slug":"los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo","title":{"rendered":"Los agricultores de Castilla y Le\u00f3n protestar\u00e1n el pr\u00f3ximo viernes en Ar\u00e9valo"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">En unidad de acci\u00f3n, ASAJA y la Alianza UPA-COAG han anunciado para el pr\u00f3ximo viernes, 29 de noviembre, una manifestaci\u00f3n a la que convocan a todos los agricultores y ganaderos de Castilla y Le\u00f3n, en protesta por los ruinosos precios del cereal. El acto tendr\u00e1 lugar en Ar\u00e9valo, frente a la sede de Harinera Villafranquina, para despu\u00e9s trasladarse al almac\u00e9n de cereales y fertilizantes de Octaviano Palomo, sin descartarse otras medidas de presi\u00f3n durante la marcha.<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1021\" src=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Recurso-3-1024x1021.png\" alt=\"\" class=\"wp-image-18659\" style=\"width:510px;height:auto\" srcset=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Recurso-3-1024x1021.png 1024w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Recurso-3-300x300.png 300w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Recurso-3-150x150.png 150w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Recurso-3-768x766.png 768w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Recurso-3-1536x1532.png 1536w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Recurso-3-2048x2042.png 2048w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Recurso-3-421x420.png 421w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Recurso-3-696x694.png 696w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Recurso-3-1068x1065.png 1068w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/Recurso-3-1920x1915.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Detalles de la protesta<\/h3>\n\n\n\n<p>El acto de protesta, con una duraci\u00f3n aproximada de 2 horas, se celebrar\u00e1 el viernes 29 de noviembre de 2024 en la localidad de AR\u00c9VALO, a partir de las 12:00 horas:<\/p>\n\n\n\n<p>-Concentraci\u00f3n de los manifestantes frente a las instalaciones de Harinera<br>Vilafranquina (Ctra. N-VI km 124)<\/p>\n\n\n\n<p>-Marcha a pie hasta las instalaciones de Cereales Octaviano Palomo (Ctra. Segovia-Zamora)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En unidad de acci\u00f3n, ASAJA y la Alianza UPA-COAG han anunciado para el pr\u00f3ximo viernes, 29 de noviembre, una manifestaci\u00f3n a la que convocan a todos los agricultores y ganaderos de Castilla y Le\u00f3n, en protesta por los ruinosos precios del cereal. El acto tendr\u00e1 lugar en Ar\u00e9valo, frente a la sede de Harinera Villafranquina, [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":18660,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[510],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los agricultores de Castilla y Le\u00f3n protestar\u00e1n el pr\u00f3ximo viernes en Ar\u00e9valo - ASAJA Salamanca<\/title>\n<meta name=\"description\" content=\"En unidad de acci\u00f3n, ASAJA y la Alianza UPA-COAG han anunciado para el pr\u00f3ximo viernes, 29 de noviembre, una manifestaci\u00f3n a la que convocan a todos los\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los agricultores de Castilla y Le\u00f3n protestar\u00e1n el pr\u00f3ximo viernes en Ar\u00e9valo - ASAJA Salamanca\" \/>\n<meta property=\"og:description\" content=\"En unidad de acci\u00f3n, ASAJA y la Alianza UPA-COAG han anunciado para el pr\u00f3ximo viernes, 29 de noviembre, una manifestaci\u00f3n a la que convocan a todos los\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Salamanca\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-27T07:54:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T07:51:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/IMG_9146.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo\",\"name\":\"Los agricultores de Castilla y Le\u00f3n protestar\u00e1n el pr\u00f3ximo viernes en Ar\u00e9valo - ASAJA Salamanca\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/IMG_9146.jpg\",\"datePublished\":\"2024-11-27T07:54:11+00:00\",\"dateModified\":\"2025-11-11T07:51:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\"},\"description\":\"En unidad de acci\u00f3n, ASAJA y la Alianza UPA-COAG han anunciado para el pr\u00f3ximo viernes, 29 de noviembre, una manifestaci\u00f3n a la que convocan a todos los\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/IMG_9146.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/IMG_9146.jpg\",\"width\":2500,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/salamanca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los agricultores de Castilla y Le\u00f3n protestar\u00e1n el pr\u00f3ximo viernes en Ar\u00e9valo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/\",\"name\":\"ASAJA Salamanca\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\",\"name\":\"Sonia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"caption\":\"Sonia\"},\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los agricultores de Castilla y Le\u00f3n protestar\u00e1n el pr\u00f3ximo viernes en Ar\u00e9valo - ASAJA Salamanca","description":"En unidad de acci\u00f3n, ASAJA y la Alianza UPA-COAG han anunciado para el pr\u00f3ximo viernes, 29 de noviembre, una manifestaci\u00f3n a la que convocan a todos los","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo","og_locale":"es_ES","og_type":"article","og_title":"Los agricultores de Castilla y Le\u00f3n protestar\u00e1n el pr\u00f3ximo viernes en Ar\u00e9valo - ASAJA Salamanca","og_description":"En unidad de acci\u00f3n, ASAJA y la Alianza UPA-COAG han anunciado para el pr\u00f3ximo viernes, 29 de noviembre, una manifestaci\u00f3n a la que convocan a todos los","og_url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo","og_site_name":"ASAJA Salamanca","article_published_time":"2024-11-27T07:54:11+00:00","article_modified_time":"2025-11-11T07:51:21+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/IMG_9146.jpg","type":"image\/jpeg"}],"author":"Sonia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sonia","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo","url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo","name":"Los agricultores de Castilla y Le\u00f3n protestar\u00e1n el pr\u00f3ximo viernes en Ar\u00e9valo - ASAJA Salamanca","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/IMG_9146.jpg","datePublished":"2024-11-27T07:54:11+00:00","dateModified":"2025-11-11T07:51:21+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f"},"description":"En unidad de acci\u00f3n, ASAJA y la Alianza UPA-COAG han anunciado para el pr\u00f3ximo viernes, 29 de noviembre, una manifestaci\u00f3n a la que convocan a todos los","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo#primaryimage","url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/IMG_9146.jpg","contentUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/11\/IMG_9146.jpg","width":2500,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/los-agricultores-de-castilla-y-leon-protestaran-el-proximo-viernes-en-arevalo#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/salamanca\/"},{"@type":"ListItem","position":2,"name":"Los agricultores de Castilla y Le\u00f3n protestar\u00e1n el pr\u00f3ximo viernes en Ar\u00e9valo"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/salamanca\/#website","url":"https:\/\/www.asajacyl.com\/salamanca\/","name":"ASAJA Salamanca","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f","name":"Sonia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","caption":"Sonia"},"url":"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18658"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/comments?post=18658"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18658\/revisions"}],"predecessor-version":[{"id":18661,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18658\/revisions\/18661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media\/18660"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media?parent=18658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/categories?post=18658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/tags?post=18658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}