{"id":18688,"date":"2024-12-03T14:12:27","date_gmt":"2024-12-03T13:12:27","guid":{"rendered":"https:\/\/www.asajacyl.com\/salamanca\/?p=18688"},"modified":"2025-11-11T08:51:02","modified_gmt":"2025-11-11T07:51:02","slug":"asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna","title":{"rendered":"ASAJA celebra la aprobaci\u00f3n del cambio de estatus de protecci\u00f3n del lobo en el Convenio de Berna"},"content":{"rendered":"\n<p><strong><em>Bruselas, 3 de diciembre de 2024.- <\/em>La Asociaci\u00f3n Agraria J\u00f3venes Agricultores (ASAJA) se congratula de que el Convenio de Berna haya decidido aprobar la rebaja del cambio de estatus de protecci\u00f3n del lobo, lo que permitir\u00e1 la convivencia con la ganader\u00eda. Por contra, lamentamos que el Gobierno de Espa\u00f1a siga manteniendo su rechazo a este cambio de estatus, ignorando los datos reales de crecimiento de la poblaci\u00f3n de lobos en nuestro pa\u00eds y los graves perjuicios que \u00e9stos causan al sector ganadero.<\/strong><\/p>\n\n\n\n<p>Aunque la decisi\u00f3n final se publicar\u00e1 el pr\u00f3ximo 6 de diciembre, la modificaci\u00f3n de \u201cespecie de fauna estrictamente protegida\u201d (Ap\u00e9ndice II) a \u201cespecie de fauna protegida\u201d (Ap\u00e9ndice III), marca un precedente en la gesti\u00f3n del lobo, que debe ser ratificado posteriormente por la UE y aplicado por cada Estado miembro seg\u00fan considere adecuado. As\u00ed pues, instamos una vez m\u00e1s al Gobierno de Espa\u00f1a a alinearse con este cambio, que favorecer\u00e1 la convivencia entre el lobo y la ganader\u00eda. Se deben tomar medidas inmediatas y eficaces, dada la situaci\u00f3n insostenible que padece el sector ganadero del noroeste espa\u00f1ol.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/00fbac5f-b8c7-4808-8325-a213afe57b7f-1024x768.jpg\" alt=\"\" class=\"wp-image-18689\" style=\"width:774px;height:auto\" srcset=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/00fbac5f-b8c7-4808-8325-a213afe57b7f-1024x768.jpg 1024w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/00fbac5f-b8c7-4808-8325-a213afe57b7f-300x225.jpg 300w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/00fbac5f-b8c7-4808-8325-a213afe57b7f-768x576.jpg 768w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/00fbac5f-b8c7-4808-8325-a213afe57b7f-1536x1152.jpg 1536w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/00fbac5f-b8c7-4808-8325-a213afe57b7f-560x420.jpg 560w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/00fbac5f-b8c7-4808-8325-a213afe57b7f-80x60.jpg 80w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/00fbac5f-b8c7-4808-8325-a213afe57b7f-696x522.jpg 696w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/00fbac5f-b8c7-4808-8325-a213afe57b7f-1068x801.jpg 1068w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/00fbac5f-b8c7-4808-8325-a213afe57b7f-1920x1440.jpg 1920w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/00fbac5f-b8c7-4808-8325-a213afe57b7f.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>En este sentido, ASAJA reclama que las indemnizaciones a ganaderos que sufren los ataques de lobos incluyan el lucro cesante, la p\u00e9rdida gen\u00e9tica, los abortos causados por el estr\u00e9s tras el ataque y que las denuncias se reconozcan mediante una declaraci\u00f3n responsable si no se logra encontrar el crotal del animal. Adem\u00e1s, insta a la Administraci\u00f3n a que colabore con las entidades bancarias para agilizar los pagos indemnizatorios.<\/p>\n\n\n\n<p>Igualmente, ASAJA reafirma su compromiso y alianza con Copa-Cogeca, CEJA, ELO y FACE, para elevar las reclamaciones del sector agropecuario a las instituciones europeas, exigiendo soluciones que protejan tanto la biodiversidad como el sustento de las comunidades rurales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d0c5baf6-9cf4-4454-95d5-6b94bde7f525-1024x768.jpg\" alt=\"\" class=\"wp-image-18690\" style=\"width:779px;height:auto\" srcset=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d0c5baf6-9cf4-4454-95d5-6b94bde7f525-1024x768.jpg 1024w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d0c5baf6-9cf4-4454-95d5-6b94bde7f525-300x225.jpg 300w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d0c5baf6-9cf4-4454-95d5-6b94bde7f525-768x576.jpg 768w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d0c5baf6-9cf4-4454-95d5-6b94bde7f525-1536x1152.jpg 1536w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d0c5baf6-9cf4-4454-95d5-6b94bde7f525-560x420.jpg 560w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d0c5baf6-9cf4-4454-95d5-6b94bde7f525-80x60.jpg 80w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d0c5baf6-9cf4-4454-95d5-6b94bde7f525-696x522.jpg 696w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d0c5baf6-9cf4-4454-95d5-6b94bde7f525-1068x801.jpg 1068w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d0c5baf6-9cf4-4454-95d5-6b94bde7f525-1920x1440.jpg 1920w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d0c5baf6-9cf4-4454-95d5-6b94bde7f525.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Asimismo, ASAJA insta ahora a la Comisi\u00f3n Europea a que incluya a los ganaderos que sufren los ataques de grandes carn\u00edvoros dentro de la nueva partida anunciada por el comisario de Agricultura, Christopher Hansen, destinada a la salud mental, puesto que es uno de los motivos que da\u00f1a el bienestar emocional de los ganaderos, que se sienten desprotegidos y abandonados.<\/p>\n\n\n\n<p>ASAJA tambi\u00e9n ha resaltado que ejercer\u00e1 una vigilancia exhaustiva cuando el Gobierno de Espa\u00f1a vuelva a enviar el censo lobero a la CE para evitar que vuelva a enviar cifras anticuadas que no responden a la realidad.<\/p>\n\n\n\n<p>En la v\u00edspera de la votaci\u00f3n del Convenio de Berna, y siguiendo con el trabajo de a\u00f1os en la defensa de la ganader\u00eda espa\u00f1ola, ASAJA ha organizado este lunes 2 de diciembre un simposio de alto nivel, titulado \u2018Lobo y ganado en Espa\u00f1a: hacia una soluci\u00f3n europea\u2019.<\/p>\n\n\n\n<p>Con la participaci\u00f3n de legisladores del Parlamento Europeo y la Comisi\u00f3n Europea, conservacionistas, cazadores y representantes clave de ASAJA Asturias, Galicia y Castilla y Le\u00f3n, se han analizado los retos y soluciones derivados del aumento de la poblaci\u00f3n de lobos en Europa y su impacto en la ganader\u00eda.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-1024x768.jpg\" alt=\"\" class=\"wp-image-18691\" style=\"width:778px;height:auto\" srcset=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-1024x768.jpg 1024w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-300x225.jpg 300w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-768x576.jpg 768w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-1536x1152.jpg 1536w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-2048x1536.jpg 2048w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-560x420.jpg 560w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-80x60.jpg 80w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-696x522.jpg 696w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-1068x801.jpg 1068w, https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-1920x1440.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Pr\u00f3ximos pasos<\/strong><\/p>\n\n\n\n<p>A partir de este momento, ASAJA seguir\u00e1 trabajando hasta el 7 de marzo para que se ratifique como la decisi\u00f3n oficial del Convenio de Berna. Como es un tratado del que la UE es signataria, la UE tendr\u00e1 que proponer un acto delegado para modificar el anexo de la Directiva H\u00e1bitats.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bruselas, 3 de diciembre de 2024.- La Asociaci\u00f3n Agraria J\u00f3venes Agricultores (ASAJA) se congratula de que el Convenio de Berna haya decidido aprobar la rebaja del cambio de estatus de protecci\u00f3n del lobo, lo que permitir\u00e1 la convivencia con la ganader\u00eda. Por contra, lamentamos que el Gobierno de Espa\u00f1a siga manteniendo su rechazo a este [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":18692,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[510],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA celebra la aprobaci\u00f3n del cambio de estatus de protecci\u00f3n del lobo en el Convenio de Berna - ASAJA Salamanca<\/title>\n<meta name=\"description\" content=\"Bruselas, 3 de diciembre de 2024.- La Asociaci\u00f3n Agraria J\u00f3venes Agricultores (ASAJA) se congratula de que el Convenio de Berna haya decidido aprobar la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA celebra la aprobaci\u00f3n del cambio de estatus de protecci\u00f3n del lobo en el Convenio de Berna - ASAJA Salamanca\" \/>\n<meta property=\"og:description\" content=\"Bruselas, 3 de diciembre de 2024.- La Asociaci\u00f3n Agraria J\u00f3venes Agricultores (ASAJA) se congratula de que el Convenio de Berna haya decidido aprobar la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Salamanca\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-03T13:12:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T07:51:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna\",\"name\":\"ASAJA celebra la aprobaci\u00f3n del cambio de estatus de protecci\u00f3n del lobo en el Convenio de Berna - ASAJA Salamanca\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-1.jpg\",\"datePublished\":\"2024-12-03T13:12:27+00:00\",\"dateModified\":\"2025-11-11T07:51:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\"},\"description\":\"Bruselas, 3 de diciembre de 2024.- La Asociaci\u00f3n Agraria J\u00f3venes Agricultores (ASAJA) se congratula de que el Convenio de Berna haya decidido aprobar la\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-1.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-1.jpg\",\"width\":2500,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/salamanca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA celebra la aprobaci\u00f3n del cambio de estatus de protecci\u00f3n del lobo en el Convenio de Berna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/\",\"name\":\"ASAJA Salamanca\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\",\"name\":\"Sonia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"caption\":\"Sonia\"},\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA celebra la aprobaci\u00f3n del cambio de estatus de protecci\u00f3n del lobo en el Convenio de Berna - ASAJA Salamanca","description":"Bruselas, 3 de diciembre de 2024.- La Asociaci\u00f3n Agraria J\u00f3venes Agricultores (ASAJA) se congratula de que el Convenio de Berna haya decidido aprobar la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna","og_locale":"es_ES","og_type":"article","og_title":"ASAJA celebra la aprobaci\u00f3n del cambio de estatus de protecci\u00f3n del lobo en el Convenio de Berna - ASAJA Salamanca","og_description":"Bruselas, 3 de diciembre de 2024.- La Asociaci\u00f3n Agraria J\u00f3venes Agricultores (ASAJA) se congratula de que el Convenio de Berna haya decidido aprobar la","og_url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna","og_site_name":"ASAJA Salamanca","article_published_time":"2024-12-03T13:12:27+00:00","article_modified_time":"2025-11-11T07:51:02+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-1.jpg","type":"image\/jpeg"}],"author":"Sonia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sonia","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna","url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna","name":"ASAJA celebra la aprobaci\u00f3n del cambio de estatus de protecci\u00f3n del lobo en el Convenio de Berna - ASAJA Salamanca","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-1.jpg","datePublished":"2024-12-03T13:12:27+00:00","dateModified":"2025-11-11T07:51:02+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f"},"description":"Bruselas, 3 de diciembre de 2024.- La Asociaci\u00f3n Agraria J\u00f3venes Agricultores (ASAJA) se congratula de que el Convenio de Berna haya decidido aprobar la","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna#primaryimage","url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-1.jpg","contentUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2024\/12\/d166c412-faab-4703-824b-07902fe58678-1.jpg","width":2500,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-celebra-la-aprobacion-del-cambio-de-estatus-de-proteccion-del-lobo-en-el-convenio-de-berna#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/salamanca\/"},{"@type":"ListItem","position":2,"name":"ASAJA celebra la aprobaci\u00f3n del cambio de estatus de protecci\u00f3n del lobo en el Convenio de Berna"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/salamanca\/#website","url":"https:\/\/www.asajacyl.com\/salamanca\/","name":"ASAJA Salamanca","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f","name":"Sonia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","caption":"Sonia"},"url":"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18688"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/comments?post=18688"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18688\/revisions"}],"predecessor-version":[{"id":18693,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18688\/revisions\/18693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media\/18692"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media?parent=18688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/categories?post=18688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/tags?post=18688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}