{"id":18954,"date":"2025-03-13T12:12:06","date_gmt":"2025-03-13T11:12:06","guid":{"rendered":"https:\/\/www.asajacyl.com\/salamanca\/?p=18954"},"modified":"2025-11-11T08:46:57","modified_gmt":"2025-11-11T07:46:57","slug":"asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha","title":{"rendered":"ASAJA pedir\u00e1 a la Consejer\u00eda de Agricultura que supervise todos los contratos de remolacha"},"content":{"rendered":"\n<p>La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n valora positivamente que la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la Junta de Castilla y Le\u00f3n,&nbsp;Mar\u00eda Gonz\u00e1lez Corral, haya incluido en el orden del d\u00eda del Consejo Regional Agrario que se va a celebrar el pr\u00f3ximo lunes 17 de marzo un punto relativo a \u201cla situaci\u00f3n de la campa\u00f1a de remolacha 2025\u201d.<\/p>\n\n\n\n<p>ASAJA, que abri\u00f3&nbsp; este debate con un comunicado de prensa el pasado 12 de febrero, espera que en el Consejo Agrario se adopten medidas para vigilar que en los contratos de remolacha se cumple la Ley de la Cadena Alimentaria, en el sentido de que el precio cubra al menos todos los costes de producci\u00f3n.<\/p>\n\n\n\n<p>Tambi\u00e9n, la organizaci\u00f3n agraria espera una instrucci\u00f3n clara por parte de la Direcci\u00f3n General de la PAC que permita, por causas de fuerza mayor vinculadas a la ca\u00edda de precios, la rescisi\u00f3n sin penalizaci\u00f3n de los contratos agroambientales vinculados a este cultivo. Esta cuesti\u00f3n est\u00e1 socavando la capacidad negociadora de los productores.<\/p>\n\n\n\n<p>Otro asunto que ASAJA pondr\u00e1 encima de la mesa tiene que ver con la obligaci\u00f3n que impone AB Azucarera a los cultivadores de suscribir el seguro del cultivo con la compa\u00f1\u00eda Agroseguro, un seguro que cuenta con una importante subvenci\u00f3n p\u00fablica del Estado y de la Junta, a favor del productor. En los contratos de remolacha, AB Azucarera obliga a los productores a ceder la totalidad de las indemnizaciones, en el caso de siniestro, a favor de la azucarera, lo que a todas luces parece una irregularidad impuesta desde una posici\u00f3n de dominancia. Estos hechos ya han sido puestos en conocimiento de la propia Consejer\u00eda de Agricultura, Agroseguro, ENESA y la Direcci\u00f3n General de Seguros del Ministerio de Econom\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n valora positivamente que la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la Junta de Castilla y Le\u00f3n,&nbsp;Mar\u00eda Gonz\u00e1lez Corral, haya incluido en el orden del d\u00eda del Consejo Regional Agrario que se va a celebrar el pr\u00f3ximo lunes 17 de marzo un punto relativo a \u201cla [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":18955,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[510],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA pedir\u00e1 a la Consejer\u00eda de Agricultura que supervise todos los contratos de remolacha - ASAJA Salamanca<\/title>\n<meta name=\"description\" content=\"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n valora positivamente que la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la Junta de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA pedir\u00e1 a la Consejer\u00eda de Agricultura que supervise todos los contratos de remolacha - ASAJA Salamanca\" \/>\n<meta property=\"og:description\" content=\"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n valora positivamente que la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la Junta de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Salamanca\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-13T11:12:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T07:46:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/03\/remolacha-cultivos-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"942\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha\",\"name\":\"ASAJA pedir\u00e1 a la Consejer\u00eda de Agricultura que supervise todos los contratos de remolacha - ASAJA Salamanca\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/03\/remolacha-cultivos-1.jpg\",\"datePublished\":\"2025-03-13T11:12:06+00:00\",\"dateModified\":\"2025-11-11T07:46:57+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\"},\"description\":\"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n valora positivamente que la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la Junta de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/03\/remolacha-cultivos-1.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/03\/remolacha-cultivos-1.jpg\",\"width\":942,\"height\":620},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/salamanca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA pedir\u00e1 a la Consejer\u00eda de Agricultura que supervise todos los contratos de remolacha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/\",\"name\":\"ASAJA Salamanca\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\",\"name\":\"Sonia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"caption\":\"Sonia\"},\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA pedir\u00e1 a la Consejer\u00eda de Agricultura que supervise todos los contratos de remolacha - ASAJA Salamanca","description":"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n valora positivamente que la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la Junta de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha","og_locale":"es_ES","og_type":"article","og_title":"ASAJA pedir\u00e1 a la Consejer\u00eda de Agricultura que supervise todos los contratos de remolacha - ASAJA Salamanca","og_description":"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n valora positivamente que la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la Junta de","og_url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha","og_site_name":"ASAJA Salamanca","article_published_time":"2025-03-13T11:12:06+00:00","article_modified_time":"2025-11-11T07:46:57+00:00","og_image":[{"width":942,"height":620,"url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/03\/remolacha-cultivos-1.jpg","type":"image\/jpeg"}],"author":"Sonia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sonia","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha","url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha","name":"ASAJA pedir\u00e1 a la Consejer\u00eda de Agricultura que supervise todos los contratos de remolacha - ASAJA Salamanca","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/03\/remolacha-cultivos-1.jpg","datePublished":"2025-03-13T11:12:06+00:00","dateModified":"2025-11-11T07:46:57+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f"},"description":"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n valora positivamente que la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la Junta de","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha#primaryimage","url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/03\/remolacha-cultivos-1.jpg","contentUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/03\/remolacha-cultivos-1.jpg","width":942,"height":620},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/asaja-pedira-a-la-consejeria-de-agricultura-que-supervise-todos-los-contratos-de-remolacha#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/salamanca\/"},{"@type":"ListItem","position":2,"name":"ASAJA pedir\u00e1 a la Consejer\u00eda de Agricultura que supervise todos los contratos de remolacha"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/salamanca\/#website","url":"https:\/\/www.asajacyl.com\/salamanca\/","name":"ASAJA Salamanca","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f","name":"Sonia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","caption":"Sonia"},"url":"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18954"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/comments?post=18954"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18954\/revisions"}],"predecessor-version":[{"id":18956,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/18954\/revisions\/18956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media\/18955"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media?parent=18954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/categories?post=18954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/tags?post=18954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}