{"id":19225,"date":"2025-05-12T13:32:15","date_gmt":"2025-05-12T11:32:15","guid":{"rendered":"https:\/\/www.asajacyl.com\/salamanca\/?p=19225"},"modified":"2025-11-11T08:44:31","modified_gmt":"2025-11-11T07:44:31","slug":"se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse","title":{"rendered":"Se ampl\u00eda al 31 de mayo el plazo sin penalizaci\u00f3n para presentar la PAC, pero ASAJA aconseja anticiparse"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Los agricultores y ganaderos podr\u00e1n presentar la solicitud \u00fanica de ayudas de la Pol\u00edtica Agraria Com\u00fan (PAC) de la campa\u00f1a 2025 hasta el pr\u00f3ximo\u00a031 de mayo\u00a0sin penalizaci\u00f3n. No obstante, ASAJA-Palencia aconseja a sus asociados mantener las citas previstas y cumplimentar la PAC cuanto antes, para as\u00ed entrar en el cruce de datos que detecta errores, un proceso que la Junta de Castilla y Le\u00f3n suele efectuar en torno al 15 de mayo.<\/h2>\n\n\n\n<p>La Consejer\u00eda de Agricultura, Ganader\u00eda efect\u00faa ese control preliminar de las parcelas declaradas, con la informaci\u00f3n disponible a esa fecha. Ese proceso permite comunicar a los solicitantes los errores detectados en sus declaraciones, como solapamiento en la delimitaci\u00f3n gr\u00e1fica de las parcelas agr\u00edcolas, exceso de superficie con respecto a los datos oficiales, dobles declaraciones de una misma parcela por m\u00e1s de un agricultor, etc\u00e9tera.<\/p>\n\n\n\n<p>El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n va a eliminar las penalizaciones que la normativa vigente aplicaba a las solicitudes presentadas en la segunda quincena de mayo. A nivel nacional, ASAJA&nbsp;ha valorado positivamente esta modificaci\u00f3n, solicitada formalmente por nuestra organizaci\u00f3n ante el evidente retraso en el ritmo de presentaci\u00f3n de solicitudes.<\/p>\n\n\n\n<p>Esta situaci\u00f3n se hab\u00eda reconocido por parte de las propias comunidades aut\u00f3nomas,&nbsp;organizaciones profesionales agrarias y otras entidades&nbsp;colaboradoras. No obstante, el equipo t\u00e9cnico de ASAJA-Palencia mantiene su calendario original de citas y atenci\u00f3n a los asociados, con el fin de anticipar al m\u00e1ximo la presentaci\u00f3n de las solicitudes de la PAC.<\/p>\n\n\n\n<p>La publicaci\u00f3n oficial de la exenci\u00f3n de penalizaciones no llegar\u00e1 antes del 1 de junio, pero el Fondo Espa\u00f1ol de Garant\u00eda Agraria (FEGA) ha firmado ya una resoluci\u00f3n que permite aplicar la medida de forma anticipada y con car\u00e1cter retroactivo&nbsp;desde el 1 de mayo. El objetivo es dotar de seguridad jur\u00eddica a las administraciones auton\u00f3micas, as\u00ed como a los agricultores y ganaderos que presenten su solicitud en esas fechas.\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los agricultores y ganaderos podr\u00e1n presentar la solicitud \u00fanica de ayudas de la Pol\u00edtica Agraria Com\u00fan (PAC) de la campa\u00f1a 2025 hasta el pr\u00f3ximo\u00a031 de mayo\u00a0sin penalizaci\u00f3n. No obstante, ASAJA-Palencia aconseja a sus asociados mantener las citas previstas y cumplimentar la PAC cuanto antes, para as\u00ed entrar en el cruce de datos que detecta errores, [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":19226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[510],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se ampl\u00eda al 31 de mayo el plazo sin penalizaci\u00f3n para presentar la PAC, pero ASAJA aconseja anticiparse - ASAJA Salamanca<\/title>\n<meta name=\"description\" content=\"Los agricultores y ganaderos podr\u00e1n presentar la solicitud \u00fanica de ayudas de la Pol\u00edtica Agraria Com\u00fan (PAC) de la campa\u00f1a 2025 hasta el pr\u00f3ximo\u00a031 de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se ampl\u00eda al 31 de mayo el plazo sin penalizaci\u00f3n para presentar la PAC, pero ASAJA aconseja anticiparse - ASAJA Salamanca\" \/>\n<meta property=\"og:description\" content=\"Los agricultores y ganaderos podr\u00e1n presentar la solicitud \u00fanica de ayudas de la Pol\u00edtica Agraria Com\u00fan (PAC) de la campa\u00f1a 2025 hasta el pr\u00f3ximo\u00a031 de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Salamanca\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-12T11:32:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T07:44:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/05\/Captura-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"879\" \/>\n\t<meta property=\"og:image:height\" content=\"544\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse\",\"name\":\"Se ampl\u00eda al 31 de mayo el plazo sin penalizaci\u00f3n para presentar la PAC, pero ASAJA aconseja anticiparse - ASAJA Salamanca\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/05\/Captura-1.jpg\",\"datePublished\":\"2025-05-12T11:32:15+00:00\",\"dateModified\":\"2025-11-11T07:44:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\"},\"description\":\"Los agricultores y ganaderos podr\u00e1n presentar la solicitud \u00fanica de ayudas de la Pol\u00edtica Agraria Com\u00fan (PAC) de la campa\u00f1a 2025 hasta el pr\u00f3ximo\u00a031 de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/05\/Captura-1.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/05\/Captura-1.jpg\",\"width\":879,\"height\":544},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/salamanca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se ampl\u00eda al 31 de mayo el plazo sin penalizaci\u00f3n para presentar la PAC, pero ASAJA aconseja anticiparse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/\",\"name\":\"ASAJA Salamanca\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\",\"name\":\"Sonia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"caption\":\"Sonia\"},\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se ampl\u00eda al 31 de mayo el plazo sin penalizaci\u00f3n para presentar la PAC, pero ASAJA aconseja anticiparse - ASAJA Salamanca","description":"Los agricultores y ganaderos podr\u00e1n presentar la solicitud \u00fanica de ayudas de la Pol\u00edtica Agraria Com\u00fan (PAC) de la campa\u00f1a 2025 hasta el pr\u00f3ximo\u00a031 de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse","og_locale":"es_ES","og_type":"article","og_title":"Se ampl\u00eda al 31 de mayo el plazo sin penalizaci\u00f3n para presentar la PAC, pero ASAJA aconseja anticiparse - ASAJA Salamanca","og_description":"Los agricultores y ganaderos podr\u00e1n presentar la solicitud \u00fanica de ayudas de la Pol\u00edtica Agraria Com\u00fan (PAC) de la campa\u00f1a 2025 hasta el pr\u00f3ximo\u00a031 de","og_url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse","og_site_name":"ASAJA Salamanca","article_published_time":"2025-05-12T11:32:15+00:00","article_modified_time":"2025-11-11T07:44:31+00:00","og_image":[{"width":879,"height":544,"url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/05\/Captura-1.jpg","type":"image\/jpeg"}],"author":"Sonia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sonia","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse","url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse","name":"Se ampl\u00eda al 31 de mayo el plazo sin penalizaci\u00f3n para presentar la PAC, pero ASAJA aconseja anticiparse - ASAJA Salamanca","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/05\/Captura-1.jpg","datePublished":"2025-05-12T11:32:15+00:00","dateModified":"2025-11-11T07:44:31+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f"},"description":"Los agricultores y ganaderos podr\u00e1n presentar la solicitud \u00fanica de ayudas de la Pol\u00edtica Agraria Com\u00fan (PAC) de la campa\u00f1a 2025 hasta el pr\u00f3ximo\u00a031 de","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse#primaryimage","url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/05\/Captura-1.jpg","contentUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2025\/05\/Captura-1.jpg","width":879,"height":544},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/se-amplia-al-31-de-mayo-el-plazo-sin-penalizacion-para-presentar-la-pac-pero-asaja-aconseja-anticiparse#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/salamanca\/"},{"@type":"ListItem","position":2,"name":"Se ampl\u00eda al 31 de mayo el plazo sin penalizaci\u00f3n para presentar la PAC, pero ASAJA aconseja anticiparse"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/salamanca\/#website","url":"https:\/\/www.asajacyl.com\/salamanca\/","name":"ASAJA Salamanca","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f","name":"Sonia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","caption":"Sonia"},"url":"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/19225"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/comments?post=19225"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/19225\/revisions"}],"predecessor-version":[{"id":19227,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/19225\/revisions\/19227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media\/19226"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media?parent=19225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/categories?post=19225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/tags?post=19225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}