{"id":6520,"date":"2019-01-18T08:31:14","date_gmt":"2019-01-18T08:31:14","guid":{"rendered":"https:\/\/www.asajacyl.com\/salamanca\/?p=6520"},"modified":"2019-01-18T08:31:14","modified_gmt":"2019-01-18T08:31:14","slug":"lonja-agropecuaria-salamanca-del-8-enero-2019","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019","title":{"rendered":"Lonja Agropecuaria de Salamanca del 8 de enero de 2019"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":5980,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37,38,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lonja Agropecuaria de Salamanca del 8 de enero de 2019 - ASAJA Salamanca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lonja Agropecuaria de Salamanca del 8 de enero de 2019 - ASAJA Salamanca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Salamanca\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-18T08:31:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2018\/08\/Triticale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"782\" \/>\n\t<meta property=\"og:image:height\" content=\"586\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019\",\"name\":\"Lonja Agropecuaria de Salamanca del 8 de enero de 2019 - ASAJA Salamanca\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2018\/08\/Triticale.jpg\",\"datePublished\":\"2019-01-18T08:31:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2018\/08\/Triticale.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2018\/08\/Triticale.jpg\",\"width\":782,\"height\":586},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/salamanca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lonja Agropecuaria de Salamanca del 8 de enero de 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/\",\"name\":\"ASAJA Salamanca\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\",\"name\":\"Sonia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"caption\":\"Sonia\"},\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lonja Agropecuaria de Salamanca del 8 de enero de 2019 - ASAJA Salamanca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019","og_locale":"es_ES","og_type":"article","og_title":"Lonja Agropecuaria de Salamanca del 8 de enero de 2019 - ASAJA Salamanca","og_url":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019","og_site_name":"ASAJA Salamanca","article_published_time":"2019-01-18T08:31:14+00:00","og_image":[{"width":782,"height":586,"url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2018\/08\/Triticale.jpg","type":"image\/jpeg"}],"author":"Sonia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sonia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019","url":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019","name":"Lonja Agropecuaria de Salamanca del 8 de enero de 2019 - ASAJA Salamanca","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2018\/08\/Triticale.jpg","datePublished":"2019-01-18T08:31:14+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f"},"breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019#primaryimage","url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2018\/08\/Triticale.jpg","contentUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2018\/08\/Triticale.jpg","width":782,"height":586},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-8-enero-2019#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/salamanca\/"},{"@type":"ListItem","position":2,"name":"Lonja Agropecuaria de Salamanca del 8 de enero de 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/salamanca\/#website","url":"https:\/\/www.asajacyl.com\/salamanca\/","name":"ASAJA Salamanca","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f","name":"Sonia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","caption":"Sonia"},"url":"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/6520"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/comments?post=6520"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/6520\/revisions"}],"predecessor-version":[{"id":6525,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/6520\/revisions\/6525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media\/5980"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media?parent=6520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/categories?post=6520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/tags?post=6520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}