{"id":7690,"date":"2019-10-17T07:59:17","date_gmt":"2019-10-17T07:59:17","guid":{"rendered":"https:\/\/www.asajacyl.com\/salamanca\/?p=7690"},"modified":"2019-10-17T08:57:38","modified_gmt":"2019-10-17T08:57:38","slug":"14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica","title":{"rendered":"Hasta el 14 de noviembre, se podr\u00e1n solicitar las ayudas por la incorporaci\u00f3n de medidas de agroambiente y clima y de agricultura ecol\u00f3gica"},"content":{"rendered":"<p>La Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convoca la incorporaci\u00f3n a las medidas de agroambiente y clima y a la medida a la agricultura ecol\u00f3gica, contenidas en el Programa de Desarrollo Rural de Castilla y Le\u00f3n 2014-2020 y cofinanciadas por el Fondo Europeo Agr\u00edcola de Desarrollo Rural (FEADER), para iniciar los compromisos en la campa\u00f1a agr\u00edcola 2019\/2020 o a\u00f1o 2020.<\/p>\n<p><strong>\u00bfQui\u00e9nes son los beneficiarios?<\/strong><\/p>\n<p>Los titulares de explotaciones agrarias que se comprometan voluntariamente a<br \/>\nadoptar pr\u00e1cticas y m\u00e9todos de agroambiente y clima y de agricultura ecol\u00f3gica, que<br \/>\ncumplan los requisitos y los compromisos establecidos.<\/p>\n<p><strong>\u00bfCu\u00e1les son los reg\u00edmenes de ayudas?<\/strong><\/p>\n<p><strong>1.<\/strong> Medidas de agroambiente y clima, incluidas en el Programa de Desarrollo Rural de Castilla y Le\u00f3n 2014-2020, para la campa\u00f1a agr\u00edcola 2019\/2020 (cosecha 2020) y\/o a\u00f1o 2020:<br \/>\n\u2013 Agroecosistemas extensivos de secano en humedales de importancia<br \/>\ninternacional<br \/>\n\u2013 Apicultura para la mejora de la biodiversidad<br \/>\n\u2013 Aprovechamiento forrajero extensivo mediante pastoreo con ganado ovino y\/o<br \/>\ncaprino<br \/>\n\u2013 Cultivo agroindustriales sostenibles<br \/>\n\u2013 Cultivos permanentes en paisajes singulares<\/p>\n<p>Gesti\u00f3n sostenible de superficies forrajeras pastables y apoyo a los sistemas tradicionales de pastoreo trashumante<br \/>\n\u2013 Producci\u00f3n integrada<br \/>\n\u2013 Mantenimiento de razas aut\u00f3ctonas puras en peligro de extinci\u00f3n<\/p>\n<p><strong>2.<\/strong> Medida de agricultura ecol\u00f3gica, incluida en el Programa de Desarrollo Rural de Castilla y Le\u00f3n 2014-2020, para la campa\u00f1a agr\u00edcola 2019\/2020 (cosecha 2020).<\/p>\n<p><strong>\u00bfCu\u00e1les son las bases reguladoras?<\/strong><\/p>\n<p>\u2013 Orden AYG\/1129\/2014, de 19 de diciembre, por la que se regulan las medidas de agroambiente y clima, contenidas en el Programa de Desarrollo Rural de Castilla y Le\u00f3n 2014-2020 y cofinanciadas por el Fondo Europeo Agr\u00edcola de Desarrollo Rural (Feader).<br \/>\n\u2013 Orden AYG\/1132\/2014, de 19 de diciembre, por la que se regula la medida de agricultura ecol\u00f3gica, contenida en el Programa de Desarrollo Rural de Castilla y Le\u00f3n 2014-2020 y cofinanciada por el Fondo Europeo Agr\u00edcola de Desarrollo Rural (Feader).<\/p>\n<p><strong>\u00bfQu\u00e9 plazo de presentaci\u00f3n de solicitudes hay?<\/strong><\/p>\n<p>Del 17 de octubre hasta el 14 de noviembre de 2019, ambos incluidos.<\/p>\n<p><strong>\u00bfCu\u00e1l es el presupuesto?<\/strong><\/p>\n<p>A los efectos de la incorporaci\u00f3n de las ayudas de agroambiente y clima se prev\u00e9 una disponibilidad presupuestaria de 10.000.000 euros, as\u00ed como, para la agricultura ecol\u00f3gica de 7.500.000 euros, todo ello para las anualidades 2020-2024 y con cargo a la aplicaci\u00f3n presupuestaria 03.05.412A01.77072 o por su equivalente en los Presupuestos Generales de la Comunidad de Castilla y Le\u00f3n en a\u00f1os sucesivos.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convoca la incorporaci\u00f3n a las medidas de agroambiente y clima y a la medida a la agricultura ecol\u00f3gica, contenidas en el Programa de Desarrollo Rural de Castilla y Le\u00f3n 2014-2020 y cofinanciadas por el Fondo Europeo Agr\u00edcola de Desarrollo Rural (FEADER), para iniciar [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":7691,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,510,39],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hasta el 14 de noviembre, se podr\u00e1n solicitar las ayudas por la incorporaci\u00f3n de medidas de agroambiente y clima y de agricultura ecol\u00f3gica - ASAJA Salamanca<\/title>\n<meta name=\"description\" content=\"La Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convoca la incorporaci\u00f3n a las medidas de agroambiente y clima y a la medida a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hasta el 14 de noviembre, se podr\u00e1n solicitar las ayudas por la incorporaci\u00f3n de medidas de agroambiente y clima y de agricultura ecol\u00f3gica - ASAJA Salamanca\" \/>\n<meta property=\"og:description\" content=\"La Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convoca la incorporaci\u00f3n a las medidas de agroambiente y clima y a la medida a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Salamanca\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-17T07:59:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-17T08:57:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2019\/10\/54728506_1051314518385762_5790895931226324992_o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica\",\"name\":\"Hasta el 14 de noviembre, se podr\u00e1n solicitar las ayudas por la incorporaci\u00f3n de medidas de agroambiente y clima y de agricultura ecol\u00f3gica - ASAJA Salamanca\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2019\/10\/54728506_1051314518385762_5790895931226324992_o.jpg\",\"datePublished\":\"2019-10-17T07:59:17+00:00\",\"dateModified\":\"2019-10-17T08:57:38+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\"},\"description\":\"La Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convoca la incorporaci\u00f3n a las medidas de agroambiente y clima y a la medida a\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2019\/10\/54728506_1051314518385762_5790895931226324992_o.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2019\/10\/54728506_1051314518385762_5790895931226324992_o.jpg\",\"width\":2048,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/salamanca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hasta el 14 de noviembre, se podr\u00e1n solicitar las ayudas por la incorporaci\u00f3n de medidas de agroambiente y clima y de agricultura ecol\u00f3gica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/\",\"name\":\"ASAJA Salamanca\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\",\"name\":\"Sonia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"caption\":\"Sonia\"},\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hasta el 14 de noviembre, se podr\u00e1n solicitar las ayudas por la incorporaci\u00f3n de medidas de agroambiente y clima y de agricultura ecol\u00f3gica - ASAJA Salamanca","description":"La Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convoca la incorporaci\u00f3n a las medidas de agroambiente y clima y a la medida a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica","og_locale":"es_ES","og_type":"article","og_title":"Hasta el 14 de noviembre, se podr\u00e1n solicitar las ayudas por la incorporaci\u00f3n de medidas de agroambiente y clima y de agricultura ecol\u00f3gica - ASAJA Salamanca","og_description":"La Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convoca la incorporaci\u00f3n a las medidas de agroambiente y clima y a la medida a","og_url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica","og_site_name":"ASAJA Salamanca","article_published_time":"2019-10-17T07:59:17+00:00","article_modified_time":"2019-10-17T08:57:38+00:00","og_image":[{"width":2048,"height":1152,"url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2019\/10\/54728506_1051314518385762_5790895931226324992_o.jpg","type":"image\/jpeg"}],"author":"Sonia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sonia","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica","url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica","name":"Hasta el 14 de noviembre, se podr\u00e1n solicitar las ayudas por la incorporaci\u00f3n de medidas de agroambiente y clima y de agricultura ecol\u00f3gica - ASAJA Salamanca","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2019\/10\/54728506_1051314518385762_5790895931226324992_o.jpg","datePublished":"2019-10-17T07:59:17+00:00","dateModified":"2019-10-17T08:57:38+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f"},"description":"La Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convoca la incorporaci\u00f3n a las medidas de agroambiente y clima y a la medida a","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica#primaryimage","url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2019\/10\/54728506_1051314518385762_5790895931226324992_o.jpg","contentUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2019\/10\/54728506_1051314518385762_5790895931226324992_o.jpg","width":2048,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/14-noviembre-se-podran-solicitar-las-ayudas-la-incorporacion-medidas-agroambiente-clima-agricultura-ecologica#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/salamanca\/"},{"@type":"ListItem","position":2,"name":"Hasta el 14 de noviembre, se podr\u00e1n solicitar las ayudas por la incorporaci\u00f3n de medidas de agroambiente y clima y de agricultura ecol\u00f3gica"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/salamanca\/#website","url":"https:\/\/www.asajacyl.com\/salamanca\/","name":"ASAJA Salamanca","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f","name":"Sonia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","caption":"Sonia"},"url":"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/7690"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/comments?post=7690"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/7690\/revisions"}],"predecessor-version":[{"id":7692,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/7690\/revisions\/7692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media\/7691"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media?parent=7690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/categories?post=7690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/tags?post=7690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}