{"id":8302,"date":"2020-02-18T12:33:28","date_gmt":"2020-02-18T12:33:28","guid":{"rendered":"https:\/\/www.asajacyl.com\/salamanca\/?p=8302"},"modified":"2020-02-18T12:33:28","modified_gmt":"2020-02-18T12:33:28","slug":"lonja-agropecuaria-salamanca-del-10-febrero-2020","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020","title":{"rendered":"Lonja Agropecuaria de Salamanca del 10 de febrero de 2020"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":8290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37,38,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lonja Agropecuaria de Salamanca del 10 de febrero de 2020 - ASAJA Salamanca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lonja Agropecuaria de Salamanca del 10 de febrero de 2020 - ASAJA Salamanca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Salamanca\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-18T12:33:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/02\/WhatsApp-Image-2019-11-19-at-12.41.12.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020\",\"name\":\"Lonja Agropecuaria de Salamanca del 10 de febrero de 2020 - ASAJA Salamanca\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/02\/WhatsApp-Image-2019-11-19-at-12.41.12.jpeg\",\"datePublished\":\"2020-02-18T12:33:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/02\/WhatsApp-Image-2019-11-19-at-12.41.12.jpeg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/02\/WhatsApp-Image-2019-11-19-at-12.41.12.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/salamanca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lonja Agropecuaria de Salamanca del 10 de febrero de 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/\",\"name\":\"ASAJA Salamanca\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\",\"name\":\"Sonia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"caption\":\"Sonia\"},\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lonja Agropecuaria de Salamanca del 10 de febrero de 2020 - ASAJA Salamanca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020","og_locale":"es_ES","og_type":"article","og_title":"Lonja Agropecuaria de Salamanca del 10 de febrero de 2020 - ASAJA Salamanca","og_url":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020","og_site_name":"ASAJA Salamanca","article_published_time":"2020-02-18T12:33:28+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/02\/WhatsApp-Image-2019-11-19-at-12.41.12.jpeg","type":"image\/jpeg"}],"author":"Sonia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sonia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020","url":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020","name":"Lonja Agropecuaria de Salamanca del 10 de febrero de 2020 - ASAJA Salamanca","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/02\/WhatsApp-Image-2019-11-19-at-12.41.12.jpeg","datePublished":"2020-02-18T12:33:28+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f"},"breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020#primaryimage","url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/02\/WhatsApp-Image-2019-11-19-at-12.41.12.jpeg","contentUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/02\/WhatsApp-Image-2019-11-19-at-12.41.12.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/salamanca\/servicios-socio\/lonja-agropecuaria-salamanca-del-10-febrero-2020#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/salamanca\/"},{"@type":"ListItem","position":2,"name":"Lonja Agropecuaria de Salamanca del 10 de febrero de 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/salamanca\/#website","url":"https:\/\/www.asajacyl.com\/salamanca\/","name":"ASAJA Salamanca","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f","name":"Sonia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","caption":"Sonia"},"url":"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/8302"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/comments?post=8302"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/8302\/revisions"}],"predecessor-version":[{"id":8305,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/8302\/revisions\/8305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media\/8290"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media?parent=8302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/categories?post=8302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/tags?post=8302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}