{"id":8462,"date":"2020-05-06T07:38:24","date_gmt":"2020-05-06T07:38:24","guid":{"rendered":"https:\/\/www.asajacyl.com\/salamanca\/?p=8462"},"modified":"2020-05-08T09:03:05","modified_gmt":"2020-05-08T09:03:05","slug":"gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19","title":{"rendered":"El Gobierno aprueba ayudas para ganaderos de ovino y caprino con dificultades de comercializaci\u00f3n por COVID-19"},"content":{"rendered":"<h2>Ser perceptor de la ayuda de la PAC a estas producciones har\u00e1 que sea autom\u00e1ticamente beneficiario de la subvenci\u00f3n<\/h2>\n<ul>\n<li><strong>Su objetivo es paliar la situaci\u00f3n de los ganaderos que no han podido dar una salida comercial a sus animales, por el cierre de la hosteler\u00eda y la restauraci\u00f3n como consecuencia de la crisis sanitaria<\/strong><strong>\u00a0<\/strong><\/li>\n<\/ul>\n<ul>\n<li><strong>El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n financiar\u00e1 estas ayudas hasta un l\u00edmite de 10 millones de euros, y las CCAA tambi\u00e9n <\/strong><strong>podr\u00e1n aportar financiaci\u00f3n complementaria, con el l\u00edmite de 25.000 euros por beneficiario<\/strong><strong>\u00a0<\/strong><\/li>\n<\/ul>\n<ul>\n<li><strong>Estas subvenciones, para el ejercicio 2020, constituyen un complemento de las ayudas destinadas al pago por oveja y cabra establecidas en el Real Decreto 1075\/2014 de ayudas de la PAC<\/strong><strong>\u00a0<\/strong><\/li>\n<\/ul>\n<ul>\n<li><strong>Para facilitar a los ganaderos la percepci\u00f3n de las ayudas y reducir las cargas administrativas, las subvenciones se percibir\u00e1n como complemento de la PAC a estas producciones<\/strong><\/li>\n<\/ul>\n<p>El \u00a0Consejo de Ministros ha aprobado este 5 de mayo de 2020, a propuesta del Ministerio de Agricultura, Pesca y Alimentaci\u00f3n, un Real Decreto por el que se establecen las bases de las ayudas estatales a las explotaciones ovinas y caprinas que han tenido dificultades en la comercializaci\u00f3n de corderos y cabritos en los meses de marzo y abril, como consecuencia de las limitaciones derivadas por el estado de alarma frente a la COVID-19.<\/p>\n<p>Unas ayudas destinadas a paliar la situaci\u00f3n de un sector estrat\u00e9gico en el \u00e1mbito econ\u00f3mico, social y medioambiental, con una producci\u00f3n muy estacional, ligada a un consumo mayoritario durante los meses de marzo y abril y casi en su totalidad a trav\u00e9s del canal de la restauraci\u00f3n y la hosteler\u00eda, cerrado por la actual crisis sanitaria.<\/p>\n<p>Estas subvenciones, para el ejercicio 2020, constituyen un complemento de las ayudas destinadas al pago por oveja y cabra establecidas en el Real Decreto 1075\/2014 de ayudas de la Pol\u00edtica Agraria Com\u00fan (PAC). Por ello, para reducir las cargas administrativas, <strong>el hecho de ser perceptor de la ayuda de la PAC a estas producciones har\u00e1 que sea autom\u00e1ticamente beneficiario de la subvenci\u00f3n<\/strong>.<\/p>\n<p>Las ayudas se otorgar\u00e1n en r\u00e9gimen de concurrencia competitiva, de acuerdo con los criterios que fijar\u00e1n las comunidades aut\u00f3nomas, pero se tomar\u00e1 en cuenta la condici\u00f3n de joven agricultor.<\/p>\n<h2>Financiaci\u00f3n<\/h2>\n<p>El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n financiar\u00e1 estas ayudas hasta un l\u00edmite de <strong>10 millones de euros<\/strong>, con cargo a los Presupuestos Generales del Estado para 2020.<\/p>\n<p>Las autonom\u00edas podr\u00e1n tambi\u00e9n aportar <strong>financiaci\u00f3n complementaria, con el l\u00edmite de 25.000 euros por beneficiario<\/strong> en tres ejercicios fiscales, de acuerdo con lo previsto sobre ayudas \u00abde minimis\u00bb en el sector agr\u00edcola.<\/p>\n<h2>Beneficiarios<\/h2>\n<p>Podr\u00e1n ser beneficiarios de las ayudas las personas f\u00edsicas o jur\u00eddicas, o entes sin personalidad jur\u00eddica, que presenten en 2020 la solicitud \u00fanica y que sean titulares de una explotaci\u00f3n inscrita en el registro general de explotaciones ganaderas (REGA).<\/p>\n<p>En concreto podr\u00e1n optar a estas subvenciones los titulares de las explotaciones de ovino con una clasificaci\u00f3n zoot\u00e9cnica de \u00abreproducci\u00f3n para la producci\u00f3n de carne\u00bb, \u00abreproducci\u00f3n para la producci\u00f3n de leche\u00bb o \u00abreproducci\u00f3n para producci\u00f3n mixta\u00bb con m\u00e1s de 50 hembras reproductoras.<\/p>\n<p>Tambi\u00e9n podr\u00e1n solicitar estas ayudas los titulares de explotaciones de caprino con una clasificaci\u00f3n zoot\u00e9cnica de \u00abreproducci\u00f3n para la producci\u00f3n de carne\u00bb, \u00abreproducci\u00f3n para la producci\u00f3n de leche\u00bb o \u00abreproducci\u00f3n para producci\u00f3n mixta\u201d con m\u00e1s de 30 hembras reproductoras conforme a la \u00faltima declaraci\u00f3n censal obligatoria.<\/p>\n<p>No obstante, las autoridades competentes de las comunidades aut\u00f3nomas podr\u00e1n rebajar el l\u00edmite inferior de m\u00e1s de 50 \u00f3 30 hembras reproductoras en caso de que su censo de ovino o caprino, respectivamente, sea inferior al 2 % respecto del censo nacional.<\/p>\n<p>En cuanto al n\u00famero de animales con derecho a ayuda, se considerar\u00e1n \u201chembras elegibles\u201d aquellas ovejas y cabras mantenidas como reproductoras que est\u00e9n correctamente identificadas y registradas a fecha 1 de enero de 2020 y cuya producci\u00f3n de corderos y cabritos se haya visto afectada por la situaci\u00f3n creada entre el 14 de marzo y el 30 de abril.<\/p>\n<p><strong>\u00a0<\/strong>La ayuda se conceder\u00e1 al n\u00famero de ovejas y cabras elegibles, con un m\u00e1ximo de 100 animales por beneficiario y una subvenci\u00f3n m\u00e1xima por animal de 12 euros. La autoridad competente de la comunidad aut\u00f3noma calcular\u00e1, a partir de la informaci\u00f3n contenida en el Sistema Integral de Trazabilidad Animal (SITRAN), el n\u00famero de animales con derecho a ayuda de los beneficiarios, pudiendo establecer los controles que considere necesarios.<\/p>\n<p>La tramitaci\u00f3n, resoluci\u00f3n, justificaci\u00f3n, pago y control de las ayudas corresponder\u00e1\u00a0 a las comunidades aut\u00f3nomas, que se encargar\u00e1n tambi\u00e9n de\u00a0 publicar las\u00a0 correspondientes convocatorias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser perceptor de la ayuda de la PAC a estas producciones har\u00e1 que sea autom\u00e1ticamente beneficiario de la subvenci\u00f3n Su objetivo es paliar la situaci\u00f3n de los ganaderos que no han podido dar una salida comercial a sus animales, por el cierre de la hosteler\u00eda y la restauraci\u00f3n como consecuencia de la crisis sanitaria\u00a0 El [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":8463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[510,39],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno aprueba ayudas para ganaderos de ovino y caprino con dificultades de comercializaci\u00f3n por COVID-19 - ASAJA Salamanca<\/title>\n<meta name=\"description\" content=\"Ser perceptor de la ayuda de la PAC a estas producciones har\u00e1 que sea autom\u00e1ticamente beneficiario de la subvenci\u00f3n Su objetivo es paliar la situaci\u00f3n de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno aprueba ayudas para ganaderos de ovino y caprino con dificultades de comercializaci\u00f3n por COVID-19 - ASAJA Salamanca\" \/>\n<meta property=\"og:description\" content=\"Ser perceptor de la ayuda de la PAC a estas producciones har\u00e1 que sea autom\u00e1ticamente beneficiario de la subvenci\u00f3n Su objetivo es paliar la situaci\u00f3n de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Salamanca\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-06T07:38:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-08T09:03:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/05\/sheep-2517055_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19\",\"name\":\"El Gobierno aprueba ayudas para ganaderos de ovino y caprino con dificultades de comercializaci\u00f3n por COVID-19 - ASAJA Salamanca\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/05\/sheep-2517055_1920.jpg\",\"datePublished\":\"2020-05-06T07:38:24+00:00\",\"dateModified\":\"2020-05-08T09:03:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\"},\"description\":\"Ser perceptor de la ayuda de la PAC a estas producciones har\u00e1 que sea autom\u00e1ticamente beneficiario de la subvenci\u00f3n Su objetivo es paliar la situaci\u00f3n de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/05\/sheep-2517055_1920.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/05\/sheep-2517055_1920.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/salamanca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno aprueba ayudas para ganaderos de ovino y caprino con dificultades de comercializaci\u00f3n por COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/\",\"name\":\"ASAJA Salamanca\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f\",\"name\":\"Sonia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g\",\"caption\":\"Sonia\"},\"url\":\"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno aprueba ayudas para ganaderos de ovino y caprino con dificultades de comercializaci\u00f3n por COVID-19 - ASAJA Salamanca","description":"Ser perceptor de la ayuda de la PAC a estas producciones har\u00e1 que sea autom\u00e1ticamente beneficiario de la subvenci\u00f3n Su objetivo es paliar la situaci\u00f3n de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno aprueba ayudas para ganaderos de ovino y caprino con dificultades de comercializaci\u00f3n por COVID-19 - ASAJA Salamanca","og_description":"Ser perceptor de la ayuda de la PAC a estas producciones har\u00e1 que sea autom\u00e1ticamente beneficiario de la subvenci\u00f3n Su objetivo es paliar la situaci\u00f3n de","og_url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19","og_site_name":"ASAJA Salamanca","article_published_time":"2020-05-06T07:38:24+00:00","article_modified_time":"2020-05-08T09:03:05+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/05\/sheep-2517055_1920.jpg","type":"image\/jpeg"}],"author":"Sonia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sonia","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19","url":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19","name":"El Gobierno aprueba ayudas para ganaderos de ovino y caprino con dificultades de comercializaci\u00f3n por COVID-19 - ASAJA Salamanca","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/05\/sheep-2517055_1920.jpg","datePublished":"2020-05-06T07:38:24+00:00","dateModified":"2020-05-08T09:03:05+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f"},"description":"Ser perceptor de la ayuda de la PAC a estas producciones har\u00e1 que sea autom\u00e1ticamente beneficiario de la subvenci\u00f3n Su objetivo es paliar la situaci\u00f3n de","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19#primaryimage","url":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/05\/sheep-2517055_1920.jpg","contentUrl":"https:\/\/www.asajacyl.com\/salamanca\/wp-content\/uploads\/sites\/7\/2020\/05\/sheep-2517055_1920.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/salamanca\/asaja-salamanca-informa\/noticias\/gobierno-aprueba-ayudas-ganaderos-ovino-caprino-dificultades-comercializacion-covid-19#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/salamanca\/"},{"@type":"ListItem","position":2,"name":"El Gobierno aprueba ayudas para ganaderos de ovino y caprino con dificultades de comercializaci\u00f3n por COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/salamanca\/#website","url":"https:\/\/www.asajacyl.com\/salamanca\/","name":"ASAJA Salamanca","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/salamanca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/2bfc7da09988e1087e6291fafe99b67f","name":"Sonia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/salamanca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b0d6eb461a1e3687cc023d59022ef0d?s=96&d=mm&r=g","caption":"Sonia"},"url":"https:\/\/www.asajacyl.com\/salamanca\/author\/juanluisde"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/8462"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/comments?post=8462"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/8462\/revisions"}],"predecessor-version":[{"id":8464,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/posts\/8462\/revisions\/8464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media\/8463"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/media?parent=8462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/categories?post=8462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/salamanca\/wp-json\/wp\/v2\/tags?post=8462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}