{"id":2979,"date":"2020-03-25T18:38:46","date_gmt":"2020-03-25T17:38:46","guid":{"rendered":"https:\/\/www.asajacyl.com\/soria\/?p=2979"},"modified":"2020-03-31T09:24:29","modified_gmt":"2020-03-31T07:24:29","slug":"honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales","title":{"rendered":"Honda preocupaci\u00f3n en ASAJA Soria por la situaci\u00f3n de aquellas explotaciones cuyo mercado era la restauraci\u00f3n o los eventos sociales"},"content":{"rendered":"<h2><em>La OPA destaca el grave escenario que sufre el sector ovino-caprino provincial y considera vital encontrar mercado y ofrecer apoyo a estas producciones<\/em><\/h2>\n<p>La Asociaci\u00f3n Agraria de J\u00f3venes Agricultores de Soria (ASAJA) corrobora que se est\u00e1n produciendo situaciones dram\u00e1ticas en las producciones ganaderas de la provincia y as\u00ed lo est\u00e1 transmitiendo a las autoridades correspondientes para que tomen medidas urgentes. Los ganaderos han trasladado a la OPA la imposibilidad de dar salida a animales hacia mataderos por el cierre de ciertos mercados por la crisis del coronavirus.<\/p>\n<p>El canal m\u00e1s fuerte de venta de muchos de estos productos es la hosteler\u00eda y restauraci\u00f3n durante todo el a\u00f1o. Pero esta salida de la producci\u00f3n queda cerrada por el Estado de Alarma. Por eso, ASAJA ya pidi\u00f3 la semana pasada a la Consejer\u00eda de Agricultura, Ganader\u00eda y Medio Rural que intercediese a favor de los subsectores y producciones agroganaderas, y ya se est\u00e1 viendo en estos d\u00edas posteriores que los primeros damnificados son productos muy ligados a la restauraci\u00f3n, como es el lechazo. Y es que en el sector ganadero de ovino de carne se detecta un hundimiento de la demanda por parte de los intermediarios, que no quieren cerrar operaciones al estar paralizado su canal principal de venta, la hosteler\u00eda, y tambi\u00e9n por la imposibilidad de que haya celebraciones familiares o de otro tipo, para respetar las medidas de cuarentena.<\/p>\n<p>Ante esta situaci\u00f3n dram\u00e1tica para muchos profesionales de la ganader\u00eda, ASAJA Soria aprovecha, como lo ha hecho siempre pero en estas circunstancias con mucha m\u00e1s insistencia, para animar a toda la sociedad a que consuma especialmente cordero, cabrito y ternera de alta calidad; esos productos tan sabrosos y que poseen una calidad y unos valores alimentarios y hasta sociales indiscutibles, y que ten\u00edan como destino principal la restauraci\u00f3n antes de que se decretase el Estado de Alarma. Hoy por hoy, como lo est\u00e1n siempre, esos productos se encuentran en los lineales de los supermercados a unos precios muy competitivos y con una calidad indiscutible en todos los sentidos.<\/p>\n<p>Uno de los objetivos que puede ser clave para el futuro del sector, en opini\u00f3n de ASAJA Soria, es que se pueda dar salida a la oferta actual de lechazo, porque por motivos clim\u00e1ticos la paridera de las ovejas se concentra fuertemente en estas semanas. La sociedad ha de entender que, para los ganaderos, no vender a su tiempo los lechazos supone un coste inasumible de alimentaci\u00f3n, y adem\u00e1s cuanto m\u00e1s grandes son se pagan peor en el mercado. Hay que recordar la importancia econ\u00f3mica y tambi\u00e9n social del sector ganadero de ovino, con explotaciones muy repartidas por todo el territorio, que sobreviven con m\u00e1rgenes muy ajustados y para las que resulta imposible afrontar las enormes p\u00e9rdidas que ya se est\u00e1n empezando a producir. El lechazo lleva meses, ya a\u00f1os, a unos precios bajos, y es justo por estas fechas, en torno a la Semana Santa, cuando tradicionalmente las cotizaciones suben un poco, algo que este a\u00f1o impide la actual crisis sanitaria y econ\u00f3mica.<\/p>\n<p>Adem\u00e1s, ya se han transmitido tambi\u00e9n al Gobierno central varias propuestas para mitigar esta preocupante situaci\u00f3n. Entre las m\u00e1s destacadas, y que se siguen ampliando y mejorando, est\u00e1n que para que la cadena siga funcionando con cierta normalidad abrir un almacenamiento privado de lechazos, cabritos, ternera&#8230; Se podr\u00eda almacenar hasta que pase la situaci\u00f3n y pueda ejecutarse su comercializaci\u00f3n, tanto interna como en el resto de la Uni\u00f3n Europea y terceros pa\u00edses. Otra alternativa podr\u00eda ser que el Ej\u00e9rcito compre estos productos para alimentaci\u00f3n de las tropas. Y una tercera, las compras para comedores colectivos, hospitales, etc.<\/p>\n<p>Seg\u00fan constata ASAJA, la situaci\u00f3n que padece el sector ovino-caprino es muy parecida a la de aquellas granjas dedicadas al cochinillo para restauraci\u00f3n, con un severo problema por su especializaci\u00f3n, el corto plazo de tiempo de maniobra que permite la producci\u00f3n y la imposibilidad de previsi\u00f3n.<\/p>\n<p>ASAJA denuncia que tambi\u00e9n se ha empezado a notar cierto estr\u00e9s en el mercado ordinario de los terneros pasteros. La organizaci\u00f3n, m\u00e1s all\u00e1 de que se pudiera constatar un problema de mercado en la carne de vacuno, advierte a los compradores sobre la necesidad de cumplir con la nueva normativa de la cadena alimentaria y asegura que estar\u00e1 muy atenta para denunciar aquellas pr\u00e1cticas que considere tendentes a aprovecharse de la situaci\u00f3n actual en contra del ganadero. ASAJA recuerda que vivimos tiempos en los que es preciso que todos arrimemos el hombro para salvar esta crisis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La OPA destaca el grave escenario que sufre el sector ovino-caprino provincial y considera vital encontrar mercado y ofrecer apoyo a estas producciones La Asociaci\u00f3n Agraria de J\u00f3venes Agricultores de Soria (ASAJA) corrobora que se est\u00e1n produciendo situaciones dram\u00e1ticas en las producciones ganaderas de la provincia y as\u00ed lo est\u00e1 transmitiendo a las autoridades correspondientes [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":458,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,25],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Honda preocupaci\u00f3n en ASAJA Soria por la situaci\u00f3n de aquellas explotaciones cuyo mercado era la restauraci\u00f3n o los eventos sociales - ASAJA Soria<\/title>\n<meta name=\"description\" content=\"La OPA destaca el grave escenario que sufre el sector ovino-caprino provincial y considera vital encontrar mercado y ofrecer apoyo a estas producciones La\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Honda preocupaci\u00f3n en ASAJA Soria por la situaci\u00f3n de aquellas explotaciones cuyo mercado era la restauraci\u00f3n o los eventos sociales - ASAJA Soria\" \/>\n<meta property=\"og:description\" content=\"La OPA destaca el grave escenario que sufre el sector ovino-caprino provincial y considera vital encontrar mercado y ofrecer apoyo a estas producciones La\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Soria\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-25T17:38:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-31T07:24:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2017\/12\/ovejas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Ignacio Prieto Nieto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Ignacio Prieto Nieto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales\",\"name\":\"Honda preocupaci\u00f3n en ASAJA Soria por la situaci\u00f3n de aquellas explotaciones cuyo mercado era la restauraci\u00f3n o los eventos sociales - ASAJA Soria\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2017\/12\/ovejas.jpg\",\"datePublished\":\"2020-03-25T17:38:46+00:00\",\"dateModified\":\"2020-03-31T07:24:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab\"},\"description\":\"La OPA destaca el grave escenario que sufre el sector ovino-caprino provincial y considera vital encontrar mercado y ofrecer apoyo a estas producciones La\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2017\/12\/ovejas.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2017\/12\/ovejas.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/soria\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Honda preocupaci\u00f3n en ASAJA Soria por la situaci\u00f3n de aquellas explotaciones cuyo mercado era la restauraci\u00f3n o los eventos sociales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/\",\"name\":\"ASAJA Soria\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/soria\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab\",\"name\":\"Juan Ignacio Prieto Nieto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g\",\"caption\":\"Juan Ignacio Prieto Nieto\"},\"url\":\"https:\/\/www.asajacyl.com\/soria\/author\/juanfranciscoby\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Honda preocupaci\u00f3n en ASAJA Soria por la situaci\u00f3n de aquellas explotaciones cuyo mercado era la restauraci\u00f3n o los eventos sociales - ASAJA Soria","description":"La OPA destaca el grave escenario que sufre el sector ovino-caprino provincial y considera vital encontrar mercado y ofrecer apoyo a estas producciones La","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales","og_locale":"es_ES","og_type":"article","og_title":"Honda preocupaci\u00f3n en ASAJA Soria por la situaci\u00f3n de aquellas explotaciones cuyo mercado era la restauraci\u00f3n o los eventos sociales - ASAJA Soria","og_description":"La OPA destaca el grave escenario que sufre el sector ovino-caprino provincial y considera vital encontrar mercado y ofrecer apoyo a estas producciones La","og_url":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales","og_site_name":"ASAJA Soria","article_published_time":"2020-03-25T17:38:46+00:00","article_modified_time":"2020-03-31T07:24:29+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2017\/12\/ovejas.jpg","type":"image\/jpeg"}],"author":"Juan Ignacio Prieto Nieto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Juan Ignacio Prieto Nieto","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales","url":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales","name":"Honda preocupaci\u00f3n en ASAJA Soria por la situaci\u00f3n de aquellas explotaciones cuyo mercado era la restauraci\u00f3n o los eventos sociales - ASAJA Soria","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/soria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2017\/12\/ovejas.jpg","datePublished":"2020-03-25T17:38:46+00:00","dateModified":"2020-03-31T07:24:29+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab"},"description":"La OPA destaca el grave escenario que sufre el sector ovino-caprino provincial y considera vital encontrar mercado y ofrecer apoyo a estas producciones La","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales#primaryimage","url":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2017\/12\/ovejas.jpg","contentUrl":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2017\/12\/ovejas.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/honda-preocupacion-asaja-soria-la-situacion-aquellas-explotaciones-cuyo-mercado-la-restauracion-los-eventos-sociales#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/soria\/"},{"@type":"ListItem","position":2,"name":"Honda preocupaci\u00f3n en ASAJA Soria por la situaci\u00f3n de aquellas explotaciones cuyo mercado era la restauraci\u00f3n o los eventos sociales"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/soria\/#website","url":"https:\/\/www.asajacyl.com\/soria\/","name":"ASAJA Soria","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/soria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab","name":"Juan Ignacio Prieto Nieto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g","caption":"Juan Ignacio Prieto Nieto"},"url":"https:\/\/www.asajacyl.com\/soria\/author\/juanfranciscoby"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/2979"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/comments?post=2979"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/2979\/revisions"}],"predecessor-version":[{"id":2980,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/2979\/revisions\/2980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/media\/458"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/media?parent=2979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/categories?post=2979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/tags?post=2979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}