{"id":3209,"date":"2020-05-25T13:43:45","date_gmt":"2020-05-25T11:43:45","guid":{"rendered":"https:\/\/www.asajacyl.com\/soria\/?p=3209"},"modified":"2020-05-28T08:26:45","modified_gmt":"2020-05-28T06:26:45","slug":"asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019","title":{"rendered":"ASAJA Soria publica los resultados de sus campos de ensayo de girasol 2019"},"content":{"rendered":"<p>Son los datos obtenidos en nuestros campos de ensayo de girasol de 2019. Con ellos, los profesionales del campo pueden comprobar los par\u00e1metros relacionados con la producci\u00f3n y la calidad de la cosecha.<\/p>\n<p>Para conocer otros datos de inter\u00e9s como ciclo o porte puedes consultarnos.<\/p>\n<p>ASAJA Soria quiere reconocer p\u00fablicamente la labor de los agricultores colaboradores, a la vez que agradece el respaldo de la Diputaci\u00f3n Provincial y de la Caja Rural de Soria, as\u00ed como el de las empresas colaboradoras, en especial a Syngenta siempre dispuesta a apoyar nuestro trabajo en coordinaci\u00f3n para ganar valor a\u00f1adido para los agricultores.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3210\" src=\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20191.jpg\" alt=\"\" width=\"637\" height=\"907\" srcset=\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20191.jpg 890w, https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20191-211x300.jpg 211w, https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20191-768x1093.jpg 768w, https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20191-719x1024.jpg 719w, https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20191-696x991.jpg 696w, https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20191-295x420.jpg 295w\" sizes=\"(max-width: 637px) 100vw, 637px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3211\" src=\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20192.jpg\" alt=\"\" width=\"614\" height=\"874\" srcset=\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20192.jpg 890w, https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20192-211x300.jpg 211w, https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20192-768x1093.jpg 768w, https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20192-719x1024.jpg 719w, https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20192-696x991.jpg 696w, https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20192-295x420.jpg 295w\" sizes=\"(max-width: 614px) 100vw, 614px\" \/><\/p>\n<p>AQU\u00cd TIENES LOS RESULTADOS TAMBI\u00c9N EN PDF:<\/p>\n<p><a href=\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20191.pdf\">GIRASOL 20191<\/a><\/p>\n<p><a href=\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/GIRASOL-20192.pdf\">GIRASOL 20192<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Son los datos obtenidos en nuestros campos de ensayo de girasol de 2019. Con ellos, los profesionales del campo pueden comprobar los par\u00e1metros relacionados con la producci\u00f3n y la calidad de la cosecha. Para conocer otros datos de inter\u00e9s como ciclo o porte puedes consultarnos. ASAJA Soria quiere reconocer p\u00fablicamente la labor de los agricultores [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":3213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,25],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA Soria publica los resultados de sus campos de ensayo de girasol 2019 - ASAJA Soria<\/title>\n<meta name=\"description\" content=\"Son los datos obtenidos en nuestros campos de ensayo de girasol de 2019. Con ellos, los profesionales del campo pueden comprobar los par\u00e1metros\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA Soria publica los resultados de sus campos de ensayo de girasol 2019 - ASAJA Soria\" \/>\n<meta property=\"og:description\" content=\"Son los datos obtenidos en nuestros campos de ensayo de girasol de 2019. Con ellos, los profesionales del campo pueden comprobar los par\u00e1metros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Soria\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-25T11:43:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-28T06:26:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/IMG_9043-girasol.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Ignacio Prieto Nieto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Ignacio Prieto Nieto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019\",\"name\":\"ASAJA Soria publica los resultados de sus campos de ensayo de girasol 2019 - ASAJA Soria\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/IMG_9043-girasol.jpg\",\"datePublished\":\"2020-05-25T11:43:45+00:00\",\"dateModified\":\"2020-05-28T06:26:45+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab\"},\"description\":\"Son los datos obtenidos en nuestros campos de ensayo de girasol de 2019. Con ellos, los profesionales del campo pueden comprobar los par\u00e1metros\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/IMG_9043-girasol.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/IMG_9043-girasol.jpg\",\"width\":2500,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/soria\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA Soria publica los resultados de sus campos de ensayo de girasol 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/\",\"name\":\"ASAJA Soria\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/soria\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab\",\"name\":\"Juan Ignacio Prieto Nieto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g\",\"caption\":\"Juan Ignacio Prieto Nieto\"},\"url\":\"https:\/\/www.asajacyl.com\/soria\/author\/juanfranciscoby\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA Soria publica los resultados de sus campos de ensayo de girasol 2019 - ASAJA Soria","description":"Son los datos obtenidos en nuestros campos de ensayo de girasol de 2019. Con ellos, los profesionales del campo pueden comprobar los par\u00e1metros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019","og_locale":"es_ES","og_type":"article","og_title":"ASAJA Soria publica los resultados de sus campos de ensayo de girasol 2019 - ASAJA Soria","og_description":"Son los datos obtenidos en nuestros campos de ensayo de girasol de 2019. Con ellos, los profesionales del campo pueden comprobar los par\u00e1metros","og_url":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019","og_site_name":"ASAJA Soria","article_published_time":"2020-05-25T11:43:45+00:00","article_modified_time":"2020-05-28T06:26:45+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/IMG_9043-girasol.jpg","type":"image\/jpeg"}],"author":"Juan Ignacio Prieto Nieto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Juan Ignacio Prieto Nieto","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019","url":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019","name":"ASAJA Soria publica los resultados de sus campos de ensayo de girasol 2019 - ASAJA Soria","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/soria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/IMG_9043-girasol.jpg","datePublished":"2020-05-25T11:43:45+00:00","dateModified":"2020-05-28T06:26:45+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab"},"description":"Son los datos obtenidos en nuestros campos de ensayo de girasol de 2019. Con ellos, los profesionales del campo pueden comprobar los par\u00e1metros","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019#primaryimage","url":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/IMG_9043-girasol.jpg","contentUrl":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/IMG_9043-girasol.jpg","width":2500,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/asaja-soria-publica-los-resultados-campos-ensayo-girasol-2019#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/soria\/"},{"@type":"ListItem","position":2,"name":"ASAJA Soria publica los resultados de sus campos de ensayo de girasol 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/soria\/#website","url":"https:\/\/www.asajacyl.com\/soria\/","name":"ASAJA Soria","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/soria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab","name":"Juan Ignacio Prieto Nieto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g","caption":"Juan Ignacio Prieto Nieto"},"url":"https:\/\/www.asajacyl.com\/soria\/author\/juanfranciscoby"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/3209"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/comments?post=3209"}],"version-history":[{"count":5,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/3209\/revisions"}],"predecessor-version":[{"id":3220,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/3209\/revisions\/3220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/media\/3213"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/media?parent=3209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/categories?post=3209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/tags?post=3209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}