{"id":3230,"date":"2020-05-18T08:25:21","date_gmt":"2020-05-18T06:25:21","guid":{"rendered":"https:\/\/www.asajacyl.com\/soria\/?p=3230"},"modified":"2020-05-19T11:36:48","modified_gmt":"2020-05-19T09:36:48","slug":"las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea","title":{"rendered":"Las claves para saber en qu\u00e9 consiste la estrategia &#8216;De la granja a la mesa&#8217; que prepara la Uni\u00f3n Europea"},"content":{"rendered":"<h2 class=\"bk-post-subtitle\">La Uni\u00f3n Europea prepara una estrategia para lograr una alimentaci\u00f3n m\u00e1s saludable y m\u00e1s sostenible. La Farm to Fork Strategy marcar\u00e1 el devenir de las normativas medioambientales o de pol\u00edticas tan importantes como la PAC.<\/h2>\n<p>En los pr\u00f3ximos d\u00edas, la Comisi\u00f3n Europea desvelar\u00e1 las claves de la que ser\u00e1 una de las pol\u00edticas clave de su mandato. Embebida dentro de la estrategia\u00a0<em>Green Deal<\/em>, la\u00a0<em>Farm to Fork Strategy\u00a0<\/em>(De la Granja a la Mesa) marcar\u00e1 el funcionamiento de la cadena agroalimentaria en todo el continente, ahondar\u00e1 en el objetivo de reducci\u00f3n de emisiones de gases de efecto invernadero y mejorar\u00e1 la protecci\u00f3n del medio ambiente en toda Europa.<\/p>\n<p>Uno de los principales valedores de la estrategia De la Granja a la Mesa o Del Campo a la Mesa es el vicepresidente de la Comisi\u00f3n Europea, el socialdem\u00f3crata holand\u00e9s\u00a0Frans Timmermans, quien pretende presentar la estrategia el pr\u00f3ximo 20 de mayo, tal y\u00a0como recogen Eldiariorural.es y Euractiv. La Comisi\u00f3n quiere que la presentaci\u00f3n de dicha estrategia coincida con el lanzamiento de la estrategia de\u00a0Biodiversidad.<\/p>\n<h3>Objetivos primordiales<\/h3>\n<p>\u201cEuropa es un ejemplo en seguridad alimentaria, as\u00ed como por la alta calidad de los\u00a0alimentos. Ahora tambi\u00e9n debe marcar el est\u00e1ndar global en sostenibilidad\u201d, aseguran desde la Comisi\u00f3n. Para ello, se incrementar\u00e1n las exigencias para reducir considerablemente \u2013hasta un 50%\u2013 el uso de pesticidas qu\u00edmicos, as\u00ed como de fertilizantes y de antibi\u00f3ticos en ganader\u00eda. Objetivo para el que se desarrollar\u00e1 un proceso de di\u00e1logo con los sectores afectados, como los agricultores y ganaderos. Las decisiones, asegura la CE, se guiar\u00e1n por criterios y evidencias cient\u00edficas.<\/p>\n<p>La estrategia De la Granja a la Mesa tratar\u00e1 de fomentar la econom\u00eda circular, reduciendo el impacto ambiental de la producci\u00f3n de alimentos y rebajando los porcentajes de desperdicio alimentario. Un asunto que preocupa mucho a la Comisi\u00f3n. No en vano, sus estimaciones afirman que cada a\u00f1o se desaprovechan en el mundo m\u00e1s de 1.300 millones de toneladas de alimentos, un tercio de la producci\u00f3n mundial.<\/p>\n<p>La estrategia Farm to Fork pretende que el 25% de la superficie agraria de la UE se destine a la producci\u00f3n ecol\u00f3gica, lejos del 9,3% que dedica Espa\u00f1a, l\u00edder de la UE en superficie, con 2,2 millones de hect\u00e1reas, pero no en porcentaje. Un objetivo que lideran Austria, Estonia y Suecia, con porcentajes por encima del 20% de las tierras dedicadas al ecol\u00f3gico.<\/p>\n<p>La estrategia promover\u00e1 tambi\u00e9n un mayor apoyo a los peque\u00f1os productores, fomentar\u00e1 el comercio de proximidad y cercan\u00eda y cambiar\u00e1 el etiquetado de los alimentos para dar una mayor informaci\u00f3n sobre el origen. Adem\u00e1s, tendr\u00e1 en cuenta conceptos como la protecci\u00f3n del paisaje que realizan los peque\u00f1os productores y tratar\u00e1 de incrementar la innovaci\u00f3n y la digitalizaci\u00f3n en la\u00a0cadena agroalimentaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Uni\u00f3n Europea prepara una estrategia para lograr una alimentaci\u00f3n m\u00e1s saludable y m\u00e1s sostenible. La Farm to Fork Strategy marcar\u00e1 el devenir de las normativas medioambientales o de pol\u00edticas tan importantes como la PAC. En los pr\u00f3ximos d\u00edas, la Comisi\u00f3n Europea desvelar\u00e1 las claves de la que ser\u00e1 una de las pol\u00edticas clave de [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":3177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,25],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las claves para saber en qu\u00e9 consiste la estrategia &#039;De la granja a la mesa&#039; que prepara la Uni\u00f3n Europea - ASAJA Soria<\/title>\n<meta name=\"description\" content=\"La Uni\u00f3n Europea prepara una estrategia para lograr una alimentaci\u00f3n m\u00e1s saludable y m\u00e1s sostenible. La Farm to Fork Strategy marcar\u00e1 el devenir de las\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las claves para saber en qu\u00e9 consiste la estrategia &#039;De la granja a la mesa&#039; que prepara la Uni\u00f3n Europea - ASAJA Soria\" \/>\n<meta property=\"og:description\" content=\"La Uni\u00f3n Europea prepara una estrategia para lograr una alimentaci\u00f3n m\u00e1s saludable y m\u00e1s sostenible. La Farm to Fork Strategy marcar\u00e1 el devenir de las\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Soria\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-18T06:25:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-19T09:36:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/ovino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Ignacio Prieto Nieto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Ignacio Prieto Nieto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea\",\"name\":\"Las claves para saber en qu\u00e9 consiste la estrategia 'De la granja a la mesa' que prepara la Uni\u00f3n Europea - ASAJA Soria\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/ovino.jpg\",\"datePublished\":\"2020-05-18T06:25:21+00:00\",\"dateModified\":\"2020-05-19T09:36:48+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab\"},\"description\":\"La Uni\u00f3n Europea prepara una estrategia para lograr una alimentaci\u00f3n m\u00e1s saludable y m\u00e1s sostenible. La Farm to Fork Strategy marcar\u00e1 el devenir de las\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/ovino.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/ovino.jpg\",\"width\":1536,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/soria\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las claves para saber en qu\u00e9 consiste la estrategia &#8216;De la granja a la mesa&#8217; que prepara la Uni\u00f3n Europea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/\",\"name\":\"ASAJA Soria\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/soria\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab\",\"name\":\"Juan Ignacio Prieto Nieto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g\",\"caption\":\"Juan Ignacio Prieto Nieto\"},\"url\":\"https:\/\/www.asajacyl.com\/soria\/author\/juanfranciscoby\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las claves para saber en qu\u00e9 consiste la estrategia 'De la granja a la mesa' que prepara la Uni\u00f3n Europea - ASAJA Soria","description":"La Uni\u00f3n Europea prepara una estrategia para lograr una alimentaci\u00f3n m\u00e1s saludable y m\u00e1s sostenible. La Farm to Fork Strategy marcar\u00e1 el devenir de las","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea","og_locale":"es_ES","og_type":"article","og_title":"Las claves para saber en qu\u00e9 consiste la estrategia 'De la granja a la mesa' que prepara la Uni\u00f3n Europea - ASAJA Soria","og_description":"La Uni\u00f3n Europea prepara una estrategia para lograr una alimentaci\u00f3n m\u00e1s saludable y m\u00e1s sostenible. La Farm to Fork Strategy marcar\u00e1 el devenir de las","og_url":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea","og_site_name":"ASAJA Soria","article_published_time":"2020-05-18T06:25:21+00:00","article_modified_time":"2020-05-19T09:36:48+00:00","og_image":[{"width":1536,"height":2048,"url":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/ovino.jpg","type":"image\/jpeg"}],"author":"Juan Ignacio Prieto Nieto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Juan Ignacio Prieto Nieto","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea","url":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea","name":"Las claves para saber en qu\u00e9 consiste la estrategia 'De la granja a la mesa' que prepara la Uni\u00f3n Europea - ASAJA Soria","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/soria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/ovino.jpg","datePublished":"2020-05-18T06:25:21+00:00","dateModified":"2020-05-19T09:36:48+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab"},"description":"La Uni\u00f3n Europea prepara una estrategia para lograr una alimentaci\u00f3n m\u00e1s saludable y m\u00e1s sostenible. La Farm to Fork Strategy marcar\u00e1 el devenir de las","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea#primaryimage","url":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/ovino.jpg","contentUrl":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/05\/ovino.jpg","width":1536,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/las-claves-saber-consiste-la-estrategia-la-granja-la-mesa-prepara-la-union-europea#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/soria\/"},{"@type":"ListItem","position":2,"name":"Las claves para saber en qu\u00e9 consiste la estrategia &#8216;De la granja a la mesa&#8217; que prepara la Uni\u00f3n Europea"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/soria\/#website","url":"https:\/\/www.asajacyl.com\/soria\/","name":"ASAJA Soria","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/soria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab","name":"Juan Ignacio Prieto Nieto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g","caption":"Juan Ignacio Prieto Nieto"},"url":"https:\/\/www.asajacyl.com\/soria\/author\/juanfranciscoby"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/3230"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/comments?post=3230"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/3230\/revisions"}],"predecessor-version":[{"id":3231,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/3230\/revisions\/3231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/media\/3177"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/media?parent=3230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/categories?post=3230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/tags?post=3230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}