{"id":3266,"date":"2020-06-02T12:35:47","date_gmt":"2020-06-02T10:35:47","guid":{"rendered":"https:\/\/www.asajacyl.com\/soria\/?p=3266"},"modified":"2020-06-03T12:14:54","modified_gmt":"2020-06-03T10:14:54","slug":"precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse","title":{"rendered":"O hay precios justos y se evitan recortes en la PAC o el campo volver\u00e1 a movilizarse"},"content":{"rendered":"<div id=\"td-outer-wrap\" class=\"td-theme-wrap\">\n<article id=\"post-155334\" class=\"td-post-template-3 post-155334 post type-post status-publish format-standard has-post-thumbnail hentry category-actualidad category-coronavirus category-de-la-granja-a-la-mesa category-destacados category-pac td-container-wrap\">\n<div class=\"td-container\">\n<div class=\"td-pb-row\">\n<div class=\"td-pb-span8 td-main-content\" role=\"main\">\n<div class=\"td-ss-main-content\">\n<div class=\"td-post-content\">\n<div class=\"td-a-rec td-a-rec-id-content_top td_uid_66_5ed5f9f5f22cc_rand td_block_template_1\">\n<div class=\"td-a-rec td-a-rec-id-content_inline td_uid_65_5ed5f9f5f2135_rand td_block_template_1\">\n<div id=\"beacon_a0770a5dd9\">\n<p>Las asociaciones agrarias ASAJA, Coag y Upa\u00a0no descartan retomar las movilizaciones y las tractoradas de enero y febrero si tras la desescalada de la crisis de la covid-19 el agricultor no recibe un precio justo por sus productos, a lo que suman la preocupaci\u00f3n por un posible recorte de las ayudas PAC.<\/p>\n<p>Seg\u00fan recoge agroinformacion.com, as\u00ed lo apuntaron el lunes 1\u00a0en el foro organizado por qcom.es\u00a0y\u00a0euroganader\u00eda.eu,\u00a0 \u201cLa importancia del sector primario en la desescalada de Espa\u00f1a\u201d el vicepresidente de ASAJA nacional, Pedro Gallardo, y los secretarios generales de Coag y Upa.<\/p>\n<p>Los tres responsables de las principales asociaciones de agricultores espa\u00f1olas han coincidido en que en esta pandemia el sector se ha puesto en valor porque ha garantizado el abastecimiento de alimentos, pero tambi\u00e9n han reconocido en que a\u00fan existen desequilibrios de precios en la cadena alimentaria.<\/p>\n<p>\u201cHay que recordar que las movilizaciones que hemos aparcado por la covid-19 quer\u00edan denunciar la grave crisis de falta de rentabilidad del sector\u201d, ha afirmado Gallardo, quien ha defendido que \u201clas administraciones tomen cartas en el asunto porque si no hay una soluci\u00f3n, se acab\u00f3 la tregua y vamos a tener que volver a sacar los tractores\u201d.<\/p>\n<p>Gallardo ha recordado que los precios en origen en muchos casos est\u00e1n a niveles de hace d\u00e9cadas mientras que los costes de producci\u00f3n se han disparado durante los \u00faltimos a\u00f1os; tambi\u00e9n, las trabas a la venta por el veto ruso a la importaci\u00f3n de alimentos comunitarios y la subida de aranceles de EE.UU., y varios productos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<h2 id=\"beacon_3875ec7eda\"><img loading=\"lazy\" decoding=\"async\" class=\"td-animation-stack-type0-2\" src=\"https:\/\/agroinformacion.com\/ads2\/www\/delivery\/lg.php?bannerid=0&amp;campaignid=0&amp;zoneid=48&amp;loc=https%3A%2F%2Fagroinformacion.com%2Fse-acabo-la-tregua-del-covid-o-hay-precios-justos-y-se-evitan-recortes-en-la-pac-o-el-campo-volver-a-movilizarse%2F&amp;referer=https%3A%2F%2Fwww.google.com%2Furl%3Fsa%3Dt%26rct%3Dj%26q%3D%26esrc%3Ds%26source%3Dweb%26cd%3D%26ved%3D2ahUKEwjH6_n-9eLpAhWlDGMBHU4PB1QQ0PADegQIBhAT%26url%3Dhttps%253A%252F%252Fagroinformacion.com%252Fse-acabo-la-tregua-del-covid-o-hay-precios-justos-y-se-evitan-recortes-en-la-pac-o-el-campo-volver-a-movilizarse%252F%26usg%3DAOvVaw0OG1G1wee3GW7Y-EuktrWs&amp;cb=3875ec7eda\" alt=\"\" width=\"0\" height=\"0\" \/><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las asociaciones agrarias ASAJA, Coag y Upa\u00a0no descartan retomar las movilizaciones y las tractoradas de enero y febrero si tras la desescalada de la crisis de la covid-19 el agricultor no recibe un precio justo por sus productos, a lo que suman la preocupaci\u00f3n por un posible recorte de las ayudas PAC. Seg\u00fan recoge agroinformacion.com, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":3267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,25],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O hay precios justos y se evitan recortes en la PAC o el campo volver\u00e1 a movilizarse - ASAJA Soria<\/title>\n<meta name=\"description\" content=\"Las asociaciones agrarias ASAJA, Coag y Upa\u00a0no descartan retomar las movilizaciones y las tractoradas de enero y febrero si tras la desescalada de la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O hay precios justos y se evitan recortes en la PAC o el campo volver\u00e1 a movilizarse - ASAJA Soria\" \/>\n<meta property=\"og:description\" content=\"Las asociaciones agrarias ASAJA, Coag y Upa\u00a0no descartan retomar las movilizaciones y las tractoradas de enero y febrero si tras la desescalada de la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Soria\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-02T10:35:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-03T10:14:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4756.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Ignacio Prieto Nieto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Ignacio Prieto Nieto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse\",\"name\":\"O hay precios justos y se evitan recortes en la PAC o el campo volver\u00e1 a movilizarse - ASAJA Soria\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4756.jpg\",\"datePublished\":\"2020-06-02T10:35:47+00:00\",\"dateModified\":\"2020-06-03T10:14:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab\"},\"description\":\"Las asociaciones agrarias ASAJA, Coag y Upa\u00a0no descartan retomar las movilizaciones y las tractoradas de enero y febrero si tras la desescalada de la\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4756.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4756.jpg\",\"width\":2500,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/soria\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O hay precios justos y se evitan recortes en la PAC o el campo volver\u00e1 a movilizarse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/\",\"name\":\"ASAJA Soria\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/soria\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab\",\"name\":\"Juan Ignacio Prieto Nieto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g\",\"caption\":\"Juan Ignacio Prieto Nieto\"},\"url\":\"https:\/\/www.asajacyl.com\/soria\/author\/juanfranciscoby\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O hay precios justos y se evitan recortes en la PAC o el campo volver\u00e1 a movilizarse - ASAJA Soria","description":"Las asociaciones agrarias ASAJA, Coag y Upa\u00a0no descartan retomar las movilizaciones y las tractoradas de enero y febrero si tras la desescalada de la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse","og_locale":"es_ES","og_type":"article","og_title":"O hay precios justos y se evitan recortes en la PAC o el campo volver\u00e1 a movilizarse - ASAJA Soria","og_description":"Las asociaciones agrarias ASAJA, Coag y Upa\u00a0no descartan retomar las movilizaciones y las tractoradas de enero y febrero si tras la desescalada de la","og_url":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse","og_site_name":"ASAJA Soria","article_published_time":"2020-06-02T10:35:47+00:00","article_modified_time":"2020-06-03T10:14:54+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4756.jpg","type":"image\/jpeg"}],"author":"Juan Ignacio Prieto Nieto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Juan Ignacio Prieto Nieto","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse","url":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse","name":"O hay precios justos y se evitan recortes en la PAC o el campo volver\u00e1 a movilizarse - ASAJA Soria","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/soria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4756.jpg","datePublished":"2020-06-02T10:35:47+00:00","dateModified":"2020-06-03T10:14:54+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab"},"description":"Las asociaciones agrarias ASAJA, Coag y Upa\u00a0no descartan retomar las movilizaciones y las tractoradas de enero y febrero si tras la desescalada de la","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse#primaryimage","url":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4756.jpg","contentUrl":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4756.jpg","width":2500,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/precios-justos-se-evitan-recortes-la-pac-campo-volvera-movilizarse#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/soria\/"},{"@type":"ListItem","position":2,"name":"O hay precios justos y se evitan recortes en la PAC o el campo volver\u00e1 a movilizarse"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/soria\/#website","url":"https:\/\/www.asajacyl.com\/soria\/","name":"ASAJA Soria","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/soria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab","name":"Juan Ignacio Prieto Nieto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g","caption":"Juan Ignacio Prieto Nieto"},"url":"https:\/\/www.asajacyl.com\/soria\/author\/juanfranciscoby"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/3266"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/comments?post=3266"}],"version-history":[{"count":6,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/3266\/revisions"}],"predecessor-version":[{"id":3273,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/3266\/revisions\/3273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/media\/3267"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/media?parent=3266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/categories?post=3266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/tags?post=3266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}