{"id":3292,"date":"2020-06-09T08:39:22","date_gmt":"2020-06-09T06:39:22","guid":{"rendered":"https:\/\/www.asajacyl.com\/soria\/?p=3292"},"modified":"2020-06-11T09:38:38","modified_gmt":"2020-06-11T07:38:38","slug":"los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva","title":{"rendered":"Los pa\u00edses de la UE temen que la transici\u00f3n ecol\u00f3gica convierta a la agricultura en menos competitiva"},"content":{"rendered":"<div id=\"container\" class=\"hfeed\">\n<div id=\"wrapper\" class=\"clearfix\">\n<div id=\"content\" class=\"grid col-680 ficha\">\n<div class=\"block\">\n<div class=\"post-entry\">\n<p>En una reciente videoconferencia, los ministros de Agricultura de la UE debatieron las estrategias \u201cDe la Granja a la mesa\u201d y \u201cBiodiversidad 2030\u201d, presentadas hace dos semanas por la Comisi\u00f3n Europea en el marco del Pacto Verde europeo para lograr una econom\u00eda neutra en emisiones de CO2 para 2050.<\/p>\n<p>Como as\u00ed recoge Efeagro, todos los pa\u00edses respaldaron la necesidad de una producci\u00f3n agr\u00edcola y ganadera m\u00e1s respetuosa con el medioambiente, pero a la vez incidieron en que hay que acompa\u00f1ar al sector en esa transici\u00f3n, con ayudas y medidas que eviten que salga perjudicado.<\/p>\n<p>\u201cValoro las dos estrategias. Est\u00e1n en l\u00ednea con los objetivos nacionales y estrat\u00e9gicos\u201d, dijo el ministro espa\u00f1ol de Agricultura, Pesca y Alimentaci\u00f3n, Luis Planas, que sin embargo critic\u00f3 la \u201caproximaci\u00f3n\u201d de la Comisi\u00f3n Europea sobre la producci\u00f3n en el sector ganadero o c\u00e1rnico.<\/p>\n<p>Planas pidi\u00f3 adem\u00e1s a la CE que explique c\u00f3mo ha calculado los objetivos de reducci\u00f3n de pesticidas o fertilizantes y pidi\u00f3 reciprocidad entre los productores europeos y de otros pa\u00edses.<\/p>\n<p>Francia consider\u00f3 que las dos estrategias van \u201cen la buena direcci\u00f3n\u201d e Italia dijo compartir \u201cel esp\u00edritu y objetivos\u201d pero defendi\u00f3 \u201cun equilibrio entre la sostenibilidad y la competitividad\u201d.<\/p>\n<div id=\"container\" class=\"hfeed\">\n<div id=\"wrapper\" class=\"clearfix\">\n<div id=\"content\" class=\"grid col-680 ficha\">\n<div class=\"block\">\n<div class=\"post-entry\">\n<p>El comisario europeo de Agricultura, Janusz Wojciechowsk, se\u00f1al\u00f3 al t\u00e9rmino de la reuni\u00f3n en rueda de prensa que hay \u201capoyo\u201d de los ministros, aunque \u201ctambi\u00e9n preocupaciones\u201d porque \u201ces un gran reto para los agricultores\u201d.<\/p>\n<p>A\u00f1adi\u00f3 que la aplicaci\u00f3n de ambas estrategias requerir\u00e1 \u201cla financiaci\u00f3n adecuada\u201d y confi\u00f3 en que salga adelante la nueva propuesta comunitaria para el presupuesto 2021-2027, que plantea 26.400 millones de euros m\u00e1s que en 2018 para el sector agr\u00edcola y ganadero.<\/p>\n<p>Muchos ministros pidieron a la UE que, para evitar que los europeos salgan perjudicados, se exijan tambi\u00e9n estrictas condiciones de producci\u00f3n a las importaciones agroalimentarias procedentes de terceros pa\u00edses.<\/p>\n<p>Planas se refiri\u00f3 durante el debate a los costes que implicar\u00e1 alcanzar los objetivos de reducci\u00f3n de pesticidas, fertilizantes o antibi\u00f3ticos para el ganado, \u201cque pueden da\u00f1ar la competencia\u201d si las importaciones a la UE no est\u00e1n sujetas a esos requisitos.<\/p>\n<p>\u201cConfiamos en que el principio de reciprocidad ser\u00e1 finalmente aplicado\u201d, dijo el ministro.<\/p>\n<p>Francia pidi\u00f3 por su parte un estudio de impacto sobre esos objetivos.<\/p>\n<p>Los llamamientos a \u201cpremiar y no penalizar a los agricultores\u201d, que durante la pandemia de la covid-19 han garantizado en todo momento el suministro alimentario y la realizaci\u00f3n de estudios de impacto previos fueron tambi\u00e9n mencionados por buena parte de los pa\u00edses.<\/p>\n<p>Tambi\u00e9n muchas delegaciones, como Francia, Italia o Austria, defendieron que no se exija el mismo nivel de esfuerzo a los productores que ya han empezado a reconvertirse y producen de manera m\u00e1s ecol\u00f3gica, que a quienes todav\u00eda no han comenzado.<\/p>\n<p>Sobre la producci\u00f3n ganadera, el comisario dijo en rueda de prensa que la intenci\u00f3n de Bruselas es apoyar m\u00e9todos de producci\u00f3n alternativos que introduzcan altos est\u00e1ndares.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En una reciente videoconferencia, los ministros de Agricultura de la UE debatieron las estrategias \u201cDe la Granja a la mesa\u201d y \u201cBiodiversidad 2030\u201d, presentadas hace dos semanas por la Comisi\u00f3n Europea en el marco del Pacto Verde europeo para lograr una econom\u00eda neutra en emisiones de CO2 para 2050. Como as\u00ed recoge Efeagro, todos los [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":3293,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,25],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los pa\u00edses de la UE temen que la transici\u00f3n ecol\u00f3gica convierta a la agricultura en menos competitiva - ASAJA Soria<\/title>\n<meta name=\"description\" content=\"En una reciente videoconferencia, los ministros de Agricultura de la UE debatieron las estrategias \u201cDe la Granja a la mesa\u201d y \u201cBiodiversidad 2030\u201d,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los pa\u00edses de la UE temen que la transici\u00f3n ecol\u00f3gica convierta a la agricultura en menos competitiva - ASAJA Soria\" \/>\n<meta property=\"og:description\" content=\"En una reciente videoconferencia, los ministros de Agricultura de la UE debatieron las estrategias \u201cDe la Granja a la mesa\u201d y \u201cBiodiversidad 2030\u201d,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Soria\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-09T06:39:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-11T07:38:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4780.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Ignacio Prieto Nieto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Ignacio Prieto Nieto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva\",\"name\":\"Los pa\u00edses de la UE temen que la transici\u00f3n ecol\u00f3gica convierta a la agricultura en menos competitiva - ASAJA Soria\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4780.jpg\",\"datePublished\":\"2020-06-09T06:39:22+00:00\",\"dateModified\":\"2020-06-11T07:38:38+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab\"},\"description\":\"En una reciente videoconferencia, los ministros de Agricultura de la UE debatieron las estrategias \u201cDe la Granja a la mesa\u201d y \u201cBiodiversidad 2030\u201d,\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4780.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4780.jpg\",\"width\":2500,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/soria\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los pa\u00edses de la UE temen que la transici\u00f3n ecol\u00f3gica convierta a la agricultura en menos competitiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/soria\/\",\"name\":\"ASAJA Soria\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/soria\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab\",\"name\":\"Juan Ignacio Prieto Nieto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g\",\"caption\":\"Juan Ignacio Prieto Nieto\"},\"url\":\"https:\/\/www.asajacyl.com\/soria\/author\/juanfranciscoby\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los pa\u00edses de la UE temen que la transici\u00f3n ecol\u00f3gica convierta a la agricultura en menos competitiva - ASAJA Soria","description":"En una reciente videoconferencia, los ministros de Agricultura de la UE debatieron las estrategias \u201cDe la Granja a la mesa\u201d y \u201cBiodiversidad 2030\u201d,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva","og_locale":"es_ES","og_type":"article","og_title":"Los pa\u00edses de la UE temen que la transici\u00f3n ecol\u00f3gica convierta a la agricultura en menos competitiva - ASAJA Soria","og_description":"En una reciente videoconferencia, los ministros de Agricultura de la UE debatieron las estrategias \u201cDe la Granja a la mesa\u201d y \u201cBiodiversidad 2030\u201d,","og_url":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva","og_site_name":"ASAJA Soria","article_published_time":"2020-06-09T06:39:22+00:00","article_modified_time":"2020-06-11T07:38:38+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4780.jpg","type":"image\/jpeg"}],"author":"Juan Ignacio Prieto Nieto","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Juan Ignacio Prieto Nieto","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva","url":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva","name":"Los pa\u00edses de la UE temen que la transici\u00f3n ecol\u00f3gica convierta a la agricultura en menos competitiva - ASAJA Soria","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/soria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4780.jpg","datePublished":"2020-06-09T06:39:22+00:00","dateModified":"2020-06-11T07:38:38+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab"},"description":"En una reciente videoconferencia, los ministros de Agricultura de la UE debatieron las estrategias \u201cDe la Granja a la mesa\u201d y \u201cBiodiversidad 2030\u201d,","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva#primaryimage","url":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4780.jpg","contentUrl":"https:\/\/www.asajacyl.com\/soria\/wp-content\/uploads\/sites\/9\/2020\/06\/IMG_4780.jpg","width":2500,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/soria\/asaja-soria-informa\/los-paises-la-ue-temen-la-transicion-ecologica-convierta-la-agricultura-menos-competitiva#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/soria\/"},{"@type":"ListItem","position":2,"name":"Los pa\u00edses de la UE temen que la transici\u00f3n ecol\u00f3gica convierta a la agricultura en menos competitiva"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/soria\/#website","url":"https:\/\/www.asajacyl.com\/soria\/","name":"ASAJA Soria","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/soria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/fd3081c40255119ce8133b87e6aedfab","name":"Juan Ignacio Prieto Nieto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/soria\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8266b36e4d9001acb4700699a2468dc8?s=96&d=mm&r=g","caption":"Juan Ignacio Prieto Nieto"},"url":"https:\/\/www.asajacyl.com\/soria\/author\/juanfranciscoby"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/3292"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/comments?post=3292"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/3292\/revisions"}],"predecessor-version":[{"id":3294,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/posts\/3292\/revisions\/3294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/media\/3293"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/media?parent=3292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/categories?post=3292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/soria\/wp-json\/wp\/v2\/tags?post=3292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}